{"id":12613,"date":"2011-11-14T13:17:23","date_gmt":"2011-11-14T12:17:23","guid":{"rendered":"http:\/\/www.mondgras.de\/sari02\/?p=12613"},"modified":"2011-11-14T13:17:23","modified_gmt":"2011-11-14T12:17:23","slug":"bitte-sag-mir-doch-wie-spat-es-ist","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/","title":{"rendered":"Bitte sag mir doch, wie sp&#228;t es ist!"},"content":{"rendered":"<p>Auf diesen Satz freue ich mich ja schon bzw. auf diese Frage. Ich hoffe, sie wird mir bald gestellt, denn dann kann ich hier schauen, wie sp&#228;t es wirklich ist *kicher* :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12614\" title=\"eulenuhr\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr.jpg\" alt=\"\" width=\"505\" height=\"172\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr.jpg 505w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr-300x102.jpg 300w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/p>\n<p>Am Samstag war ich mit der Lieblingskollegin am <a href=\"http:\/\/www.berliner-troedelmarkt.de\/\" target=\"_blank\">17. Juni auf dem Antiktr&#246;delmarkt<\/a>. Samstag ist insofern gut, wenn man mit Kinderwagen unterwegs ist, weil der Markt nicht so &#252;berf&#252;llt ist. Mehr zu sehen gibt es aber wahrscheinlich am Sonntag. Gut, nun waren wir aber am Samstag da, haben bei einem unfreundlichen H&#228;ndler doch kein Geld gelassen, von einem anderen ein kleines Honda Spielzeugmotorad f&#252;r den Minihelden geschenkt bekommen und uns in eben dieses und ein anderes Schmuckst&#252;ck bei einer Asiatin verliebt *omg* . Als sich dann auch noch zeigte, dass sich in ihrem Innern eine Uhr befindet, wusste ich, dass ich die Eule haben musste, unbedingt. Die Kollegin hat ein &#228;hnliches St&#252;ck mitgenommen. Nur dass ihres eine vollst&#228;ndige Eule zeigt und ihr Bauch die Uhr beinhaltet. Da muss nichts aufgeklappt werden. Ich finde es sch&#246;n, dass der Anh&#228;nger nicht sofort zeigt, was sich in ihm verbirgt&#8230; hachja, ich liebe sie.<\/p>\n<p>Aber insgesamt muss ich sagen, daf&#252;r, dass ich schon so lange gerne mal auf einen Antikmarkt wollte, habe ich doch letztendlich ordentlich Hemmung gehabt, um mal hier und da nach dem Preis zu fragen. Du siehst den H&#228;ndlern einfach an, dass sie wissen, was sie f&#252;r ihre Sachen nehmen k&#246;nnen. Es war aber auch sch&#246;n einfach mal so nach so vielen Jahren <em>(fr&#252;her habe ich das immer mit meinen Eltern regelm&#228;&#223;ig gemacht *loving* )<\/em> &#252;ber einen Tr&#246;delmarkt zu schlendern und die Dinge auf sich wirken zu lassen&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf diesen Satz freue ich mich ja schon bzw. auf diese Frage. Ich hoffe, sie wird mir bald gestellt, denn dann kann ich hier schauen, wie sp&#228;t es wirklich ist *kicher* : Am Samstag war ich mit der Lieblingskollegin am 17. Juni auf dem Antiktr&#246;delmarkt. Samstag ist insofern gut, wenn man mit Kinderwagen unterwegs ist, weil der Markt nicht so &#252;berf&#252;llt ist. Mehr zu sehen gibt es aber wahrscheinlich am Sonntag. Gut, nun waren wir aber am Samstag da, haben bei einem unfreundlichen H&#228;ndler doch kein Geld gelassen, von einem anderen ein kleines Honda Spielzeugmotorad f&#252;r den Minihelden geschenkt bekommen und uns in eben dieses und ein anderes Schmuckst&#252;ck bei einer Asiatin verliebt *omg* . Als sich dann auch noch zeigte, dass sich in ihrem Innern eine Uhr befindet, wusste ich, dass ich die Eule haben musste, unbedingt. Die Kollegin hat ein &#228;hnliches St&#252;ck mitgenommen. Nur dass ihres eine vollst&#228;ndige Eule zeigt und ihr Bauch die Uhr beinhaltet. Da muss nichts aufgeklappt werden. Ich finde es sch&#246;n, dass der Anh&#228;nger nicht sofort zeigt, was sich in ihm verbirgt&#8230; hachja, ich liebe sie. Aber insgesamt muss ich sagen, daf&#252;r, dass ich schon so lange gerne mal auf einen Antikmarkt wollte, habe ich doch letztendlich ordentlich Hemmung gehabt, um mal hier und da nach dem Preis zu fragen. Du siehst den H&#228;ndlern einfach an, dass sie wissen, was sie f&#252;r ihre Sachen nehmen k&#246;nnen. Es war aber auch sch&#246;n einfach mal so nach so vielen Jahren (fr&#252;her habe ich das immer mit meinen Eltern regelm&#228;&#223;ig gemacht *loving* ) &#252;ber einen Tr&#246;delmarkt zu schlendern und die Dinge auf sich wirken zu lassen&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[323],"tags":[],"class_list":["post-12613","post","type-post","status-publish","format-standard","hentry","category-alltag"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bitte sag mir doch, wie sp\u00e4t es ist! - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bitte sag mir doch, wie sp\u00e4t es ist! - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-14T12:17:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr.jpg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"Bitte sag mir doch, wie sp&#228;t es ist!\",\"datePublished\":\"2011-11-14T12:17:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/\"},\"wordCount\":292,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/eulenuhr.jpg\",\"articleSection\":[\"Alltagschaos\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/\",\"name\":\"Bitte sag mir doch, wie sp\u00e4t es ist! - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/eulenuhr.jpg\",\"datePublished\":\"2011-11-14T12:17:23+00:00\",\"description\":\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/eulenuhr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/eulenuhr.jpg\",\"width\":505,\"height\":172},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2011\\\/11\\\/14\\\/bitte-sag-mir-doch-wie-spat-es-ist\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bitte sag mir doch, wie sp&#228;t es ist!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bitte sag mir doch, wie sp\u00e4t es ist! - Heldenhaushalt","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/","og_locale":"de_DE","og_type":"article","og_title":"Bitte sag mir doch, wie sp\u00e4t es ist! - Heldenhaushalt","og_description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/","og_site_name":"Heldenhaushalt","article_published_time":"2011-11-14T12:17:23+00:00","og_image":[{"url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr.jpg","type":"","width":"","height":""}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"Bitte sag mir doch, wie sp&#228;t es ist!","datePublished":"2011-11-14T12:17:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/"},"wordCount":292,"commentCount":8,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr.jpg","articleSection":["Alltagschaos"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/","name":"Bitte sag mir doch, wie sp\u00e4t es ist! - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr.jpg","datePublished":"2011-11-14T12:17:23+00:00","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2011\/11\/eulenuhr.jpg","width":505,"height":172},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2011\/11\/14\/bitte-sag-mir-doch-wie-spat-es-ist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"Bitte sag mir doch, wie sp&#228;t es ist!"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":7185,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/12613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=12613"}],"version-history":[{"count":2,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/12613\/revisions"}],"predecessor-version":[{"id":12623,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/12613\/revisions\/12623"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=12613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=12613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=12613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}