{"id":22885,"date":"2014-05-22T08:00:00","date_gmt":"2014-05-22T06:00:00","guid":{"rendered":"http:\/\/www.mondgras.de\/sari02\/?p=22885"},"modified":"2014-05-22T07:07:59","modified_gmt":"2014-05-22T05:07:59","slug":"zur-probe-lee-lou","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/","title":{"rendered":"[Zur Probe] Lee Lou"},"content":{"rendered":"<p>Mein Gott, wenn Ihr w&#252;sstet, wie oft ich mich schon f&#252;r ein Proben&#228;hen beworden habe und wie entt&#228;uscht ich dann war, wenn meine Name nicht unter den Auserw&#228;hlten auftauchte *drop* Aber wie Ihr ja aus meinem letzten R&#252;ckblick wisst, hat es endlich mal geklappt. Ja, ehrlich!! Ich durfte Proben&#228;hen und ich freue mich so unb&#228;ndig dar&#252;ber. Ist das seltsam??<\/p>\n<p>Na jedenfalls habe ich Euch ja neulich erst den f&#252;r einige eher gew&#246;hnungsbed&#252;rftigen <a href=\"http:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/14\/mal-was-anderes-fr-mich\/\" target=\"_blank\">Overall<\/a> von <a href=\"http:\/\/de.dawanda.com\/shop\/Dani-Fusselinchen\" target=\"_blank\">Fusselinchen<\/a> gezeigt, den ich pers&#246;nlich aber gerade jetzt bei den sommerlichen Temperaturen wirklich toll finde. Und genau dort durfte ich zur Probe n&#228;hen. Und zwar das luftige Kleidchen &#8220;<a href=\"http:\/\/de.dawanda.com\/product\/63357867-Ebook-LEE-LOU-34-46-OVERSIZED-KLEID-TUNIKA\" target=\"_blank\"><em><strong>Lee Lou<\/strong><\/em><\/a>&#8220;, angelehnt an die japanischen lockeren Shirt-Schnitte. Lee Lou ist wirklich einfach und relativ schnell gen&#228;ht, sitzt sehr locker und kann vielseitig eingesetzt werden, wie ich finde. Man kann gut in der L&#228;nge variieren und dem Kleidchen dadurch seine Bestimmung geben.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-22892\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01.jpg\" alt=\"leelou-geandert01\" width=\"505\" height=\"321\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01-300x190.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01-768x487.jpg 768w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/p>\n<p>Ich habe mich daf&#252;r entschieden es im<strong> Color-Block mit Spitze oben<\/strong> zu n&#228;hen und f&#252;r den Rest festen Leinen gew&#228;hlt. Der Leinen f&#228;llt etwas schwerer. Ich musste es f&#252;r mich unten ungef&#228;hr 10 cm k&#252;rzen, da ich ja doch recht klein ausfalle, aber das ist bei desem SM echt probemlos m&#246;glich. Wenn man den Color-Block-Look nicht mag, kann man das auch ganz einfach mit nur einer Farbe n&#228;hen, dann geht es sogar noch schneller, weil man ja nur 2 Teile im Grunde braucht ^^ .Mit einem G&#252;rtel um die H&#252;fte mag ich es sogar noch lieber, so<strong> wie bei Fusselinchen im Beispiel<\/strong> gezeigt, so dass es locker luftig sitzt und vor allem f&#252;r den Strand oder sommerliche Ausfl&#252;ge gut geeignet ist.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-22891\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelouendergebnis.jpg\" alt=\"leelouendergebnis\" width=\"505\" height=\"530\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelouendergebnis.jpg 505w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelouendergebnis-286x300.jpg 286w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/p>\n<p>Da die Proben&#228;hrunde ganz gut lief, kann man das Schnittmuster sogar schon kaufen. Wer es auch mal versuchen m&#246;chte, kann<a href=\"http:\/\/de.dawanda.com\/product\/63357867-Ebook-LEE-LOU-34-46-OVERSIZED-KLEID-TUNIKA\" target=\"_blank\"><strong> hier<\/strong><\/a> nachschauen.<\/p>\n<p>Und? Wie findet Ihr meine Version?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mein Gott, wenn Ihr w&#252;sstet, wie oft ich mich schon f&#252;r ein Proben&#228;hen beworden habe und wie entt&#228;uscht ich dann war, wenn meine Name nicht unter den Auserw&#228;hlten auftauchte *drop* Aber wie Ihr ja aus meinem letzten R&#252;ckblick wisst, hat es endlich mal geklappt. Ja, ehrlich!! Ich durfte Proben&#228;hen und ich freue mich so unb&#228;ndig dar&#252;ber. Ist das seltsam?? Na jedenfalls habe ich Euch ja neulich erst den f&#252;r einige eher gew&#246;hnungsbed&#252;rftigen Overall von Fusselinchen gezeigt, den ich pers&#246;nlich aber gerade jetzt bei den sommerlichen Temperaturen wirklich toll finde. Und genau dort durfte ich zur Probe n&#228;hen. Und zwar das luftige Kleidchen &#8220;Lee Lou&#8220;, angelehnt an die japanischen lockeren Shirt-Schnitte. Lee Lou ist wirklich einfach und relativ schnell gen&#228;ht, sitzt sehr locker und kann vielseitig eingesetzt werden, wie ich finde. Man kann gut in der L&#228;nge variieren und dem Kleidchen dadurch seine Bestimmung geben. Ich habe mich daf&#252;r entschieden es im Color-Block mit Spitze oben zu n&#228;hen und f&#252;r den Rest festen Leinen gew&#228;hlt. Der Leinen f&#228;llt etwas schwerer. Ich musste es f&#252;r mich unten ungef&#228;hr 10 cm k&#252;rzen, da ich ja doch recht klein ausfalle, aber das ist bei desem SM echt probemlos m&#246;glich. Wenn man den Color-Block-Look nicht mag, kann man das auch ganz einfach mit nur einer Farbe n&#228;hen, dann geht es sogar noch schneller, weil man ja nur 2 Teile im Grunde braucht ^^ .Mit einem G&#252;rtel um die H&#252;fte mag ich es sogar noch lieber, so wie bei Fusselinchen im Beispiel gezeigt, so dass es locker luftig sitzt und vor allem f&#252;r den Strand oder sommerliche Ausfl&#252;ge gut geeignet ist. Da die Proben&#228;hrunde ganz gut lief, kann man das Schnittmuster sogar schon kaufen. Wer es auch mal versuchen m&#246;chte, kann hier nachschauen. Und? Wie findet Ihr meine Version?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[224],"tags":[],"class_list":["post-22885","post","type-post","status-publish","format-standard","hentry","category-handarbeiten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Zur Probe] Lee Lou - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Zur Probe] Lee Lou - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-22T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01.jpg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"[Zur Probe] Lee Lou\",\"datePublished\":\"2014-05-22T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/\"},\"wordCount\":326,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/leelou-geandert01.jpg\",\"articleSection\":[\"Aus Wolle &amp; Stoff\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/\",\"name\":\"[Zur Probe] Lee Lou - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/leelou-geandert01.jpg\",\"datePublished\":\"2014-05-22T06:00:00+00:00\",\"description\":\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/leelou-geandert01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/leelou-geandert01.jpg\",\"width\":1000,\"height\":634},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/05\\\/22\\\/zur-probe-lee-lou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Zur Probe] Lee Lou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Zur Probe] Lee Lou - Heldenhaushalt","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/","og_locale":"de_DE","og_type":"article","og_title":"[Zur Probe] Lee Lou - Heldenhaushalt","og_description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/","og_site_name":"Heldenhaushalt","article_published_time":"2014-05-22T06:00:00+00:00","og_image":[{"url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01.jpg","type":"","width":"","height":""}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"[Zur Probe] Lee Lou","datePublished":"2014-05-22T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/"},"wordCount":326,"commentCount":3,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01.jpg","articleSection":["Aus Wolle &amp; Stoff"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/","name":"[Zur Probe] Lee Lou - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01.jpg","datePublished":"2014-05-22T06:00:00+00:00","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/05\/leelou-geandert01.jpg","width":1000,"height":634},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/05\/22\/zur-probe-lee-lou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"[Zur Probe] Lee Lou"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":5956,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/22885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=22885"}],"version-history":[{"count":1,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/22885\/revisions"}],"predecessor-version":[{"id":22893,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/22885\/revisions\/22893"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=22885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=22885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=22885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}