{"id":24208,"date":"2014-10-24T11:30:00","date_gmt":"2014-10-24T09:30:00","guid":{"rendered":"http:\/\/www.mondgras.de\/sari02\/?p=24208"},"modified":"2014-10-24T11:37:40","modified_gmt":"2014-10-24T09:37:40","slug":"man-soll-nicht-mit-suessigkeiten-spielen","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/","title":{"rendered":"Man soll nicht mit S&#252;&#223;igkeiten spielen?"},"content":{"rendered":"<p>Doch, in diesem Fall schon, denn diese s&#252;&#223;en Pralinen machen nicht dick, sondern trainieren sogar dein K&#246;fpchen *lach* Obwohl sie so s&#252;&#223; aussehen, dass man sie gerne mal probieren m&#246;chte. Wir durften testen. Und zwar ein Spiel mit dem Namen &#8220;<a href=\"http:\/\/www.thinkfun.com\/cf_brainfitness\" target=\"_blank\" rel=\"nofollow\"><em>Chocolate Fix<\/em><\/a>&#8221; aus dem Hause <a href=\"http:\/\/www.thinkfun.com\/\" target=\"_blank\" rel=\"nofollow\"><strong>ThinkFun<\/strong><\/a>. Kennt Ihr die? Ich habe interessanter Weise vorher noch nie etwas davon geh&#246;rt und war dann doch ganz sch&#246;n neugierig.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24209\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01.jpg\" alt=\"chocolatefix01\" width=\"505\" height=\"225\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01.jpg 505w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01-300x134.jpg 300w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/p>\n<p>Das Spiel ist vordergr&#252;ndig vor allem<strong> f&#252;r einen Spieler<\/strong>, bei dem es verschiedene Aufgaben gibt, die man l&#246;sen muss. Mein erster Gedanke war ein bisschen wie Sodoku. Man bekommt eine <strong>unvollst&#228;ndige Kombination vorgegeben<\/strong> und muss diese sinnvoll vervollst&#228;nden. Im Anf&#228;ngermodus gibt es noch hinweise auf Farbe oder Form, aber sp&#228;ter muss man es auch alleine schaffen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24210\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix02.jpg\" alt=\"chocolatefix02\" width=\"505\" height=\"225\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix02.jpg 505w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix02-300x134.jpg 300w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/p>\n<p>In <strong>Anleitungsheft<\/strong> fndet man dann auch sp&#228;ter die <strong>L&#246;sungen zur Selbstkontrolle<\/strong>, in einem andere<strong> die Aufgaben<\/strong>, die sich auf Anf&#228;nger, Fortgeschritten, Experten und sogar Challenges beziehen. Das Spiel ist <strong>ab 8 Jahre<\/strong>, aber wir haben auch mal den Minihelden testen lassen, denn die Pralinen haben drei Farben und in jeder Farbe gibt es eine runde, eine quadratische und eine dreieckige Praline, so dass wir dachten, dass es f&#252;r einen drei Jahre alten Jungen sicher auch eine Herausforderung ist anhand der L&#246;sungsbilder die Pralinen richtig auf das Spielbrett zu ordnen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24211\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix03.jpg\" alt=\"chocolatefix03\" width=\"505\" height=\"297\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix03.jpg 505w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix03-300x176.jpg 300w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/p>\n<p>Dem Minihelden macht es in jedem Fall Spa&#223; und er fragt des &#214;fteren nach dem Spiel, so dass ich es eigentlich fast f&#252;r jedes Alter empfehlen kann, denn auch der Mann war zwischendurch pl&#246;tzlich nicht mehr zu h&#246;ren, weil er &#252;ber dem Brett gr&#252;belnd in der Zimmerecke sa&#223; *lach* .<\/p>\n<p><strong>Kennt Ihr ThinkFun oder gar Chocolate Fix?<\/strong> Habt Ihr schon mal von diesen Ged&#228;chnisrainingsspielen geh&#246;rt? Wie sind Eure Erfahrungen damit? Ich hoffe ja jetzt noch auf eine Familienausgabe *lach* .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doch, in diesem Fall schon, denn diese s&#252;&#223;en Pralinen machen nicht dick, sondern trainieren sogar dein K&#246;fpchen *lach* Obwohl sie so s&#252;&#223; aussehen, dass man sie gerne mal probieren m&#246;chte. Wir durften testen. Und zwar ein Spiel mit dem Namen &#8220;Chocolate Fix&#8221; aus dem Hause ThinkFun. Kennt Ihr die? Ich habe interessanter Weise vorher noch nie etwas davon geh&#246;rt und war dann doch ganz sch&#246;n neugierig. Das Spiel ist vordergr&#252;ndig vor allem f&#252;r einen Spieler, bei dem es verschiedene Aufgaben gibt, die man l&#246;sen muss. Mein erster Gedanke war ein bisschen wie Sodoku. Man bekommt eine unvollst&#228;ndige Kombination vorgegeben und muss diese sinnvoll vervollst&#228;nden. Im Anf&#228;ngermodus gibt es noch hinweise auf Farbe oder Form, aber sp&#228;ter muss man es auch alleine schaffen. In Anleitungsheft fndet man dann auch sp&#228;ter die L&#246;sungen zur Selbstkontrolle, in einem andere die Aufgaben, die sich auf Anf&#228;nger, Fortgeschritten, Experten und sogar Challenges beziehen. Das Spiel ist ab 8 Jahre, aber wir haben auch mal den Minihelden testen lassen, denn die Pralinen haben drei Farben und in jeder Farbe gibt es eine runde, eine quadratische und eine dreieckige Praline, so dass wir dachten, dass es f&#252;r einen drei Jahre alten Jungen sicher auch eine Herausforderung ist anhand der L&#246;sungsbilder die Pralinen richtig auf das Spielbrett zu ordnen. Dem Minihelden macht es in jedem Fall Spa&#223; und er fragt des &#214;fteren nach dem Spiel, so dass ich es eigentlich fast f&#252;r jedes Alter empfehlen kann, denn auch der Mann war zwischendurch pl&#246;tzlich nicht mehr zu h&#246;ren, weil er &#252;ber dem Brett gr&#252;belnd in der Zimmerecke sa&#223; *lach* . Kennt Ihr ThinkFun oder gar Chocolate Fix? Habt Ihr schon mal von diesen Ged&#228;chnisrainingsspielen geh&#246;rt? Wie sind Eure Erfahrungen damit? Ich hoffe ja jetzt noch auf eine Familienausgabe *lach* .<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-24208","post","type-post","status-publish","format-standard","hentry","category-empfehlungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Man soll nicht mit S\u00fc\u00dfigkeiten spielen? - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Man soll nicht mit S\u00fc\u00dfigkeiten spielen? - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-24T09:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-24T09:37:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01.jpg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"Man soll nicht mit S&#252;&#223;igkeiten spielen?\",\"datePublished\":\"2014-10-24T09:30:00+00:00\",\"dateModified\":\"2014-10-24T09:37:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/\"},\"wordCount\":318,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/chocolatefix01.jpg\",\"articleSection\":[\"Empfehlungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/\",\"name\":\"Man soll nicht mit S\u00fc\u00dfigkeiten spielen? - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/chocolatefix01.jpg\",\"datePublished\":\"2014-10-24T09:30:00+00:00\",\"dateModified\":\"2014-10-24T09:37:40+00:00\",\"description\":\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/chocolatefix01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/chocolatefix01.jpg\",\"width\":505,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2014\\\/10\\\/24\\\/man-soll-nicht-mit-suessigkeiten-spielen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Man soll nicht mit S&#252;&#223;igkeiten spielen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Man soll nicht mit S\u00fc\u00dfigkeiten spielen? - Heldenhaushalt","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/","og_locale":"de_DE","og_type":"article","og_title":"Man soll nicht mit S\u00fc\u00dfigkeiten spielen? - Heldenhaushalt","og_description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/","og_site_name":"Heldenhaushalt","article_published_time":"2014-10-24T09:30:00+00:00","article_modified_time":"2014-10-24T09:37:40+00:00","og_image":[{"url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01.jpg","type":"","width":"","height":""}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"Man soll nicht mit S&#252;&#223;igkeiten spielen?","datePublished":"2014-10-24T09:30:00+00:00","dateModified":"2014-10-24T09:37:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/"},"wordCount":318,"commentCount":7,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01.jpg","articleSection":["Empfehlungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/","name":"Man soll nicht mit S\u00fc\u00dfigkeiten spielen? - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01.jpg","datePublished":"2014-10-24T09:30:00+00:00","dateModified":"2014-10-24T09:37:40+00:00","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2014\/10\/chocolatefix01.jpg","width":505,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2014\/10\/24\/man-soll-nicht-mit-suessigkeiten-spielen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"Man soll nicht mit S&#252;&#223;igkeiten spielen?"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":5816,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/24208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=24208"}],"version-history":[{"count":1,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/24208\/revisions"}],"predecessor-version":[{"id":24212,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/24208\/revisions\/24212"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=24208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=24208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=24208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}