{"id":34017,"date":"2017-09-28T10:00:00","date_gmt":"2017-09-28T08:00:00","guid":{"rendered":"http:\/\/www.heldenhaushalt.de\/sari02\/?p=34017"},"modified":"2017-09-28T09:52:31","modified_gmt":"2017-09-28T07:52:31","slug":"der-kleine-optimist-rezension","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/","title":{"rendered":"Der kleine Optimist &#8211; Das Buch f&#252;r kleine Gr&#252;bler #Rezension"},"content":{"rendered":"<p>Der kleine Optimist. Eine Beschreibung f&#252;r einen kleinen Menschen, aber auch der Titel eines sch&#246;nen Buches, von dem ich euch heute erz&#228;hlen m&#246;chte.<\/p>\n<p>Der Miniheld ist ein Gr&#252;bler. Das erz&#228;hlte ich bereits. Manchmal macht er sich das Leben selber schwer, indem er mit seinen Gedanken und seiner Gr&#252;belei alle Dinge bis ins kleinste Detail zerlegt und dann bis sp&#228;t in die Nacht wach liegt und nicht einschlafen kann, weil er seine Gedanken einfach nicht ausschalten kann. Wir Erwachsenen kennen das. Je l&#228;nger wir &#252;ber etwas nachdenken, desto mehr negative Dinge finden wir und es f&#228;llt immer schwerer optimistisch zu sein. Ein Optimist zu sein, das ist einfach mal keine einfache Sache, nicht wahr?<\/p>\n<h2>Nach dem Guten im Alltag suchen und einfach gl&#252;cklich sein.<\/h2>\n<p>Das habe ich Anfang des Jahres mit dem Minihelden versucht. Wie ihr sicher noch wisst, sind wir dazu &#252;bergegangen ein <a href=\"http:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/03\/04\/mein-kind-fuehrt-glueckstagebuch\/\">Gl&#252;ckstagebuch <\/a>zu f&#252;hren und ich bin der festen &#220;berzeugung, dass viele positive Ver&#228;nderungen des letzten halben bis dreiviertel Jahres <a href=\"http:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/04\/04\/ein-monat-glueckstagebuch\/\">darauf zur&#252;ck zu f&#252;hren sind<\/a>. Man merkt in jedem Fall, wenn wir es schleifen lassen den Tag am Abend zu reflektieren und den Blick auf die positiven Dinge zu lenken, die sich immer &#8211; wirklich immer &#8211; finden lassen.<\/p>\n<p>Es ist so wichtig, dass man in der Hinsicht seine F&#252;hler ausstreckt und zul&#228;sst, dass auch die kleinen Dinge im Leben wahrgenommen und wert gesch&#228;tzt werden.<\/p>\n<h2>&#8220;Der kleine Optimist&#8221; von Yvonne Alberts<\/h2>\n<p>Durch Zufall bin ich vor einiger Zeit bei den vielen Einschulungs &#8211; Schult&#252;ten &#8211; F&#252;llungs &#8211; Listen auf ein wirklich sch&#246;nes und f&#252;r uns perfektes Buch gesto&#223;en: <a href=\"http:\/\/www.der-kleine-optimist.com\/\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Der kleine Optimist<\/strong><\/a>. Es stammt aus der Feder von Yvonne Alberts und ist ein ganz besonderes Tagebuch f&#252;r Kinder. Im Grunde &#228;hnelt es dem, was ich mit dem Minihelden schon so lange jetzt mache, sehr. Dabei ist es allerdings viel sch&#246;ner und bietet noch kleine Denkanst&#246;&#223;e, die man bei einem einfachen Aufschreiben jeden Tag eher nicht unbedingt ber&#252;cksichtigt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34256\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist01.jpg\" alt=\"Optimist\" width=\"800\" height=\"570\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist01.jpg 800w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist01-300x214.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist01-768x547.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist01-600x428.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Mit dem Buch m&#246;chte Yvonne vor allem einen positiven und dankbaren Blick beim Kind f&#246;rdern und somit dazu beitragen, dass es lernt etwas optimistischer durch den Alltag zu gehen.<\/p>\n<p>Mit liebevollen Zeichnungen und gut durchdachten Fragen f&#252;r jeden Tag, dokumentiert das Kind hier nun t&#228;glich seine Gedanken. Was war besonders sch&#246;n, wof&#252;r ist es dankbar. Und an jedem Tag kommt eine andere Frage dazu. Wohin m&#246;chte ich unbedingt mal reisen? Was ist mein gr&#246;&#223;ter W&#252;nsch? Wem konnte ich heute helfen? Diese und &#228;hnliche Fragen lassen das Kind dar&#252;ber nachdenken, was im Alltag besonders war, was gut war und wor&#252;ber es sich besonders freut. Dadurch lernt es sich besser kennen und sein Umfeld mehr sch&#228;tzen.&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34257\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist02.jpg\" alt=\"Optimist\" width=\"800\" height=\"530\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist02.jpg 800w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist02-300x199.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist02-768x509.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist02-600x398.jpg 600w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist02-373x248.jpg 373w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2>Das Ziel? Etwas mehr Selbstvertrauen und Gl&#252;ck im Alltag!<\/h2>\n<p>Wir starten gerade in die Schule. Nun gut, gerade ist vielleicht falsch formuliert. Gemeinsam gehen wir gerade den Weg und an manchen Tagen f&#228;llt er leichter, an anderen schwerer. Eines ist jedoch klar: Schule ist eine gigantische Ver&#228;nderung mit unglaublich vielen neuen Einfl&#252;ssen und Dingen, die den Alltag auf einmal durcheinander wirbeln. F&#252;r ein Kind, das sehr sensibel und gr&#252;blerisch ist, keine einfache Sache und es gilt einen Weg zu finden, der ihm dabei hilft diese H&#252;rde unbeschadet zu nehmen und gest&#228;rkt durch diesen neuen, ver&#228;nderten Alltag zu gehen.<\/p>\n<p>Als ich also auf dieses sch&#246;ne Buch von Yvonne stie&#223;, wollte ich es unbedingt f&#252;r den Minihelden haben.&nbsp; Unser Gl&#252;ckstagebuch in abgewandelter Form. Mit sch&#246;nen Bildern, interessanten (und wie ich finde, auch nicht unwichtigen) Fragen, die dazu beitragen sollen, dass mein Kind lernt ein kleiner Optimist zu werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34258\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist03.jpg\" alt=\"Optimist\" width=\"800\" height=\"542\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist03.jpg 800w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist03-300x203.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist03-768x520.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist03-600x407.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Jeden Abend sitzen wir nun gemeinsam zusammen und denken &#252;ber den Tag nach. Erst sprechen wir &#252;ber das was doof war und dann nehmen wir uns die Zeit, um &#252;ber die Fragen aus dem Buch nachzudenken. Das Positive immer zum Schluss, denn das hallt dann auch am l&#228;ngsten nach und begleitet vielleicht sogar in die Tr&#228;ume.<\/p>\n<p>Hier und heute also eine klare Empfehlung hier von meiner Seite! Wer nun neugierig geworden ist, <a href=\"http:\/\/www.der-kleine-optimist.com\/#kaufen\" target=\"_blank\" rel=\"nofollow noopener\">hier gibt es das wundervolle Buch zu kaufen<\/a>.<\/p>\n<p>Habt einen sch&#246;nen Tag,<\/p>\n<p><img decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2015\/01\/sari-unter.jpg?zoom=1.5&amp;resize=130%2C59\" alt=\"sari-unter\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der kleine Optimist. Eine Beschreibung f&#252;r einen kleinen Menschen, aber auch der Titel eines sch&#246;nen Buches, von dem ich euch heute erz&#228;hlen m&#246;chte. Der Miniheld ist ein Gr&#252;bler. Das erz&#228;hlte ich bereits. Manchmal macht er sich das Leben selber schwer, indem er mit seinen Gedanken und seiner Gr&#252;belei alle Dinge bis ins kleinste Detail zerlegt und dann bis sp&#228;t in die Nacht wach liegt und nicht einschlafen kann, weil er seine Gedanken einfach nicht ausschalten kann. Wir Erwachsenen kennen das. Je l&#228;nger wir &#252;ber etwas nachdenken, desto mehr negative Dinge finden wir und es f&#228;llt immer schwerer optimistisch zu sein. Ein Optimist zu sein, das ist einfach mal keine einfache Sache, nicht wahr? Nach dem Guten im Alltag suchen und einfach gl&#252;cklich sein. Das habe ich Anfang des Jahres mit dem Minihelden versucht. Wie ihr sicher noch wisst, sind wir dazu &#252;bergegangen ein Gl&#252;ckstagebuch zu f&#252;hren und ich bin der festen &#220;berzeugung, dass viele positive Ver&#228;nderungen des letzten halben bis dreiviertel Jahres darauf zur&#252;ck zu f&#252;hren sind. Man merkt in jedem Fall, wenn wir es schleifen lassen den Tag am Abend zu reflektieren und den Blick auf die positiven Dinge zu lenken, die sich immer &#8211; wirklich immer &#8211; finden lassen. Es ist so wichtig, dass man in der Hinsicht seine F&#252;hler ausstreckt und zul&#228;sst, dass auch die kleinen Dinge im Leben wahrgenommen und wert gesch&#228;tzt werden. &#8220;Der kleine Optimist&#8221; von Yvonne Alberts Durch Zufall bin ich vor einiger Zeit bei den vielen Einschulungs &#8211; Schult&#252;ten &#8211; F&#252;llungs &#8211; Listen auf ein wirklich sch&#246;nes und f&#252;r uns perfektes Buch gesto&#223;en: Der kleine Optimist. Es stammt aus der Feder von Yvonne Alberts und ist ein ganz besonderes Tagebuch f&#252;r Kinder. Im Grunde &#228;hnelt es dem, was ich mit dem Minihelden schon so lange jetzt mache, sehr. Dabei ist es allerdings viel sch&#246;ner und bietet noch kleine Denkanst&#246;&#223;e, die man bei einem einfachen Aufschreiben jeden Tag eher nicht unbedingt ber&#252;cksichtigt. Mit dem Buch m&#246;chte Yvonne vor allem einen positiven und dankbaren Blick beim Kind f&#246;rdern und somit dazu beitragen, dass es lernt etwas optimistischer durch den Alltag zu gehen. Mit liebevollen Zeichnungen und gut durchdachten Fragen f&#252;r jeden Tag, dokumentiert das Kind hier nun t&#228;glich seine Gedanken. Was war besonders sch&#246;n, wof&#252;r ist es dankbar. Und an jedem Tag kommt eine andere Frage dazu. Wohin m&#246;chte ich unbedingt mal reisen? Was ist mein gr&#246;&#223;ter W&#252;nsch? Wem konnte ich heute helfen? Diese und &#228;hnliche Fragen lassen das Kind dar&#252;ber nachdenken, was im Alltag besonders war, was gut war und wor&#252;ber es sich besonders freut. Dadurch lernt es sich besser kennen und sein Umfeld mehr sch&#228;tzen.&nbsp; Das Ziel? Etwas mehr Selbstvertrauen und Gl&#252;ck im Alltag! Wir starten gerade in die Schule. Nun gut, gerade ist vielleicht falsch formuliert. Gemeinsam gehen wir gerade den Weg und an manchen Tagen f&#228;llt er leichter, an anderen schwerer. Eines ist jedoch klar: Schule ist eine gigantische Ver&#228;nderung mit unglaublich vielen neuen Einfl&#252;ssen und Dingen, die den Alltag auf einmal durcheinander wirbeln. F&#252;r ein Kind, das sehr sensibel und gr&#252;blerisch ist, keine einfache Sache und es gilt einen Weg zu finden, der ihm dabei hilft diese H&#252;rde unbeschadet zu nehmen und gest&#228;rkt durch diesen neuen, ver&#228;nderten Alltag zu gehen. Als ich also auf dieses sch&#246;ne Buch von Yvonne stie&#223;, wollte ich es unbedingt f&#252;r den Minihelden haben.&nbsp; Unser Gl&#252;ckstagebuch in abgewandelter Form. Mit sch&#246;nen Bildern, interessanten (und wie ich finde, auch nicht unwichtigen) Fragen, die dazu beitragen sollen, dass mein Kind lernt ein kleiner Optimist zu werden. Jeden Abend sitzen wir nun gemeinsam zusammen und denken &#252;ber den Tag nach. Erst sprechen wir &#252;ber das was doof war und dann nehmen wir uns die Zeit, um &#252;ber die Fragen aus dem Buch nachzudenken. Das Positive immer zum Schluss, denn das hallt dann auch am l&#228;ngsten nach und begleitet vielleicht sogar in die Tr&#228;ume. Hier und heute also eine klare Empfehlung hier von meiner Seite! Wer nun neugierig geworden ist, hier gibt es das wundervolle Buch zu kaufen. Habt einen sch&#246;nen Tag,<\/p>\n","protected":false},"author":1,"featured_media":34259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[53,321],"tags":[253,1626,1624,202,81,1623,732,1622,1193,1625],"class_list":["post-34017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empfehlungen","category-minimum","tag-buch","tag-dankbarkeit","tag-der-kleine-optimist","tag-empfehlung","tag-kinder","tag-optimist","tag-rezension","tag-selbstvertrauen","tag-tagebuch","tag-yvonne-alberts"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der kleine Optimist - Das Buch f\u00fcr kleine Gr\u00fcbler #Rezension<\/title>\n<meta name=\"description\" content=\"Durch Zufall bin ich vor einiger Zeit auf ein sch\u00f6nes und f\u00fcr uns perfektes Buch gestossen: Der kleine Optimist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der kleine Optimist - Das Buch f\u00fcr kleine Gr\u00fcbler #Rezension\" \/>\n<meta property=\"og:description\" content=\"Durch Zufall bin ich vor einiger Zeit auf ein sch\u00f6nes und f\u00fcr uns perfektes Buch gestossen: Der kleine Optimist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-28T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"558\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"Der kleine Optimist &#8211; Das Buch f&#252;r kleine Gr&#252;bler #Rezension\",\"datePublished\":\"2017-09-28T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/\"},\"wordCount\":732,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/optimist04.jpg\",\"keywords\":[\"Buch\",\"Dankbarkeit\",\"Der kleine Optimist\",\"Empfehlung\",\"Kinder\",\"Optimist\",\"Rezension\",\"Selbstvertrauen\",\"Tagebuch\",\"Yvonne Alberts\"],\"articleSection\":[\"Empfehlungen\",\"Heldenkinder\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/\",\"name\":\"Der kleine Optimist - Das Buch f\u00fcr kleine Gr\u00fcbler #Rezension\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/optimist04.jpg\",\"datePublished\":\"2017-09-28T08:00:00+00:00\",\"description\":\"Durch Zufall bin ich vor einiger Zeit auf ein sch\u00f6nes und f\u00fcr uns perfektes Buch gestossen: Der kleine Optimist.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/optimist04.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/optimist04.jpg\",\"width\":800,\"height\":558,\"caption\":\"Optimist\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2017\\\/09\\\/28\\\/der-kleine-optimist-rezension\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der kleine Optimist &#8211; Das Buch f&#252;r kleine Gr&#252;bler #Rezension\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der kleine Optimist - Das Buch f\u00fcr kleine Gr\u00fcbler #Rezension","description":"Durch Zufall bin ich vor einiger Zeit auf ein sch\u00f6nes und f\u00fcr uns perfektes Buch gestossen: Der kleine Optimist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/","og_locale":"de_DE","og_type":"article","og_title":"Der kleine Optimist - Das Buch f\u00fcr kleine Gr\u00fcbler #Rezension","og_description":"Durch Zufall bin ich vor einiger Zeit auf ein sch\u00f6nes und f\u00fcr uns perfektes Buch gestossen: Der kleine Optimist.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/","og_site_name":"Heldenhaushalt","article_published_time":"2017-09-28T08:00:00+00:00","og_image":[{"width":800,"height":558,"url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist04.jpg","type":"image\/jpeg"}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"Der kleine Optimist &#8211; Das Buch f&#252;r kleine Gr&#252;bler #Rezension","datePublished":"2017-09-28T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/"},"wordCount":732,"commentCount":5,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist04.jpg","keywords":["Buch","Dankbarkeit","Der kleine Optimist","Empfehlung","Kinder","Optimist","Rezension","Selbstvertrauen","Tagebuch","Yvonne Alberts"],"articleSection":["Empfehlungen","Heldenkinder"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/","name":"Der kleine Optimist - Das Buch f\u00fcr kleine Gr\u00fcbler #Rezension","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist04.jpg","datePublished":"2017-09-28T08:00:00+00:00","description":"Durch Zufall bin ich vor einiger Zeit auf ein sch\u00f6nes und f\u00fcr uns perfektes Buch gestossen: Der kleine Optimist.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist04.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2017\/09\/optimist04.jpg","width":800,"height":558,"caption":"Optimist"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2017\/09\/28\/der-kleine-optimist-rezension\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"Der kleine Optimist &#8211; Das Buch f&#252;r kleine Gr&#252;bler #Rezension"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":5091,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/34017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=34017"}],"version-history":[{"count":4,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/34017\/revisions"}],"predecessor-version":[{"id":34260,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/34017\/revisions\/34260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media\/34259"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=34017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=34017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=34017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}