{"id":39150,"date":"2018-06-22T09:17:49","date_gmt":"2018-06-22T07:17:49","guid":{"rendered":"https:\/\/www.heldenhaushalt.de\/sari02\/?p=39150"},"modified":"2018-06-23T10:00:28","modified_gmt":"2018-06-23T08:00:28","slug":"freitags5-5-tage-5-fotos-im-juni-04-2","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/","title":{"rendered":"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04"},"content":{"rendered":"<p>Oh man, die Jungs haben diese Woche ganz sch&#246;n gelitten. Sie durften zwar wieder unter Menschen, aber immer noch keinen Sport machen. Gar nicht so einfach, wenn man zwei Kinder hat, die eigentlich nichts anderes gerne machen, au&#223;er Sport. Ups&#8230; Immerhin sind sie wieder fit wie ein Turnschuh und das ist die Hauptsache. Wie wir die Woche sonst so &#252;berstanden haben gibt es heute wieder in unseren #Freitags5.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<h2>Meine #Freitags5 #Freitagslieblinge<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-39216\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-02.jpg\" alt=\"#Freitags5\" width=\"1000\" height=\"935\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-02.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-02-300x281.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-02-768x718.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><strong>Meine Lieblingslekt&#252;re der Woche \u2013&nbsp;<\/strong>&nbsp;Wir lernen einen neuen Verlag kennen. Kennt ihr schon den <a href=\"https:\/\/www.biber-butzemann.de\/\" target=\"_blank\" rel=\"noopener\">Biber &amp; Butzemann Verlag<\/a>? Ganz wundervolle B&#252;cher, die ich euch demn&#228;chst mal n&#228;her vorstellen m&#246;chte. Hier und heute schon einmal ein kleiner Teaser f&#252;r euch.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-39219\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-05.jpg\" alt=\"#Freitags5\" width=\"1000\" height=\"1015\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-05.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-05-296x300.jpg 296w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-05-768x780.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><b>Mein Lieblingsessen der Woche \u2013&nbsp; <\/b>Diese Woche habe ich mal etwas Neues versucht. Ich habe mir ein kleines Omlette gemacht und zusammen mit Gurke auf Kn&#228;ckebrot gegessen. Eine leckere Kombi, die nun sicher &#246;fters mal auf meinem Teller landet.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-39217\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-03.jpg\" alt=\"#Freitags5\" width=\"1000\" height=\"990\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-03.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-03-150x150.jpg 150w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-03-300x297.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-03-768x760.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><strong>Meilensteine der Kinder&nbsp;<\/strong>\u2013&nbsp; Nun ja, so wirklich viel durften sie diese Woche ja nicht machen, weswegen es nat&#252;rlich die eine oder andere Diskussion gab. Aber bei solchen Sachen bleibe ich unnachgiebig. Wenn die &#196;rztin schon sagt, dass Sport diese Woche noch ausfallen sollte, dann wird das seine Gr&#252;nde haben und muss eingehalten werden. Als Ausgleich wurde dann viel gelesen und gemalt. Beim Heldenkind ist derzeit das Obstgarten &#8211; Spiel ganz hoch im Kurs und wird t&#228;glich gespielt. Der Miniheld hingegen lebt das WM &#8211; Fieber aus, rennt stolz in seinen Trikots rum und sortiert seine Sticker nach den WM &#8211; Gruppen. Er hat sich sogar Deckbl&#228;tter daf&#252;r gebastelt. Schau an. Am Mittwoch konnte der gro&#223;e Sohn endlich eine Verabredung nachholen, die wegen Krankheit nun zwei Mal verschoben werden und hatte in der Schule einen Auftritt in einem Schul &#8211; Musical. Deswegen war er ganz sch&#246;n nerv&#246;s, aber gleichzeitig auch voller Vorfreude, weil er endlich <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/12\/diy-ein-loewen-kostuem\/\" target=\"_blank\" rel=\"noopener\">sein L&#246;wenkost&#252;m<\/a> nutzen durfte. Am Abend vorher konnte er vor Aufregung kaum schlafen, aber er hat seine Sache ganz toll gemacht.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-39220\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-06.jpg\" alt=\"#Freitags5\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-06.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-06-150x150.jpg 150w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-06-300x300.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-06-768x768.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-06-660x660.jpg 660w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-06-373x373.jpg 373w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><strong>Was Mama bewegt hat<\/strong>&nbsp; \u2013&nbsp; Vor allem hat Mama sich bewegt. Nachdem ich die letzte Woche quasi zu Hause fest sa&#223;, weil die Kinder ja nicht gesund waren, musste ich diese Woche wieder f&#252;r ein bisschen Aufschwung bei mir sorgen. Ich kam letzte Woche nicht einen Tag auf meine 10.000 Schritte und das hat mich echt gewurmt. Mein Durchschnitt ist derzeit ganz sch&#246;n im Keller und das soll nicht so bleiben. Ich versuche mich derzeit mal wieder an einer 30 &#8211; Tage Challenge und habe den Stepper endlich mal entstaubt. Mal sehen, ob das was bringt. Immerhin habe ich so diese Woche mein Tagesziel jeden Tag wieder schaffen k&#246;nnen. Sehr gefreut habe ich mich, endlich das Theaterst&#252;ck zu sehen, f&#252;r das der Miniheld so flei&#223;ig ge&#252;bt hat.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-39215\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-01.jpg\" alt=\"#Freitags5\" width=\"1000\" height=\"983\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-01.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-01-300x295.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-01-768x755.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><strong>Empfehlungen und Entdeckungen der Woche<\/strong>&nbsp;\u2013&nbsp; Inspiriert f&#252;hle ich mich derzeit stark v<a href=\"https:\/\/lieblingichbloggejetzt.com\/wie-geht-es-fuer-mich-nach-meiner-fastenzeit-weiter\/\" target=\"_blank\" rel=\"noopener\">on Alina<\/a>, die das Fasten ausprobiert und spannenden Konsequenzen daraus f&#252;r sich gezogen hat. Sie strahlt im Moment so viel positive Energie aus, dass diese Energie direkt abf&#228;rbt und motiviert. Auch in der Blogsph&#228;re gab es wieder spannende Entdeckungen: <a href=\"https:\/\/feiersun.de\/sommerferien-daheim-low-budget-ideen-fuer-kinder\/\" target=\"_blank\" rel=\"noopener\">Sommerferien Ideen<\/a> &#8211; K<a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=12764\" target=\"_blank\" rel=\"noopener\">irschen aus Papier basteln<\/a> &#8211; <a href=\"https:\/\/fitundgluecklich.net\/2018\/06\/19\/erdbeerwaffeln-mit-beeren-im-teig\/\" target=\"_blank\" rel=\"noopener\">Erdbeerwaffeln<\/a> &#8211; <a href=\"https:\/\/fraeuleinan.blogspot.com\/2018\/06\/diy-lenkertasche.html\" target=\"_blank\" rel=\"noopener\">DIY Lenkertasche<\/a> &#8211; <a href=\"https:\/\/funkelfaden.de\/naehanleitung-bauchtasche-naehen\/\" target=\"_blank\" rel=\"noopener\">N&#228;hanleitung Bauchtasche<\/a><\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Man merkt, dass die Ferien immer n&#228;her r&#252;cken, denn wir haben immer weniger mit Hausaufgaben und Co zu tun, daf&#252;r aber Abschiedsfeste und mehr. Morgen hoffen wir aber erst einmal auf sch&#246;nes Wetter, damit wir grillen k&#246;nnen. Mehr bildhafte #Freitags5 R&#252;ckblicke gibt es auch heute wieder bei&nbsp;<a href=\"https:\/\/berlinmittemom.com\/6-freitagslieblinge-am-22-juni-2018\/\">BerlinMtteMom<\/a>.<\/p>\n<p><img decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/04\/sari-unter.jpg\"><\/p>\n<div id=\"wp_rp_first\" class=\"wp_rp_wrap wp_rp_vertical\">\n<div class=\"wp_rp_content\">\n<h3 class=\"related_post_title\">&nbsp;<\/h3>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Oh man, die Jungs haben diese Woche ganz sch&#246;n gelitten. Sie durften zwar wieder unter Menschen, aber immer noch keinen Sport machen. Gar nicht so einfach, wenn man zwei Kinder hat, die eigentlich nichts anderes gerne machen, au&#223;er Sport. Ups&#8230; Immerhin sind sie wieder fit wie ein Turnschuh und das ist die Hauptsache. Wie wir die Woche sonst so &#252;berstanden haben gibt es heute wieder in unseren #Freitags5. *** Meine #Freitags5 #Freitagslieblinge Meine Lieblingslekt&#252;re der Woche \u2013&nbsp;&nbsp;Wir lernen einen neuen Verlag kennen. Kennt ihr schon den Biber &amp; Butzemann Verlag? Ganz wundervolle B&#252;cher, die ich euch demn&#228;chst mal n&#228;her vorstellen m&#246;chte. Hier und heute schon einmal ein kleiner Teaser f&#252;r euch. *** Mein Lieblingsessen der Woche \u2013&nbsp; Diese Woche habe ich mal etwas Neues versucht. Ich habe mir ein kleines Omlette gemacht und zusammen mit Gurke auf Kn&#228;ckebrot gegessen. Eine leckere Kombi, die nun sicher &#246;fters mal auf meinem Teller landet. *** Meilensteine der Kinder&nbsp;\u2013&nbsp; Nun ja, so wirklich viel durften sie diese Woche ja nicht machen, weswegen es nat&#252;rlich die eine oder andere Diskussion gab. Aber bei solchen Sachen bleibe ich unnachgiebig. Wenn die &#196;rztin schon sagt, dass Sport diese Woche noch ausfallen sollte, dann wird das seine Gr&#252;nde haben und muss eingehalten werden. Als Ausgleich wurde dann viel gelesen und gemalt. Beim Heldenkind ist derzeit das Obstgarten &#8211; Spiel ganz hoch im Kurs und wird t&#228;glich gespielt. Der Miniheld hingegen lebt das WM &#8211; Fieber aus, rennt stolz in seinen Trikots rum und sortiert seine Sticker nach den WM &#8211; Gruppen. Er hat sich sogar Deckbl&#228;tter daf&#252;r gebastelt. Schau an. Am Mittwoch konnte der gro&#223;e Sohn endlich eine Verabredung nachholen, die wegen Krankheit nun zwei Mal verschoben werden und hatte in der Schule einen Auftritt in einem Schul &#8211; Musical. Deswegen war er ganz sch&#246;n nerv&#246;s, aber gleichzeitig auch voller Vorfreude, weil er endlich sein L&#246;wenkost&#252;m nutzen durfte. Am Abend vorher konnte er vor Aufregung kaum schlafen, aber er hat seine Sache ganz toll gemacht. *** Was Mama bewegt hat&nbsp; \u2013&nbsp; Vor allem hat Mama sich bewegt. Nachdem ich die letzte Woche quasi zu Hause fest sa&#223;, weil die Kinder ja nicht gesund waren, musste ich diese Woche wieder f&#252;r ein bisschen Aufschwung bei mir sorgen. Ich kam letzte Woche nicht einen Tag auf meine 10.000 Schritte und das hat mich echt gewurmt. Mein Durchschnitt ist derzeit ganz sch&#246;n im Keller und das soll nicht so bleiben. Ich versuche mich derzeit mal wieder an einer 30 &#8211; Tage Challenge und habe den Stepper endlich mal entstaubt. Mal sehen, ob das was bringt. Immerhin habe ich so diese Woche mein Tagesziel jeden Tag wieder schaffen k&#246;nnen. Sehr gefreut habe ich mich, endlich das Theaterst&#252;ck zu sehen, f&#252;r das der Miniheld so flei&#223;ig ge&#252;bt hat. *** Empfehlungen und Entdeckungen der Woche&nbsp;\u2013&nbsp; Inspiriert f&#252;hle ich mich derzeit stark von Alina, die das Fasten ausprobiert und spannenden Konsequenzen daraus f&#252;r sich gezogen hat. Sie strahlt im Moment so viel positive Energie aus, dass diese Energie direkt abf&#228;rbt und motiviert. Auch in der Blogsph&#228;re gab es wieder spannende Entdeckungen: Sommerferien Ideen &#8211; Kirschen aus Papier basteln &#8211; Erdbeerwaffeln &#8211; DIY Lenkertasche &#8211; N&#228;hanleitung Bauchtasche *** Man merkt, dass die Ferien immer n&#228;her r&#252;cken, denn wir haben immer weniger mit Hausaufgaben und Co zu tun, daf&#252;r aber Abschiedsfeste und mehr. Morgen hoffen wir aber erst einmal auf sch&#246;nes Wetter, damit wir grillen k&#246;nnen. Mehr bildhafte #Freitags5 R&#252;ckblicke gibt es auch heute wieder bei&nbsp;BerlinMtteMom. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":39218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[323,49],"tags":[780,781,45,69,1824,81,926],"class_list":["post-39150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alltag","category-blogspaehre","tag-freitags5","tag-freitagslieblinge","tag-alltag","tag-familie","tag-familienalltag","tag-kinder","tag-kleinkinder"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04 - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04 - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-22T07:17:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-23T08:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1015\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04\",\"datePublished\":\"2018-06-22T07:17:49+00:00\",\"dateModified\":\"2018-06-23T08:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/\"},\"wordCount\":613,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/18-24-04.jpg\",\"keywords\":[\"#Freitags5\",\"#Freitagslieblinge\",\"Allt\u00e4glich\",\"Familie\",\"Familienalltag\",\"Kinder\",\"Kleinkinder\"],\"articleSection\":[\"Alltagschaos\",\"Blogsph\u00e4re\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/\",\"name\":\"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04 - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/18-24-04.jpg\",\"datePublished\":\"2018-06-22T07:17:49+00:00\",\"dateModified\":\"2018-06-23T08:00:28+00:00\",\"description\":\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/18-24-04.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/18-24-04.jpg\",\"width\":1000,\"height\":1015,\"caption\":\"#Freitags5\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2018\\\/06\\\/22\\\/freitags5-5-tage-5-fotos-im-juni-04-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04 - Heldenhaushalt","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/","og_locale":"de_DE","og_type":"article","og_title":"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04 - Heldenhaushalt","og_description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/","og_site_name":"Heldenhaushalt","article_published_time":"2018-06-22T07:17:49+00:00","article_modified_time":"2018-06-23T08:00:28+00:00","og_image":[{"width":1000,"height":1015,"url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-04.jpg","type":"image\/jpeg"}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04","datePublished":"2018-06-22T07:17:49+00:00","dateModified":"2018-06-23T08:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/"},"wordCount":613,"commentCount":6,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-04.jpg","keywords":["#Freitags5","#Freitagslieblinge","Allt\u00e4glich","Familie","Familienalltag","Kinder","Kleinkinder"],"articleSection":["Alltagschaos","Blogsph\u00e4re"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/","name":"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04 - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-04.jpg","datePublished":"2018-06-22T07:17:49+00:00","dateModified":"2018-06-23T08:00:28+00:00","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-04.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/06\/18-24-04.jpg","width":1000,"height":1015,"caption":"#Freitags5"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/06\/22\/freitags5-5-tage-5-fotos-im-juni-04-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"#Freitags5 \u2013 5 Tage 5 Fotos im Juni #04"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":2981,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/39150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=39150"}],"version-history":[{"count":3,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/39150\/revisions"}],"predecessor-version":[{"id":39240,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/39150\/revisions\/39240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media\/39218"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=39150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=39150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=39150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}