{"id":43473,"date":"2019-01-08T10:00:00","date_gmt":"2019-01-08T09:00:00","guid":{"rendered":"https:\/\/www.heldenhaushalt.de\/sari02\/?p=43473"},"modified":"2019-01-08T10:28:42","modified_gmt":"2019-01-08T09:28:42","slug":"gute-vorsaetze","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/","title":{"rendered":"Zeit f&#252;r Ver&#228;nderung: Die Sache mit den guten Vors&#228;tzen&#8230;"},"content":{"rendered":"<p><small>Werbung \u2013 Der folgende Artikel enth&#228;lt evtl. Bilder mit Produkten, die wir in unserem Alltag nutzen oder Linkempfehlungen. Wir haben keine Bezahlung f&#252;r das Zeigen oder Nutzen derselbigen erhalten.<\/small><\/p>\n<p>Da sitze ich nun also an meinem Esstisch und schreibe. Ich schreibe hier seit Tagen auf dem Blog, dass ich gro&#223;e Pl&#228;ne habe. Vors&#228;tze. Ihr kennt das. Jedes Jahr wieder aufs Neue. Immer wieder. Die Dinge, die man sich vornimmt und die man doch nie so richtig umgesetzt bekommt. Wenn ich auf meine Listen und Projekte der vergangenen Jahre blicke, dann kann ich eigentlich nur eines feststellen: Es wiederholt sich!<\/p>\n<h2>Die Dinge kommen immer wieder. Es ist weniger ein Vornehmen, als vielmehr ein erhalten der Vors&#228;tze.<\/h2>\n<p>Jedes Jahr wieder steht es auf meiner Liste. Das Abnehmen. Das bessere Essen. Das mehr kreativ sein. Das Thema Selbstliebe. Immer und immer wieder die gleichen Dinge. Kann ich es also tats&#228;chlich so sehen, dass ich neue Vors&#228;tze ausformulier oder schaue ich eher auf die Dinge, die ich bisher geschafft habe und &#252;berlege mir, wie ich weiter daran arbeiten kann? Ich denke, das ist der Punkt: Ich befinde mich jedes Jahr wieder auf dem gleichen Weg. Es sind diese Standard &#8211; Vors&#228;tze, die ein jeder von uns hat. Mehr Bewegung, ges&#252;nderes Essen, mehr an sich selber denken und an die Dinge, die einem wichtig sind. Sie ver&#228;ndern sich nur ein kleines bisschen und sie sind in meinem Kopf (glaube ich) immer deshalb zu Beginn eines neuen Jahres so pr&#228;sent, weil ich zum Jahresende hin schw&#228;chle. Die Weihnachtszeit kommt. Mit all dem S&#252;&#223;kram. Es ist dunkel und grau, das Wetter schlecht und die Bewegung l&#228;sst nach. Im Sommer f&#228;llt es einem zum Beispiel so viel leichter aktiver und ges&#252;nder unterwegs zu sein.<\/p>\n<p>Als ich nun also an meinem Esstisch sa&#223; und verschiedene Brainstormings anstellte, sah ich am Ende auf meine Zettel und musste feststellen: Es hat sich nicht viel ge&#228;ndert. Nur bei den Unterpunkten hat sich etwas getan. Die Priorit&#228;ten in den einzelnen Bereichen haben sich etwas verschoben oder sind pr&#228;ziser geworden. Wie gehe ich also damit um.<\/p>\n<h2>Eine Erkenntnis ereilte mich: Ich brauche diese Selbstkontrolle!<\/h2>\n<p>Einer der Gr&#252;nde, warum ich so effektiv gearbeitet habe, als ich mein Jahr durch das <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/?s=12in2012&amp;submit=Suche\">12in2012<\/a> oder gar dem <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2016\/01\/05\/sparkle-shine-2016-im-heldenhaushalt\/\">Sparkle &amp; Shine<\/a> begleiten lie&#223;, war sicher der, dass ich mich monatlich selber kontrollieren musste. Offen f&#252;r andere. Es blieb also am Ende dieser Druck, dass ich nicht nur vor mir rechtfertigen musste, wenn ich etwas nicht gemacht hatte, sondern eben auch vor anderen. Ich brauche Listen, die ich abhaken kann und den st&#228;ndig pr&#252;fenden Blick, der schaut, ob auch alles passt und seine Richtigkeit hat. Welchen Schluss ziehe ich also aus dieser ersten Erkenntnis (die so neu eigentlich gar nicht , aber f&#252;r die Planung in diesem Jahr dennoch wichtig ist)? Richtig&#8230; ich muss es f&#252;r mich und f&#252;r euch wieder transparenter gestalten.<\/p>\n<h2>Daraus ergibt sich folgende logische Konsequenz: Ich brauche ein Format, das mich durch das Jahr begleitet.<\/h2>\n<p>Doch wie soll dieses aussehen? Will ich es monatlich oder pro Quartal? Brauche ich eine Liste, die ich abhaken kann oder arbeite ich mit &#220;berbegriffen? Um das heraus zu finden, gab es ein weiteres Brainstorming. Ich berief mich auf alte Methoden. Ich schrieb zuerst 12 Ziele auf, die ich im Auge behalten wollte. F&#252;r jeden Monat eines quasi. Ich wollte zuerst einmal wissen, ob ich &#252;berhaupt auf 12 Punkte kommen w&#252;rde&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43649\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv01.jpg\" alt=\"Ver&#228;nderung\" width=\"1000\" height=\"688\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv01.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv01-300x206.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv01-768x528.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Anschlie&#223;end betrachtete ich die 12 Punkte und &#252;berlegte, ob sie sich auf Oberbegriffe aufteilen lie&#223;en. Wie viele &#220;berschriften w&#252;rden da wohl entstehen und w&#252;rden sie eventuell sogar mit dem Prinzip von Sparkle &amp; Shine konform gehen, die sich mit Kopf, Herz, K&#246;rper, Emotion usw. befassten?&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43650\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv02.jpg\" alt=\"Ver&#228;nderung\" width=\"1000\" height=\"691\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv02.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv02-300x207.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv02-768x531.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Und zum Schluss nahm ich diese Begriffe, formulierte sie in meine pers&#246;nlichen Ziele um und schrieb darunter die Dinge, die mir dazu einfielen. Ich ging also ins Detail, um zu schauen, wie sich das vielleicht auf monatliche Ziele und Jahresziele aufteilen lie&#223;. Dabei heraus kam dann diese Grafik:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43652\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv04.jpg\" alt=\"Ver&#228;nderung\" width=\"1000\" height=\"709\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv04.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv04-300x213.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv04-768x545.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h2>Meine Vors&#228;tze 2019: Zeit f&#252;r Ver&#228;nderung!<\/h2>\n<p>Nachdem ich nun also wusste, was ich gerne schaffen m&#246;chte, wollte ich dem ganzen gerne einen Arbeitstitel geben. &#8220;Lebe, Liebe, Lache&#8221; gefiel mir gut, aber auch so Phrasen wie &#8220;Make it Happen&#8221;, doch dann stand ich vor der Frage, inwiefern ich das &#252;berhaupt nutzen darf. Also hielt ich es simple. Simple as possible&#8230; oder so &#228;hnlich. Denn letztendlich ist es ein Ziel, dass ich tats&#228;chlich erreichen m&#246;chte: Eine dauerhafte und vor allem nachhaltige Ver&#228;nderung von Angewohnheiten in meinem Leben! Das Ganze teilt sich nun wie folgt auf.<\/p>\n<h2>Meine 5 Bereiche und ihre Unterkategorien<\/h2>\n<p><strong>01. Selbstliebe &#8211;<\/strong> Dieser Punkt ist wohl der, der in diesem Jahr die h&#246;chste Priorit&#228;t von mir erhalten wird. Ich hatte es in der Vergangenheit mehrfach angesprochen: Ich habe irgendwie einen Knick in der Optik und mag mich gar nicht mehr. Daran muss und m&#246;chte ich in diesem Jahr weiterhin arbeiten. Das Ganze teilt sich in einige Unterziele auf:<\/p>\n<ul>\n<li><strong>Fitness &amp; Muskelaufbau:<\/strong> Weiterhin m&#246;chte ich, dass Sport ein fester Bestandteil meines Alltages ist. Im letzten Jahr gelang mir das schon ganz gut, aber ich m&#246;chte es in diesem Jahr gezielter angehen. Der R&#252;cken muss gest&#228;rkt, der Bauch und die Oberschenkeln gestrafft und die Oberarme minimiert werden. So meine Sicht der Dinge.<\/li>\n<li><strong>Ern&#228;hrung, Zucker, Wasser:<\/strong> Weniger naschen, mehr Obst und Gem&#252;se und mal wieder mehr Wasser als anderes zum Trinken. Im Grunde das &#252;bliche, aber ich m&#246;chte meine Ern&#228;hrung und <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2015\/01\/05\/sas2015-30-day-water-challenge\/\">mein Trinkverhalten etwas optimieren<\/a>.<\/li>\n<li><strong>Daraus ergibt sich:<\/strong> Ein Wohlf&#252;hlgewicht finden und ein Bild von mir schaffen, das ich gerne auf Fotos und im Spiegel sehe<\/li>\n<li><strong>Me &#8211; Time:<\/strong> Zeit f&#252;r mich. 10 Minuten am Tag, in denen ich nichts mache, was mit Haushalt, Arbeit, Kinder oder sonst was zu tun hat. Frei von jeglichen Verpflichtungen. Einfach nur ich. Vielleicht gef&#252;llt mit Yoga oder einer Art Meditation, um besser in mich hineinsehen und mich verstehen zu k&#246;nnen. Mal sehen, was sich da finden l&#228;sst. Und wenn es nur ein kurzer Spaziergang um die H&#228;user ist.<\/li>\n<\/ul>\n<p><strong>02. Kreativit&#228;t &#8211;<\/strong> Nicht nur ich habe den Wunsch danach alte Hobbies wieder aufleben zu lassen, sondern auch euer Feedback hat mir zu verstehen gegeben, dass ihr euch wieder mehr von diesen Inhalten w&#252;nscht. Mit einem Blick auf die Dinge, die mein Umfeld umgeben, bin ich dabei auf folgende Bereiche und Ziele gekommen:<\/p>\n<ul>\n<li><strong>Lesen:<\/strong> In den letzten Jahren habe ich kaum ein Buch lesen k&#246;nnen. Meine Hauptlekt&#252;re bestand aus Kinderb&#252;chern, was grunds&#228;tzlich toll ist, aber ich habe einige B&#252;cher, die ich schon l&#228;nger gerne mal lesen wollte. Also gibt es einen Stapel, den ich dieses Jahr gerne schaffen m&#246;chte. Insgesamt sind es bisher 5 B&#252;cher, die ich mir vorgenommen habe. Erscheint mir recht realistisch.<\/li>\n<li><strong>H&#228;keln:<\/strong> Ich habe mir Ende letztens Jahres zwei bunte Kn&#228;uel Wolle gekauft. Aus einem Impuls heraus. Daraus m&#246;chte ich in diesem Jahr etwas h&#228;keln. Vermutlich eine Decke. Das ist mein Ziel.&nbsp;<\/li>\n<li><strong>N&#228;hen:<\/strong> Die Kinder brauchen nicht unbedingt neue Klamotten, aber dann und wann schon. Besonders Hosen f&#252;r den Kleinen und deshalb m&#246;chte ich auch da wieder mehr tun in diesem Jahr. Aber nicht nur Kleidung: Ich m&#246;chte die Kissenbez&#252;ge f&#252;r die Couch selber n&#228;hen. Da einfach wieder mehr machen.<\/li>\n<li><strong>Zeichnen:<\/strong> Da gibt es zwar dank der <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/ausmalbilder\/\">Ausmalbilder<\/a> eine gewisse Regelm&#228;&#223;igkeit, doch ich m&#246;chte da doch wieder mehr machen. Ich nehme mir das jedes Jahr vor, aber dieses Mal habe ich ein Ziel: Ich m&#246;chte monatlich einen Comic schaffen und den Umgang mit dem <strong>Grafiktablett<\/strong> lernen.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43654\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv06.jpg\" alt=\"Ver&#228;nderung\" width=\"1000\" height=\"694\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv06.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv06-300x208.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv06-768x533.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><strong>03. Familienmensch &#8211;<\/strong> Mit einem Sohn, der Fu&#223;ball im Verein spielt und einem zweiten, der die selbe Tendenz zeigt, ist Freizeit etwas Seltenes. Zumindest hat sich dieses Gef&#252;hl in den letzten drei Jahren sehr verst&#228;rkt. Dazu kommt Arbeit, Schule, Kita und andere normale Termine, die kaum Luft f&#252;r Freizeit lassen. Daher ebenfalls wichtig: Zeit f&#252;r die Familie!<\/p>\n<ul>\n<li>Zeit im Alltag finden f&#252;r <strong>sch&#246;ne&nbsp;<\/strong><b>Aktivit&#228;ten<\/b>. Es muss gar nicht viel sein. Ein Ausflug auf den Spielplatz oder &#246;fter ein Ausflug im n&#228;heren Umfeld.<\/li>\n<li>Ruhige, gemeinsame <strong>Momente zu Hause<\/strong> schaffen. Einen Spielenachmittag einf&#252;hren und wieder mehr gemeinsam basteln.<\/li>\n<li><strong>Mehr von der Stadt sehen.<\/strong> Das haben wir uns schon einmal vorgenommen. Es gibt noch so viele Dinge, die unsere Stadt zu bieten hat, die wir noch nicht gesehen haben.<\/li>\n<li>Vielleicht schaffen wir auch <strong>gemeinsame neue Rituale<\/strong>, die sich gut in den sich st&#228;ndig ver&#228;ndernden Alltag integrieren lassen.<\/li>\n<\/ul>\n<p><strong>04. Home sweet Home &#8211;<\/strong> Das ist ein Bereich, der den Helden und mich in diese Jahr noch sehr besch&#228;ftigen wird. Die gro&#223;e Baustelle ist zwar weg, doch gibt es noch viele kleine Dinge auf unserer Liste, die erledigt werden m&#252;ssen. Ein 30 Jahre altes Haus hat seine Macken und Spuren der letzten Jahre. Manches muss noch ersetzt, anderes neu gemacht werden. Hier fehlt noch eine Steckdose, dort eine Leiste. Auch m&#252;ssen wir noch einiges ausmisten.<\/p>\n<ul>\n<li>Nach wie vor m&#246;chte ich eine <strong>Routine f&#252;r den Haushalt<\/strong> entwickeln<\/li>\n<li><strong><a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2018\/01\/10\/mmi-erste-schaltzentrale\/\">Familien &#8211; Schaltzentrale<\/a><\/strong> optimieren<\/li>\n<li><strong>Dachboden<\/strong> ausmisten<\/li>\n<li><strong>Schuppen<\/strong> ausmisten<\/li>\n<li><strong>Garten<\/strong> weiter anpassen (nachdem im Herbst die Hecken raus sind, m&#252;ssen wir dort nun etwas Neues hinmachen).<\/li>\n<li><strong>Kleinigkeiten<\/strong> im Haus<\/li>\n<li><strong>Papierkram <\/strong>ausmisten, ordnen, einsortieren<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43653\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv05.jpg\" alt=\"Ver&#228;nderung\" width=\"1000\" height=\"724\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv05.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv05-300x217.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv05-768x556.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><strong>05. Bloggerleben &#8211;<\/strong> Auch wenn das Leben als Blogger nicht unbedingt einfacher wird, soll es nach wie vor ein Teil meines Alltages sein. &#220;ber ein Jahrzehnt geh&#246;rt dieser Blog nun zu mir und ich habe mir vorgenommen ihn auch weiter zu erhalten, auch wenn ich vielleicht ein bisschen das Tempo rausnehmen m&#246;chte. F&#252;r 2019 ist (in etwa) geplant:<\/p>\n<ul>\n<li><strong>Projekte<\/strong> weiterf&#252;hren (z.B. WIB, Wochenlieblinge, 12von12, 1000 Fragen, f&#252;nffragenamf&#252;nften, evtl. das Fotoprojekt ABC u.&#228;.)<\/li>\n<li>Wieder mehr <strong>DIY Projekte<\/strong> auf dem Blog vorstellen<\/li>\n<li>weiterhin <strong>Ausmalbilder<\/strong> f&#252;r euch erstellen<\/li>\n<li><strong>Kinderbuch<\/strong> &#8211; Empfehlungen<\/li>\n<li>Ihr habt euch <strong>Planertipps<\/strong> gew&#252;nscht<\/li>\n<li>Mehr <strong>Rezepte<\/strong> ausprobieren und mit euch teilen<\/li>\n<li>Auf anderen Blogs mehr <strong>kommentieren<\/strong> und so den Austausch untereinander f&#246;rdern<\/li>\n<\/ul>\n<h2>Erscheint euch das viel? Mir nicht&#8230;<\/h2>\n<p>Ich werde noch sehen, wie ich das nun durch das ganze Jahr tragen werde. Angedacht ist, dass ich mich gerne monatlich eurem strengen Blick stellen und alles auf dem Blog transparent halten m&#246;chte. Immer zu Beginn des neuen Monats also auf die Vorhaben des alten Monats schauen, die ich jeden Monat neu definiere. In kleinen Schritten und teilweise passend zur Jahreszeit. Nicht alles ist zu jeder Jahreszeit m&#246;glich. Den Schuppen kann man zum Beispiel nur bei deutlich besserem Wetter aussortieren. Ab und an m&#246;chte ich einzelnen Aktionen zumindest ansatzweise unter einer Art Arbeitstitel hier dann auch vorstellen. Angefangene Kreativ &#8211; Projekte zum Beispiel, kleine Erfolge mit euch teilen oder Ideen an euch weitergeben.&nbsp;<\/p>\n<p>Das sind die Gedanken und Ergebnisse meiner &#220;berlegungen der letzten Tage. Ich denke in den folgenden Tagen werde ich meine Januar &#8211; Ziele nochmal vollst&#228;ndig ausformulieren, auch wenn ich daf&#252;r nun doch schon reichlich sp&#228;t dran bin, aber irgendwo muss man ja anfangen, nicht wahr?<\/p>\n<p>Mal sehen, wie es in diesem Jahr f&#252;r mich funktionieren und wie nachhaltig das Ganze tats&#228;chlich sein wird. Wie geht ihr in diesem Jahr damit um?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36568 alignright\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2018\/04\/sari-unter.jpg\" alt=\"\" width=\"130\" height=\"59\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Werbung \u2013 Der folgende Artikel enth&#228;lt evtl. Bilder mit Produkten, die wir in unserem Alltag nutzen oder Linkempfehlungen. Wir haben keine Bezahlung f&#252;r das Zeigen oder Nutzen derselbigen erhalten. Da sitze ich nun also an meinem Esstisch und schreibe. Ich schreibe hier seit Tagen auf dem Blog, dass ich gro&#223;e Pl&#228;ne habe. Vors&#228;tze. Ihr kennt das. Jedes Jahr wieder aufs Neue. Immer wieder. Die Dinge, die man sich vornimmt und die man doch nie so richtig umgesetzt bekommt. Wenn ich auf meine Listen und Projekte der vergangenen Jahre blicke, dann kann ich eigentlich nur eines feststellen: Es wiederholt sich! Die Dinge kommen immer wieder. Es ist weniger ein Vornehmen, als vielmehr ein erhalten der Vors&#228;tze. Jedes Jahr wieder steht es auf meiner Liste. Das Abnehmen. Das bessere Essen. Das mehr kreativ sein. Das Thema Selbstliebe. Immer und immer wieder die gleichen Dinge. Kann ich es also tats&#228;chlich so sehen, dass ich neue Vors&#228;tze ausformulier oder schaue ich eher auf die Dinge, die ich bisher geschafft habe und &#252;berlege mir, wie ich weiter daran arbeiten kann? Ich denke, das ist der Punkt: Ich befinde mich jedes Jahr wieder auf dem gleichen Weg. Es sind diese Standard &#8211; Vors&#228;tze, die ein jeder von uns hat. Mehr Bewegung, ges&#252;nderes Essen, mehr an sich selber denken und an die Dinge, die einem wichtig sind. Sie ver&#228;ndern sich nur ein kleines bisschen und sie sind in meinem Kopf (glaube ich) immer deshalb zu Beginn eines neuen Jahres so pr&#228;sent, weil ich zum Jahresende hin schw&#228;chle. Die Weihnachtszeit kommt. Mit all dem S&#252;&#223;kram. Es ist dunkel und grau, das Wetter schlecht und die Bewegung l&#228;sst nach. Im Sommer f&#228;llt es einem zum Beispiel so viel leichter aktiver und ges&#252;nder unterwegs zu sein. Als ich nun also an meinem Esstisch sa&#223; und verschiedene Brainstormings anstellte, sah ich am Ende auf meine Zettel und musste feststellen: Es hat sich nicht viel ge&#228;ndert. Nur bei den Unterpunkten hat sich etwas getan. Die Priorit&#228;ten in den einzelnen Bereichen haben sich etwas verschoben oder sind pr&#228;ziser geworden. Wie gehe ich also damit um. Eine Erkenntnis ereilte mich: Ich brauche diese Selbstkontrolle! Einer der Gr&#252;nde, warum ich so effektiv gearbeitet habe, als ich mein Jahr durch das 12in2012 oder gar dem Sparkle &amp; Shine begleiten lie&#223;, war sicher der, dass ich mich monatlich selber kontrollieren musste. Offen f&#252;r andere. Es blieb also am Ende dieser Druck, dass ich nicht nur vor mir rechtfertigen musste, wenn ich etwas nicht gemacht hatte, sondern eben auch vor anderen. Ich brauche Listen, die ich abhaken kann und den st&#228;ndig pr&#252;fenden Blick, der schaut, ob auch alles passt und seine Richtigkeit hat. Welchen Schluss ziehe ich also aus dieser ersten Erkenntnis (die so neu eigentlich gar nicht , aber f&#252;r die Planung in diesem Jahr dennoch wichtig ist)? Richtig&#8230; ich muss es f&#252;r mich und f&#252;r euch wieder transparenter gestalten. Daraus ergibt sich folgende logische Konsequenz: Ich brauche ein Format, das mich durch das Jahr begleitet. Doch wie soll dieses aussehen? Will ich es monatlich oder pro Quartal? Brauche ich eine Liste, die ich abhaken kann oder arbeite ich mit &#220;berbegriffen? Um das heraus zu finden, gab es ein weiteres Brainstorming. Ich berief mich auf alte Methoden. Ich schrieb zuerst 12 Ziele auf, die ich im Auge behalten wollte. F&#252;r jeden Monat eines quasi. Ich wollte zuerst einmal wissen, ob ich &#252;berhaupt auf 12 Punkte kommen w&#252;rde&#8230; Anschlie&#223;end betrachtete ich die 12 Punkte und &#252;berlegte, ob sie sich auf Oberbegriffe aufteilen lie&#223;en. Wie viele &#220;berschriften w&#252;rden da wohl entstehen und w&#252;rden sie eventuell sogar mit dem Prinzip von Sparkle &amp; Shine konform gehen, die sich mit Kopf, Herz, K&#246;rper, Emotion usw. befassten?&nbsp; Und zum Schluss nahm ich diese Begriffe, formulierte sie in meine pers&#246;nlichen Ziele um und schrieb darunter die Dinge, die mir dazu einfielen. Ich ging also ins Detail, um zu schauen, wie sich das vielleicht auf monatliche Ziele und Jahresziele aufteilen lie&#223;. Dabei heraus kam dann diese Grafik: Meine Vors&#228;tze 2019: Zeit f&#252;r Ver&#228;nderung! Nachdem ich nun also wusste, was ich gerne schaffen m&#246;chte, wollte ich dem ganzen gerne einen Arbeitstitel geben. &#8220;Lebe, Liebe, Lache&#8221; gefiel mir gut, aber auch so Phrasen wie &#8220;Make it Happen&#8221;, doch dann stand ich vor der Frage, inwiefern ich das &#252;berhaupt nutzen darf. Also hielt ich es simple. Simple as possible&#8230; oder so &#228;hnlich. Denn letztendlich ist es ein Ziel, dass ich tats&#228;chlich erreichen m&#246;chte: Eine dauerhafte und vor allem nachhaltige Ver&#228;nderung von Angewohnheiten in meinem Leben! Das Ganze teilt sich nun wie folgt auf. Meine 5 Bereiche und ihre Unterkategorien 01. Selbstliebe &#8211; Dieser Punkt ist wohl der, der in diesem Jahr die h&#246;chste Priorit&#228;t von mir erhalten wird. Ich hatte es in der Vergangenheit mehrfach angesprochen: Ich habe irgendwie einen Knick in der Optik und mag mich gar nicht mehr. Daran muss und m&#246;chte ich in diesem Jahr weiterhin arbeiten. Das Ganze teilt sich in einige Unterziele auf: Fitness &amp; Muskelaufbau: Weiterhin m&#246;chte ich, dass Sport ein fester Bestandteil meines Alltages ist. Im letzten Jahr gelang mir das schon ganz gut, aber ich m&#246;chte es in diesem Jahr gezielter angehen. Der R&#252;cken muss gest&#228;rkt, der Bauch und die Oberschenkeln gestrafft und die Oberarme minimiert werden. So meine Sicht der Dinge. Ern&#228;hrung, Zucker, Wasser: Weniger naschen, mehr Obst und Gem&#252;se und mal wieder mehr Wasser als anderes zum Trinken. Im Grunde das &#252;bliche, aber ich m&#246;chte meine Ern&#228;hrung und mein Trinkverhalten etwas optimieren. Daraus ergibt sich: Ein Wohlf&#252;hlgewicht finden und ein Bild von mir schaffen, das ich gerne auf Fotos und im Spiegel sehe Me &#8211; Time: Zeit f&#252;r mich. 10 Minuten am Tag, in denen ich nichts mache, was mit Haushalt, Arbeit, Kinder oder sonst was zu tun hat. Frei von jeglichen Verpflichtungen. Einfach nur ich. Vielleicht gef&#252;llt mit Yoga oder einer Art Meditation, um besser in mich hineinsehen und mich verstehen zu k&#246;nnen. Mal sehen, was sich da finden l&#228;sst. Und wenn es nur ein kurzer Spaziergang um die H&#228;user ist. 02. Kreativit&#228;t &#8211; Nicht nur ich habe den Wunsch danach alte Hobbies wieder aufleben zu lassen, sondern auch euer Feedback hat mir zu verstehen gegeben, dass ihr euch wieder mehr von diesen Inhalten w&#252;nscht. Mit einem Blick auf die Dinge, die mein Umfeld umgeben, bin ich dabei auf folgende Bereiche und Ziele gekommen: Lesen: In den letzten Jahren habe ich kaum ein Buch lesen k&#246;nnen. Meine Hauptlekt&#252;re bestand aus Kinderb&#252;chern, was grunds&#228;tzlich toll ist, aber ich habe einige B&#252;cher, die ich schon l&#228;nger gerne mal lesen wollte. Also gibt es einen Stapel, den ich dieses Jahr gerne schaffen m&#246;chte. Insgesamt sind es bisher 5 B&#252;cher, die ich mir vorgenommen habe. Erscheint mir recht realistisch. H&#228;keln: Ich habe mir Ende letztens Jahres zwei bunte Kn&#228;uel Wolle gekauft. Aus einem Impuls heraus. Daraus m&#246;chte ich in diesem Jahr etwas h&#228;keln. Vermutlich eine Decke. Das ist mein Ziel.&nbsp; N&#228;hen: Die Kinder brauchen nicht unbedingt neue Klamotten, aber dann und wann schon. Besonders Hosen f&#252;r den Kleinen und deshalb m&#246;chte ich auch da wieder mehr tun in diesem Jahr. Aber nicht nur Kleidung: Ich m&#246;chte die Kissenbez&#252;ge f&#252;r die Couch selber n&#228;hen. Da einfach wieder mehr machen. Zeichnen: Da gibt es zwar dank der Ausmalbilder eine gewisse Regelm&#228;&#223;igkeit, doch ich m&#246;chte da doch wieder mehr machen. Ich nehme mir das jedes Jahr vor, aber dieses Mal habe ich ein Ziel: Ich m&#246;chte monatlich einen Comic schaffen und den Umgang mit dem Grafiktablett lernen. 03. Familienmensch &#8211; Mit einem Sohn, der Fu&#223;ball im Verein spielt und einem zweiten, der die selbe Tendenz zeigt, ist Freizeit etwas Seltenes. Zumindest hat sich dieses Gef&#252;hl in den letzten drei Jahren sehr verst&#228;rkt. Dazu kommt Arbeit, Schule, Kita und andere normale Termine, die kaum Luft f&#252;r Freizeit lassen. Daher ebenfalls wichtig: Zeit f&#252;r die Familie! Zeit im Alltag finden f&#252;r sch&#246;ne&nbsp;Aktivit&#228;ten. Es muss gar nicht viel sein. Ein Ausflug auf den Spielplatz oder &#246;fter ein Ausflug im n&#228;heren Umfeld. Ruhige, gemeinsame Momente zu Hause schaffen. Einen Spielenachmittag einf&#252;hren und wieder mehr gemeinsam basteln. Mehr von der Stadt sehen. Das haben wir uns schon einmal vorgenommen. Es gibt noch so viele Dinge, die unsere Stadt zu bieten hat, die wir noch nicht gesehen haben. Vielleicht schaffen wir auch gemeinsame neue Rituale, die sich gut in den sich st&#228;ndig ver&#228;ndernden Alltag integrieren lassen. 04. Home sweet Home &#8211; Das ist ein Bereich, der den Helden und mich in diese Jahr noch sehr besch&#228;ftigen wird. Die gro&#223;e Baustelle ist zwar weg, doch gibt es noch viele kleine Dinge auf unserer Liste, die erledigt werden m&#252;ssen. Ein 30 Jahre altes Haus hat seine Macken und Spuren der letzten Jahre. Manches muss noch ersetzt, anderes neu gemacht werden. Hier fehlt noch eine Steckdose, dort eine Leiste. Auch m&#252;ssen wir noch einiges ausmisten. Nach wie vor m&#246;chte ich eine Routine f&#252;r den Haushalt entwickeln Familien &#8211; Schaltzentrale optimieren Dachboden ausmisten Schuppen ausmisten Garten weiter anpassen (nachdem im Herbst die Hecken raus sind, m&#252;ssen wir dort nun etwas Neues hinmachen). Kleinigkeiten im Haus Papierkram ausmisten, ordnen, einsortieren 05. Bloggerleben &#8211; Auch wenn das Leben als Blogger nicht unbedingt einfacher wird, soll es nach wie vor ein Teil meines Alltages sein. &#220;ber ein Jahrzehnt geh&#246;rt dieser Blog nun zu mir und ich habe mir vorgenommen ihn auch weiter zu erhalten, auch wenn ich vielleicht ein bisschen das Tempo rausnehmen m&#246;chte. F&#252;r 2019 ist (in etwa) geplant: Projekte weiterf&#252;hren (z.B. WIB, Wochenlieblinge, 12von12, 1000 Fragen, f&#252;nffragenamf&#252;nften, evtl. das Fotoprojekt ABC u.&#228;.) Wieder mehr DIY Projekte auf dem Blog vorstellen weiterhin Ausmalbilder f&#252;r euch erstellen Kinderbuch &#8211; Empfehlungen Ihr habt euch Planertipps gew&#252;nscht Mehr Rezepte ausprobieren und mit euch teilen Auf anderen Blogs mehr kommentieren und so den Austausch untereinander f&#246;rdern Erscheint euch das viel? Mir nicht&#8230; Ich werde noch sehen, wie ich das nun durch das ganze Jahr tragen werde. Angedacht ist, dass ich mich gerne monatlich eurem strengen Blick stellen und alles auf dem Blog transparent halten m&#246;chte. Immer zu Beginn des neuen Monats also auf die Vorhaben des alten Monats schauen, die ich jeden Monat neu definiere. In kleinen Schritten und teilweise passend zur Jahreszeit. Nicht alles ist zu jeder Jahreszeit m&#246;glich. Den Schuppen kann man zum Beispiel nur bei deutlich besserem Wetter aussortieren. Ab und an m&#246;chte ich einzelnen Aktionen zumindest ansatzweise unter einer Art Arbeitstitel hier dann auch vorstellen. Angefangene Kreativ &#8211; Projekte zum Beispiel, kleine Erfolge mit euch teilen oder Ideen an euch weitergeben.&nbsp; Das sind die Gedanken und Ergebnisse meiner &#220;berlegungen der letzten Tage. Ich denke in den folgenden Tagen werde ich meine Januar &#8211; Ziele nochmal vollst&#228;ndig ausformulieren, auch wenn ich daf&#252;r nun doch schon reichlich sp&#228;t dran bin, aber irgendwo muss man ja anfangen, nicht wahr? Mal sehen, wie es in diesem Jahr f&#252;r mich funktionieren und wie nachhaltig das Ganze tats&#228;chlich sein wird. Wie geht ihr in diesem Jahr damit um?<\/p>\n","protected":false},"author":1,"featured_media":43651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[50],"tags":[336,45,69,523,2162,2163,566],"class_list":["post-43473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gedanken","tag-veraenderung","tag-alltag","tag-familie","tag-gute-vorsaetze","tag-jahresnanfang","tag-vorsatz","tag-vorsaetze"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zeit f\u00fcr Ver\u00e4nderung: Die Sache mit den guten Vors\u00e4tzen...<\/title>\n<meta name=\"description\" content=\"Da sitze ich nun also an meinem Esstisch und schreibe. Ich schreibe hier seit Tagen, dass ich gro\u00dfe Pl\u00e4ne habe. Vors\u00e4tze. Ihr kennt das.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeit f\u00fcr Ver\u00e4nderung: Die Sache mit den guten Vors\u00e4tzen...\" \/>\n<meta property=\"og:description\" content=\"Da sitze ich nun also an meinem Esstisch und schreibe. Ich schreibe hier seit Tagen, dass ich gro\u00dfe Pl\u00e4ne habe. Vors\u00e4tze. Ihr kennt das.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-08T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-08T09:28:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"Zeit f&#252;r Ver&#228;nderung: Die Sache mit den guten Vors&#228;tzen&#8230;\",\"datePublished\":\"2019-01-08T09:00:00+00:00\",\"dateModified\":\"2019-01-08T09:28:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/\"},\"wordCount\":1907,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/zfv03.jpg\",\"keywords\":[\"#ver\u00e4nderung\",\"Allt\u00e4glich\",\"Familie\",\"Gute Vors\u00e4tze\",\"Jahresnanfang\",\"Vorsatz\",\"Vors\u00e4tze\"],\"articleSection\":[\"Gedankenwelt\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/\",\"name\":\"Zeit f\u00fcr Ver\u00e4nderung: Die Sache mit den guten Vors\u00e4tzen...\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/zfv03.jpg\",\"datePublished\":\"2019-01-08T09:00:00+00:00\",\"dateModified\":\"2019-01-08T09:28:42+00:00\",\"description\":\"Da sitze ich nun also an meinem Esstisch und schreibe. Ich schreibe hier seit Tagen, dass ich gro\u00dfe Pl\u00e4ne habe. Vors\u00e4tze. Ihr kennt das.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/zfv03.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/zfv03.jpg\",\"width\":1000,\"height\":728,\"caption\":\"Ver\u00e4nderung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2019\\\/01\\\/08\\\/gute-vorsaetze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zeit f&#252;r Ver&#228;nderung: Die Sache mit den guten Vors&#228;tzen&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zeit f\u00fcr Ver\u00e4nderung: Die Sache mit den guten Vors\u00e4tzen...","description":"Da sitze ich nun also an meinem Esstisch und schreibe. Ich schreibe hier seit Tagen, dass ich gro\u00dfe Pl\u00e4ne habe. Vors\u00e4tze. Ihr kennt das.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/","og_locale":"de_DE","og_type":"article","og_title":"Zeit f\u00fcr Ver\u00e4nderung: Die Sache mit den guten Vors\u00e4tzen...","og_description":"Da sitze ich nun also an meinem Esstisch und schreibe. Ich schreibe hier seit Tagen, dass ich gro\u00dfe Pl\u00e4ne habe. Vors\u00e4tze. Ihr kennt das.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/","og_site_name":"Heldenhaushalt","article_published_time":"2019-01-08T09:00:00+00:00","article_modified_time":"2019-01-08T09:28:42+00:00","og_image":[{"width":1000,"height":728,"url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv03.jpg","type":"image\/jpeg"}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"Zeit f&#252;r Ver&#228;nderung: Die Sache mit den guten Vors&#228;tzen&#8230;","datePublished":"2019-01-08T09:00:00+00:00","dateModified":"2019-01-08T09:28:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/"},"wordCount":1907,"commentCount":4,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv03.jpg","keywords":["#ver\u00e4nderung","Allt\u00e4glich","Familie","Gute Vors\u00e4tze","Jahresnanfang","Vorsatz","Vors\u00e4tze"],"articleSection":["Gedankenwelt"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/","name":"Zeit f\u00fcr Ver\u00e4nderung: Die Sache mit den guten Vors\u00e4tzen...","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv03.jpg","datePublished":"2019-01-08T09:00:00+00:00","dateModified":"2019-01-08T09:28:42+00:00","description":"Da sitze ich nun also an meinem Esstisch und schreibe. Ich schreibe hier seit Tagen, dass ich gro\u00dfe Pl\u00e4ne habe. Vors\u00e4tze. Ihr kennt das.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv03.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/01\/zfv03.jpg","width":1000,"height":728,"caption":"Ver\u00e4nderung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2019\/01\/08\/gute-vorsaetze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"Zeit f&#252;r Ver&#228;nderung: Die Sache mit den guten Vors&#228;tzen&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":2373,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/43473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=43473"}],"version-history":[{"count":4,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/43473\/revisions"}],"predecessor-version":[{"id":43656,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/43473\/revisions\/43656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media\/43651"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=43473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=43473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=43473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}