{"id":56710,"date":"2022-11-30T10:00:00","date_gmt":"2022-11-30T09:00:00","guid":{"rendered":"https:\/\/www.heldenhaushalt.de\/sari02\/?p=56710"},"modified":"2022-11-30T10:08:41","modified_gmt":"2022-11-30T09:08:41","slug":"30-dinge-und-die-bestofnine-im-november","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/","title":{"rendered":"30 Dinge und die #bestofnine im November"},"content":{"rendered":"<p style=\"text-align: right;\"><small>Enth&#228;lt (unbezahlte) Werbung*<\/small><\/p>\n<p>Und schon wieder ist ein Monat vorbei. Der November war irgendwie gef&#252;hlt so eine Art Zwischenwelt, in der wir uns bewegt haben. Noch nicht Winter, aber auch irgendwie nicht mehr Herbst. Und wir hatten einen langen milden Herbst, wie ich finde. Daf&#252;r hatte der November irgendwie alles zu bieten.<\/p>\n<p>Und was das alles war, das will ich heute wieder in unserem kleinen monatlichen R&#252;ckblick zusammenfassen. 30 Dinge, die unvergessen sein wollen. 30 sch&#246;ne Erinnerungen oder zumindest Ereignisse, die den November zu dem Monat gemacht haben, der er f&#252;r uns als Familie war. Dazu dann wieder ein paar Eindr&#252;cke, die ich mit euch auf Instagram geteilt habe. Wie aktiv seid ihr dort eigentlich? Was ist eure liebste Plattform, die ihr aktuell gerne nutzt?<\/p>\n<h2>30 Dinge im Oktober und die #bestofnine<\/h2>\n<figure id=\"attachment_56797\" aria-describedby=\"caption-attachment-56797\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-56797 size-full\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-01.jpg\" alt=\"#bestofnine\" width=\"1000\" height=\"349\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-01.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-01-300x105.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-01-768x268.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-01-172x60.jpg 172w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-56797\" class=\"wp-caption-text\"><small> #bestofnine im November<\/small><\/figcaption><\/figure>\n<p><strong>1.&nbsp;<\/strong> Der November startet f&#252;r uns <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/06\/unsere-wochenlieblinge-432022\/\">mit einem Fu&#223;ball-Camp<\/a>. 5 Tage lang besucht er jeden Tag den Fu&#223;ballplatz und erh&#228;lt an Stationen durch F&#246;rdertrainer ein zus&#228;tzliches Training. Er liebt es und ich bin immer wieder da um zuzuschauen.<\/p>\n<p><strong>2.<\/strong> Der kleine Sohn und ich sind einen Nachmittag alleine unterwegs und besuchen <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/07\/unser-wib-am-05-06-11-2022\/\">einen Laden voller Noppensteine<\/a>. Der Sohn ist im Paradies.<\/p>\n<p><strong>3.<\/strong> Im November steht nat&#252;rlich auch das Laternenfest auf dem Plan und wir basteln in der Schule niedliche &#8220;Das kleine WIR&#8221;-Laternen.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/43-03.jpg\" alt=\"Fu&#223;ball Camp\"><\/p>\n<p><strong>4.<\/strong> Highlight beim Fu&#223;ball-Camp f&#252;r den kleinen Sohn: Er gewinnt das Amsterdam Turnier und geht sogar aus dem gesamten Turnier als Spieler mit der h&#246;chsten Punktzahl hervor. Daf&#252;r gibt es einen Riesen-Lolli, den er mit seinem gro&#223;en Bruder teilt.<\/p>\n<p><strong>5.<\/strong> Das Wetter ist mild und sonnig und ich genie&#223;e das total. Ich komme mit meiner geliebten Weste locker nochmal durch den halben November. Die ist wirklich Gold wert und war die beste Anschaffung dieses Jahr, was Wetter angeht.<\/p>\n<p><strong>6.<\/strong> Ich nutze die Tatsache aus, dass ich fast t&#228;glich am Sportplatz die erste Woche war und gehe <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/06\/unsere-wochenlieblinge-432022\/\">an 4 von 5 Tagen laufen<\/a>. Allerdings jeden Tag ein anderer Modus. Ich probiere mich n&#228;mlich an gef&#252;hrten L&#228;ufen: Regenerationsl&#228;ufe, Speed-Runs und Intervall-L&#228;ufe. Dadurch lerne ich meinen K&#246;rper und meine F&#228;higkeiten nochmal vollkommen neu kennen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/43-04.jpg\" alt=\"30 Dinge\" width=\"1000\" height=\"735\"><\/p>\n<p><strong>7.<\/strong> Bei einem Shopping-Nachmittag mit dem kleinen Sohn bekommt er in einem Einkaufsladen ganze 17 T&#252;ten mit Fu&#223;ball-Karten f&#252;r ein Sammelalbum geschenkt. Den Rest der fehlenden Karten bekommen wir &#252;ber Freunde zusammen, so dass er am Ende des Monats wirklich die Bonuskarte beantragen kann, die man nur bekommt, wenn man alle Karten beisammen hat.<\/p>\n<p><strong>8.<\/strong> Der gro&#223;e Sohn ist <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/11\/unsere-wochenlieblinge-442022-ferien-zu-ende-chaos-im-kopf\/\">fast den gesamten Monat erk&#228;ltet<\/a> und muss vieles absagen. Das tut mir unendlich leid f&#252;r ihn. Der kleine Sohn dagegen ist st&#228;ndig verabredet oder an der frischen Luft. Auch er ist zwar hin und wieder erk&#228;ltet, aber bei ihm ist das irgendwie besser zu handhaben.<\/p>\n<p><strong>9.<\/strong> Wir bauen an coolen Klemmbaustein-Landschaften. Dabei entsteht auf <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/07\/unser-wib-am-05-06-11-2022\/\">einer kleinen Platte eine Star Wars Welt<\/a>, wo Gut gegen B&#246;se k&#228;mpfen soll.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/44-04.jpg\" alt=\"Wochenlieblinge\"><\/p>\n<p><strong>10.<\/strong> Ich gehe alleine spazieren, nachdem ich den kleinen Sohn bei einer Verabredung vorbei gebracht habe. Das erste Mal verabredet mit einem Kind aus der neuen Klasse. Das war schon ein Highlight. Jedenfalls wandere ich bei einem wundersch&#246;nen Sonnenuntergang an einem See entlang.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/44-06.jpg\" alt=\"Klemmbausteine\"><\/p>\n<p><strong>11.<\/strong> Wir bekommen die Klemmbaustein-Landschaft fertig und der kleine Sohn spielt mit gro&#223;er Begeisterung damit. Ich bin von der Qualit&#228;t der Steine echt positiv &#252;berrascht und freue mich, dass der Sohn tats&#228;chlich auch gerne damit spielt. Wir &#252;berlegen ernsthaft das Zimmer in eine Klemmbausteine-Werkstatt umzubauen *lach*.<\/p>\n<p><strong>12.<\/strong> Mitte November, direkt vom Laternenfest aus, d&#252;sen wir wieder zum Schwimmkurs. Dieser endet Anfang Dezember und bis dahin soll der kleine Sohn unbedingt sein Seepferdchen schaffen. Oh man&#8230; da ist jede Stunde wichtig. Am Tag des Laternenumzugs dann ein weiteres Erfolgserlebnis: <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/11\/unsere-wochenlieblinge-442022-ferien-zu-ende-chaos-im-kopf\/\">Er schafft zwei Mal 15 Meter ohne jegliches Hilfsmittel<\/a>. Ab jetzt ist der Sohn hochmotiviert!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/wib46-01.jpg\" alt=\"30 Dinge\" width=\"1000\" height=\"747\"><\/p>\n<p><strong>13.<\/strong> Es gibt Knacker mit Gr&#252;nkohl. Die Kinder sind semi begeistert, aber ab und an m&#252;ssen der Mann und ich uns auch mal ein Mittagessen g&#246;nnen, das den Kindern nicht schmeckt *lach*.<\/p>\n<p><strong>14.<\/strong> Wir fahren noch einmal <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/14\/unser-wib-am-12-13-11-2022\/\">als Familie zu Blue Brixx<\/a>, dem oben erw&#228;hnten Noppenstein-Laden. Aber dieses Mal zum Megastore in einem anderen Bezirk mit deutlich mehr Regalen voller einzelner Klemmbausteine und vielen, vielen ziemlich genialen Bausets. Mit viel Inspiration im Kopf kommen wir abends mit neuen Errungenschaften nach Hause.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/wib46-07.jpg\" alt=\"Bluebrixx\" width=\"1000\" height=\"720\"><\/p>\n<p><strong>15.<\/strong> Zusammen mit Papa und Mama wird an einem Warden gebaut, einer Figur, die es wohl in Minecraft gibt. Gar nicht so einfach, aber am Ende gelingt uns ein<a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/14\/unser-wib-am-12-13-11-2022\/\"> zufriedenstellendes Ergebnis<\/a>. Werden wir noch zu Baumeistern? Wer wei&#223;.<\/p>\n<p><strong>16.<\/strong> Der Sohn hat ein Testspiel mit dem &#8220;Endboss&#8221;. Einer der schwierigsten Gegner, die wir so in der Altersklasse des kleinen Sohnes erwarten. Aus dem Testspiel <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/14\/unser-wib-am-12-13-11-2022\/\">wurde ein kleines Turnier<\/a>, weil pl&#246;tzlich noch mehr Mannschaften da waren. Die Jungs schlagen sich super und erzielen ein unerwartet gutes Ergebnis!<\/p>\n<p><strong>17.<\/strong> Am Abend belohnen wir uns mit Kekse, N&#252;ssen, einem Familienfilm und dem ersten Gl&#252;hwein des Jahres.<\/p>\n<figure id=\"attachment_56798\" aria-describedby=\"caption-attachment-56798\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-56798 size-full\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-02.jpg\" alt=\"#bestofnine\" width=\"1000\" height=\"356\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-02.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-02-300x107.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-02-768x273.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-02-169x60.jpg 169w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-56798\" class=\"wp-caption-text\"><small>#bestofnine im November<\/small><\/figcaption><\/figure>\n<p><strong>18.<\/strong> Langsam aber sicher wird es nun doch immer k&#228;lter da drau&#223;en und die Katzen nutzen jede Gelegenheit, um zu kuscheln oder sich bei einem aufzuw&#228;rmen. Und wenn nicht das, dann suchen sie sich die Ecken, wo es warm ist. An der Heizung zum Beispiel oder auf dem Geschirrsp&#252;ler, wenn er l&#228;uft. Nun zieht tats&#228;chlich der Winter ein.<\/p>\n<p><strong>19.<\/strong> So kommt es, dass wir wieder Mal <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/28\/unser-wib-am-26-27-11-2022\/\">Kekse backen<\/a>. Aber Kekse gehen ja auch wirklich immer, nicht wahr?<\/p>\n<p><strong>20.<\/strong> Und dann schneit es pl&#246;tzlich. Wie kann das sein? Na ganz einfach: Wir haben pl&#246;tzlich &#8211; 6 Grad und tags&#252;ber d&#252;mpeln wir um die 0 Grad herum. Da kann es auch mal passieren, dass <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/21\/unser-wib-am-19-20-11-2022\/\">f&#252;r ein zwei Tage so etwas &#228;hnliches wie eine d&#252;nne Decke Schnee<\/a> liegt. Die Kinder sind begeistert.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/45-03.jpg\" alt=\"30 Dinge\" width=\"1000\" height=\"786\"><\/p>\n<p><strong>21.<\/strong> Ich begleite den kleinen Sohn an einem Nachmittag mit in die Schule. Diese hat zum <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/18\/unsere-wochenlieblinge-452022\/\">Adventsbasteln eingeladen<\/a> f&#252;r den bevorstehenden Adventsbasar der Schule. Gedanklich darf ich also schon mal eine Liste an Dingen notieren, die wir dann beim Basar kaufen m&#252;ssen, weil sie ja mein Kind gebastelt hat. Da geht das Konzept der Schule wohl auf.<\/p>\n<p><strong>22.<\/strong> Wir haben ein <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/16\/gedankentagebuch-08-schulgedanken-und-fast-schon-advent\/\">Elterngespr&#228;ch in der Schule<\/a> &#252;ber den aktuellen Leistungsstand des kleinen Sohnes bzw. bekommen wir mal einen Zwischenbericht, wie er sich so macht. Das Feedback ist wirklich toll und es freut uns immer sehr, wenn wir h&#246;ren, dass der Sohn so beliebt ist und sich toll benimmt. Aber ein bisschen &#252;ben m&#252;ssen wir auch und das macht der Sohn mit gro&#223;er Begeisterung. Er liebt wirklich so gut wie alles an der Schule. Wer h&#228;tte das gedacht.<\/p>\n<p><strong>23.<\/strong> Der gro&#223;e Sohn ist zwischendurch tats&#228;chlich mal f&#252;r 1 1\/2 Wochen so gesund, dass er Schulsport und auch Training mitmachen kann und bei zwei Spielen dabei ist. Beide Spiele werden gewonnen. So sammelt er zumindest wieder ein bisschen <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/21\/unser-wib-am-19-20-11-2022\/\">positives Feedback<\/a>. Auch wenn die Wetterbedingungen echt nicht lustig sind mit vereisten oder gar eingeschneiten Pl&#228;tzen.<\/p>\n<figure id=\"attachment_56799\" aria-describedby=\"caption-attachment-56799\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-56799 size-full\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-03.jpg\" alt=\"#bestofnine\" width=\"1000\" height=\"348\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-03.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-03-300x104.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-03-768x267.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/nov22-03-172x60.jpg 172w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-56799\" class=\"wp-caption-text\"><small> #bestofnine im November<\/small><\/figcaption><\/figure>\n<p><strong>24.<\/strong> Auf Wunsch der Kinder <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/21\/unser-wib-am-19-20-11-2022\/\">backen wir Waffeln<\/a> und probieren zu diesem Anlass mal ein <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/24\/heldenkueche-einfaches-waffelrezept\/\">neues Rezept<\/a> aus, das echt super ist und mit wenig Zutaten auskommt. So gibt es ein paar Tage sp&#228;ter direkt nochmal Waffeln.<\/p>\n<p><strong>25.<\/strong> Ich werde zum Kratzbaum oder so? Frida ist an manchen Tagen wirklich ein bisschen wie ein Kind, das<a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/25\/unsere-wochenlieblinge-462022\/\"> st&#228;ndig und &#252;berall an einem dran klebt<\/a>.<\/p>\n<p><strong>26.<\/strong> Der kleine Sohn ist nun schon zur zweiten <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/28\/unser-wib-am-26-27-11-2022\/\">Geburtstagsfeier eines Schulfreundes<\/a> eingeladen. Es ist ein Fu&#223;ballgeburtstag und er hat nicht nur unglaublich viel Spa&#223;, sondern bekommt von einem Erwachsenen, der selber 30 Jahre gespielt hat (unter anderem wohl bei Hertha BSC) ganz viel Lob.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/wib48-16.jpg\" alt=\"30 Dinge\" width=\"1000\" height=\"727\"><\/p>\n<p><strong>27.<\/strong> Wir besuchen <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/28\/unser-wib-am-26-27-11-2022\/\">einen Weihnachtsrummel<\/a>, wo der kleine Sohn mit Papa Autoscooter f&#228;hrt und das Lachen gar nicht mehr aus seinem Gesicht bekommt, beim Dosenwerfen ein Pl&#252;schtier f&#252;r sich UND seinen gro&#223;en Bruder gewinnt und zwei neue Minecraft Kuscheltiere mit nach Hause nehmen darf. Ich glaube wir m&#252;ssen irgendwann mal nur f&#252;r all die Kuscheltiere ein Zimmer frei machen.<\/p>\n<p><strong>28.<\/strong> Hurraaaaaa&#8230; der kleine Sohn schafft sein Seepferdchen noch bevor der Schwimmkurs zu Ende ist. Er ist so unglaublich stolz auf sich selbst, weil er nie gedacht h&#228;tte, dass er das schaffen kann.<\/p>\n<p><strong>29.<\/strong> Zeit f&#252;r Wunschzettel. Der erste Advent liegt bereits hinter uns und ab morgen darf das erste T&#252;rchen ge&#246;ffnet werden. Da m&#252;ssen nat&#252;rlich auch Wunschzettel und Briefe f&#252;r den Weihnachtsmann geschrieben werden. Hierf&#252;r gibt es nach langer Zeit mal wieder ein Freebie f&#252;r euch, <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/29\/wunschzettel-oder-brief-freebie\/\">das ihr hier findet<\/a>.<\/p>\n<p><strong>30.<\/strong> Rechtzeitig zum 1. Dezember h&#228;ngen die selbst bef&#252;llten Adventskalender der Kinder. Ehrlich gesagt h&#228;tte ich nicht gedacht, dass ich das noch rechtzeitig schaffe, aber nun hat der Sohn sich einen Countdown gebastelt, mit dem er die Tage herunter z&#228;hlt, bis er endlich das erste T&#252;rchen &#246;ffnen kann und sie sorgen f&#252;r ein weihnachtliches Ambiente in unserem Wohnzimmer.<\/p>\n<h2>Nun beginnt die (hoffentlich) besinnliche Zeit des Jahres<\/h2>\n<p>30 Dinge im November zu finden, das war dieses Mal gar nicht so schwer und das, obwohl der gro&#223;e Sohn fast den gesamten Monat krank war, wir zwei Mal zum Arzt mussten und einmal sogar den Bereitschaftsdienst anrufen mussten. Auch der kleine Sohn hatte hin und wieder damit zu k&#228;mpfen, bekam das aber wieder besser unter Kontrolle. Wie nervig das doch alles ist. Aber Kekse, Waffeln, Familienzeit und kleine kreative Projekte waren auch Bestandteil dieses Monats und das ist so wichtig und wertvoll. Vor allem, dass man sich das auch immer wieder vor Augen f&#252;hrt.<\/p>\n<p>Nun freuen wir uns auf den Dezember. Er ist jetzt schon total voll mit Terminen, Events, Geburtstagen, Spielen, Turnieren und Feiern&#8230; eigentlich will man nur schreien, aber vieles davon ist einfach nur sch&#246;n und deshalb wollen wir uns vor allem darauf freuen und neue 30 Dinge finden, von denen ich euch dann kurz vor dem neuen Jahr erz&#228;hle. Oh man, das neue Jahr ist schon so nahe&#8230; k&#246;nnt ihr es glauben?<\/p>\n<p>An welche 30 Dinge wollt ihr euch im November zur&#252;ckerinnern?<\/p>\n<p><small><strong>*Anmerkung:<\/strong>&nbsp;Der Artikel &#252;ber unsere 30 Dinge und #bestofnine enth&#228;lt evtl. Bilder mit Produkten, die wir in unserem Alltag nutzen oder Linkempfehlungen. Wir haben keine Bezahlung f&#252;r das Zeigen oder Nutzen derselbigen erhalten. Affiliate Links sind als solche markiert.<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enth&#228;lt (unbezahlte) Werbung* Und schon wieder ist ein Monat vorbei. Der November war irgendwie gef&#252;hlt so eine Art Zwischenwelt, in der wir uns bewegt haben. Noch nicht Winter, aber auch irgendwie nicht mehr Herbst. Und wir hatten einen langen milden Herbst, wie ich finde. Daf&#252;r hatte der November irgendwie alles zu bieten. Und was das alles war, das will ich heute wieder in unserem kleinen monatlichen R&#252;ckblick zusammenfassen. 30 Dinge, die unvergessen sein wollen. 30 sch&#246;ne Erinnerungen oder zumindest Ereignisse, die den November zu dem Monat gemacht haben, der er f&#252;r uns als Familie war. Dazu dann wieder ein paar Eindr&#252;cke, die ich mit euch auf Instagram geteilt habe. Wie aktiv seid ihr dort eigentlich? Was ist eure liebste Plattform, die ihr aktuell gerne nutzt? 30 Dinge im Oktober und die #bestofnine 1.&nbsp; Der November startet f&#252;r uns mit einem Fu&#223;ball-Camp. 5 Tage lang besucht er jeden Tag den Fu&#223;ballplatz und erh&#228;lt an Stationen durch F&#246;rdertrainer ein zus&#228;tzliches Training. Er liebt es und ich bin immer wieder da um zuzuschauen. 2. Der kleine Sohn und ich sind einen Nachmittag alleine unterwegs und besuchen einen Laden voller Noppensteine. Der Sohn ist im Paradies. 3. Im November steht nat&#252;rlich auch das Laternenfest auf dem Plan und wir basteln in der Schule niedliche &#8220;Das kleine WIR&#8221;-Laternen. 4. Highlight beim Fu&#223;ball-Camp f&#252;r den kleinen Sohn: Er gewinnt das Amsterdam Turnier und geht sogar aus dem gesamten Turnier als Spieler mit der h&#246;chsten Punktzahl hervor. Daf&#252;r gibt es einen Riesen-Lolli, den er mit seinem gro&#223;en Bruder teilt. 5. Das Wetter ist mild und sonnig und ich genie&#223;e das total. Ich komme mit meiner geliebten Weste locker nochmal durch den halben November. Die ist wirklich Gold wert und war die beste Anschaffung dieses Jahr, was Wetter angeht. 6. Ich nutze die Tatsache aus, dass ich fast t&#228;glich am Sportplatz die erste Woche war und gehe an 4 von 5 Tagen laufen. Allerdings jeden Tag ein anderer Modus. Ich probiere mich n&#228;mlich an gef&#252;hrten L&#228;ufen: Regenerationsl&#228;ufe, Speed-Runs und Intervall-L&#228;ufe. Dadurch lerne ich meinen K&#246;rper und meine F&#228;higkeiten nochmal vollkommen neu kennen. 7. Bei einem Shopping-Nachmittag mit dem kleinen Sohn bekommt er in einem Einkaufsladen ganze 17 T&#252;ten mit Fu&#223;ball-Karten f&#252;r ein Sammelalbum geschenkt. Den Rest der fehlenden Karten bekommen wir &#252;ber Freunde zusammen, so dass er am Ende des Monats wirklich die Bonuskarte beantragen kann, die man nur bekommt, wenn man alle Karten beisammen hat. 8. Der gro&#223;e Sohn ist fast den gesamten Monat erk&#228;ltet und muss vieles absagen. Das tut mir unendlich leid f&#252;r ihn. Der kleine Sohn dagegen ist st&#228;ndig verabredet oder an der frischen Luft. Auch er ist zwar hin und wieder erk&#228;ltet, aber bei ihm ist das irgendwie besser zu handhaben. 9. Wir bauen an coolen Klemmbaustein-Landschaften. Dabei entsteht auf einer kleinen Platte eine Star Wars Welt, wo Gut gegen B&#246;se k&#228;mpfen soll. 10. Ich gehe alleine spazieren, nachdem ich den kleinen Sohn bei einer Verabredung vorbei gebracht habe. Das erste Mal verabredet mit einem Kind aus der neuen Klasse. Das war schon ein Highlight. Jedenfalls wandere ich bei einem wundersch&#246;nen Sonnenuntergang an einem See entlang. 11. Wir bekommen die Klemmbaustein-Landschaft fertig und der kleine Sohn spielt mit gro&#223;er Begeisterung damit. Ich bin von der Qualit&#228;t der Steine echt positiv &#252;berrascht und freue mich, dass der Sohn tats&#228;chlich auch gerne damit spielt. Wir &#252;berlegen ernsthaft das Zimmer in eine Klemmbausteine-Werkstatt umzubauen *lach*. 12. Mitte November, direkt vom Laternenfest aus, d&#252;sen wir wieder zum Schwimmkurs. Dieser endet Anfang Dezember und bis dahin soll der kleine Sohn unbedingt sein Seepferdchen schaffen. Oh man&#8230; da ist jede Stunde wichtig. Am Tag des Laternenumzugs dann ein weiteres Erfolgserlebnis: Er schafft zwei Mal 15 Meter ohne jegliches Hilfsmittel. Ab jetzt ist der Sohn hochmotiviert! 13. Es gibt Knacker mit Gr&#252;nkohl. Die Kinder sind semi begeistert, aber ab und an m&#252;ssen der Mann und ich uns auch mal ein Mittagessen g&#246;nnen, das den Kindern nicht schmeckt *lach*. 14. Wir fahren noch einmal als Familie zu Blue Brixx, dem oben erw&#228;hnten Noppenstein-Laden. Aber dieses Mal zum Megastore in einem anderen Bezirk mit deutlich mehr Regalen voller einzelner Klemmbausteine und vielen, vielen ziemlich genialen Bausets. Mit viel Inspiration im Kopf kommen wir abends mit neuen Errungenschaften nach Hause. 15. Zusammen mit Papa und Mama wird an einem Warden gebaut, einer Figur, die es wohl in Minecraft gibt. Gar nicht so einfach, aber am Ende gelingt uns ein zufriedenstellendes Ergebnis. Werden wir noch zu Baumeistern? Wer wei&#223;. 16. Der Sohn hat ein Testspiel mit dem &#8220;Endboss&#8221;. Einer der schwierigsten Gegner, die wir so in der Altersklasse des kleinen Sohnes erwarten. Aus dem Testspiel wurde ein kleines Turnier, weil pl&#246;tzlich noch mehr Mannschaften da waren. Die Jungs schlagen sich super und erzielen ein unerwartet gutes Ergebnis! 17. Am Abend belohnen wir uns mit Kekse, N&#252;ssen, einem Familienfilm und dem ersten Gl&#252;hwein des Jahres. 18. Langsam aber sicher wird es nun doch immer k&#228;lter da drau&#223;en und die Katzen nutzen jede Gelegenheit, um zu kuscheln oder sich bei einem aufzuw&#228;rmen. Und wenn nicht das, dann suchen sie sich die Ecken, wo es warm ist. An der Heizung zum Beispiel oder auf dem Geschirrsp&#252;ler, wenn er l&#228;uft. Nun zieht tats&#228;chlich der Winter ein. 19. So kommt es, dass wir wieder Mal Kekse backen. Aber Kekse gehen ja auch wirklich immer, nicht wahr? 20. Und dann schneit es pl&#246;tzlich. Wie kann das sein? Na ganz einfach: Wir haben pl&#246;tzlich &#8211; 6 Grad und tags&#252;ber d&#252;mpeln wir um die 0 Grad herum. Da kann es auch mal passieren, dass f&#252;r ein zwei Tage so etwas &#228;hnliches wie eine d&#252;nne Decke Schnee liegt. Die Kinder sind begeistert. 21. Ich begleite den kleinen Sohn an einem Nachmittag mit in die Schule. Diese hat zum Adventsbasteln eingeladen f&#252;r den bevorstehenden Adventsbasar der Schule. Gedanklich darf ich also schon mal eine Liste an Dingen notieren, die wir dann beim Basar kaufen m&#252;ssen, weil sie ja mein Kind gebastelt hat. Da geht das Konzept der Schule wohl auf. 22. Wir haben ein Elterngespr&#228;ch in der Schule &#252;ber den aktuellen Leistungsstand des kleinen Sohnes bzw. bekommen wir mal einen Zwischenbericht, wie er sich so macht. Das Feedback ist wirklich toll und es freut uns immer sehr, wenn wir h&#246;ren, dass der Sohn so beliebt ist und sich toll benimmt. Aber ein bisschen &#252;ben m&#252;ssen wir auch und das macht der Sohn mit gro&#223;er Begeisterung. Er liebt wirklich so gut wie alles an der Schule. Wer h&#228;tte das gedacht. 23. Der gro&#223;e Sohn ist zwischendurch tats&#228;chlich mal f&#252;r 1 1\/2 Wochen so gesund, dass er Schulsport und auch Training mitmachen kann und bei zwei Spielen dabei ist. Beide Spiele werden gewonnen. So sammelt er zumindest wieder ein bisschen positives Feedback. Auch wenn die Wetterbedingungen echt nicht lustig sind mit vereisten oder gar eingeschneiten Pl&#228;tzen. 24. Auf Wunsch der Kinder backen wir Waffeln und probieren zu diesem Anlass mal ein neues Rezept aus, das echt super ist und mit wenig Zutaten auskommt. So gibt es ein paar Tage sp&#228;ter direkt nochmal Waffeln. 25. Ich werde zum Kratzbaum oder so? Frida ist an manchen Tagen wirklich ein bisschen wie ein Kind, das st&#228;ndig und &#252;berall an einem dran klebt. 26. Der kleine Sohn ist nun schon zur zweiten Geburtstagsfeier eines Schulfreundes eingeladen. Es ist ein Fu&#223;ballgeburtstag und er hat nicht nur unglaublich viel Spa&#223;, sondern bekommt von einem Erwachsenen, der selber 30 Jahre gespielt hat (unter anderem wohl bei Hertha BSC) ganz viel Lob. 27. Wir besuchen einen Weihnachtsrummel, wo der kleine Sohn mit Papa Autoscooter f&#228;hrt und das Lachen gar nicht mehr aus seinem Gesicht bekommt, beim Dosenwerfen ein Pl&#252;schtier f&#252;r sich UND seinen gro&#223;en Bruder gewinnt und zwei neue Minecraft Kuscheltiere mit nach Hause nehmen darf. Ich glaube wir m&#252;ssen irgendwann mal nur f&#252;r all die Kuscheltiere ein Zimmer frei machen. 28. Hurraaaaaa&#8230; der kleine Sohn schafft sein Seepferdchen noch bevor der Schwimmkurs zu Ende ist. Er ist so unglaublich stolz auf sich selbst, weil er nie gedacht h&#228;tte, dass er das schaffen kann. 29. Zeit f&#252;r Wunschzettel. Der erste Advent liegt bereits hinter uns und ab morgen darf das erste T&#252;rchen ge&#246;ffnet werden. Da m&#252;ssen nat&#252;rlich auch Wunschzettel und Briefe f&#252;r den Weihnachtsmann geschrieben werden. Hierf&#252;r gibt es nach langer Zeit mal wieder ein Freebie f&#252;r euch, das ihr hier findet. 30. Rechtzeitig zum 1. Dezember h&#228;ngen die selbst bef&#252;llten Adventskalender der Kinder. Ehrlich gesagt h&#228;tte ich nicht gedacht, dass ich das noch rechtzeitig schaffe, aber nun hat der Sohn sich einen Countdown gebastelt, mit dem er die Tage herunter z&#228;hlt, bis er endlich das erste T&#252;rchen &#246;ffnen kann und sie sorgen f&#252;r ein weihnachtliches Ambiente in unserem Wohnzimmer. Nun beginnt die (hoffentlich) besinnliche Zeit des Jahres 30 Dinge im November zu finden, das war dieses Mal gar nicht so schwer und das, obwohl der gro&#223;e Sohn fast den gesamten Monat krank war, wir zwei Mal zum Arzt mussten und einmal sogar den Bereitschaftsdienst anrufen mussten. Auch der kleine Sohn hatte hin und wieder damit zu k&#228;mpfen, bekam das aber wieder besser unter Kontrolle. Wie nervig das doch alles ist. Aber Kekse, Waffeln, Familienzeit und kleine kreative Projekte waren auch Bestandteil dieses Monats und das ist so wichtig und wertvoll. Vor allem, dass man sich das auch immer wieder vor Augen f&#252;hrt. Nun freuen wir uns auf den Dezember. Er ist jetzt schon total voll mit Terminen, Events, Geburtstagen, Spielen, Turnieren und Feiern&#8230; eigentlich will man nur schreien, aber vieles davon ist einfach nur sch&#246;n und deshalb wollen wir uns vor allem darauf freuen und neue 30 Dinge finden, von denen ich euch dann kurz vor dem neuen Jahr erz&#228;hle. Oh man, das neue Jahr ist schon so nahe&#8230; k&#246;nnt ihr es glauben? An welche 30 Dinge wollt ihr euch im November zur&#252;ckerinnern? *Anmerkung:&nbsp;Der Artikel &#252;ber unsere 30 Dinge und #bestofnine enth&#228;lt evtl. Bilder mit Produkten, die wir in unserem Alltag nutzen oder Linkempfehlungen. Wir haben keine Bezahlung f&#252;r das Zeigen oder Nutzen derselbigen erhalten. Affiliate Links sind als solche markiert.<\/p>\n","protected":false},"author":1,"featured_media":56576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[323,49],"tags":[3101,3273,45,1941,69,339,81,2110,2126,199,515,51],"class_list":["post-56710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alltag","category-blogspaehre","tag-30-dinge","tag-adventsbasteln","tag-alltag","tag-bestofnine","tag-familie","tag-instagram","tag-kinder","tag-laternenumzug","tag-november","tag-rueckblick","tag-weihnachtszeit","tag-erinnerungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>30 Dinge und die #bestofnine im November - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Und was das alles war, das will ich heute wieder in unserem kleinen monatlichen R\u00fcckblick zusammenfassen. 30 Dinge, die unvergessen sein...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30 Dinge und die #bestofnine im November - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Und was das alles war, das will ich heute wieder in unserem kleinen monatlichen R\u00fcckblick zusammenfassen. 30 Dinge, die unvergessen sein...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-30T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-30T09:08:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/43-07.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"30 Dinge und die #bestofnine im November\",\"datePublished\":\"2022-11-30T09:00:00+00:00\",\"dateModified\":\"2022-11-30T09:08:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/\"},\"wordCount\":1746,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/43-07.jpg\",\"keywords\":[\"30 Dinge\",\"Adventsbasteln\",\"Allt\u00e4glich\",\"bestofnine\",\"Familie\",\"Instagram\",\"Kinder\",\"Laternenumzug\",\"November\",\"R\u00fcckblick\",\"Weihnachtszeit\",\"Zur\u00fcckgedacht\"],\"articleSection\":[\"Alltagschaos\",\"Blogsph\u00e4re\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/\",\"name\":\"30 Dinge und die #bestofnine im November - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/43-07.jpg\",\"datePublished\":\"2022-11-30T09:00:00+00:00\",\"dateModified\":\"2022-11-30T09:08:41+00:00\",\"description\":\"Und was das alles war, das will ich heute wieder in unserem kleinen monatlichen R\u00fcckblick zusammenfassen. 30 Dinge, die unvergessen sein...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/43-07.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/43-07.jpg\",\"width\":1000,\"height\":750,\"caption\":\"Wochenlieblinge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2022\\\/11\\\/30\\\/30-dinge-und-die-bestofnine-im-november\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"30 Dinge und die #bestofnine im November\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"30 Dinge und die #bestofnine im November - Heldenhaushalt","description":"Und was das alles war, das will ich heute wieder in unserem kleinen monatlichen R\u00fcckblick zusammenfassen. 30 Dinge, die unvergessen sein...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/","og_locale":"de_DE","og_type":"article","og_title":"30 Dinge und die #bestofnine im November - Heldenhaushalt","og_description":"Und was das alles war, das will ich heute wieder in unserem kleinen monatlichen R\u00fcckblick zusammenfassen. 30 Dinge, die unvergessen sein...","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/","og_site_name":"Heldenhaushalt","article_published_time":"2022-11-30T09:00:00+00:00","article_modified_time":"2022-11-30T09:08:41+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/43-07.jpg","type":"image\/jpeg"}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"30 Dinge und die #bestofnine im November","datePublished":"2022-11-30T09:00:00+00:00","dateModified":"2022-11-30T09:08:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/"},"wordCount":1746,"commentCount":0,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/43-07.jpg","keywords":["30 Dinge","Adventsbasteln","Allt\u00e4glich","bestofnine","Familie","Instagram","Kinder","Laternenumzug","November","R\u00fcckblick","Weihnachtszeit","Zur\u00fcckgedacht"],"articleSection":["Alltagschaos","Blogsph\u00e4re"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/","name":"30 Dinge und die #bestofnine im November - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/43-07.jpg","datePublished":"2022-11-30T09:00:00+00:00","dateModified":"2022-11-30T09:08:41+00:00","description":"Und was das alles war, das will ich heute wieder in unserem kleinen monatlichen R\u00fcckblick zusammenfassen. 30 Dinge, die unvergessen sein...","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/43-07.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2022\/11\/43-07.jpg","width":1000,"height":750,"caption":"Wochenlieblinge"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2022\/11\/30\/30-dinge-und-die-bestofnine-im-november\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"30 Dinge und die #bestofnine im November"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":2047,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/56710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=56710"}],"version-history":[{"count":1,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/56710\/revisions"}],"predecessor-version":[{"id":56800,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/56710\/revisions\/56800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media\/56576"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=56710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=56710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=56710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}