{"id":61725,"date":"2024-09-03T10:00:00","date_gmt":"2024-09-03T08:00:00","guid":{"rendered":"https:\/\/www.heldenhaushalt.de\/sari02\/?p=61725"},"modified":"2024-09-03T10:12:41","modified_gmt":"2024-09-03T08:12:41","slug":"blogparaden-projekte","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/","title":{"rendered":"Blogparaden &#038; Projekte, an denen ich teilnehme"},"content":{"rendered":"<p>Fragt mich nicht wieso, aber irgendwie kam ich auf die Idee, dass es doch mal ganz nett w&#228;re alle Projekte und Blogparaden hier zusammen zu fassen und vorzustellen, an denen ich so teilnehme. Nicht zuletzt, weil in den vergangenen Monate die Community hier wieder ein bisschen gewachsen ist und mehr Austausch und Leben in der Blogsph&#228;re scheinbar wieder herrscht. Und wisst ihr was? Ich liebe das!<\/p>\n<p>Diese Projekte oder auch Blogparaden sind ja neben einer netten Inspiration f&#252;r Blogbeitr&#228;ge und Inhalte auch ein sch&#246;ner Weg zum gegenseitigen Vernetzen. Besonders davon hat die Blogsph&#228;re damals ja auch sehr gelebt. Man hat sich gegenseitig empfohlen, besucht und kommentiert. Man hat in Gespr&#228;chen miteinander Anregungen f&#252;r neue Themen bekommen und teilweise auch Freunde gefunden. Bestes Beispiel hierf&#252;r sind zum Beispiel Maru oder auch Elisa, die ich durch das Internet und die Homepage damals kennengelernt und bis heute nicht aus den Augen verloren habe. Und wir sprechen hier von mittlerweile zwei Jahrezehnten. Nicht vergessen. Und speziell Maru und ihre Familie sehen wir jedes Jahr auch pers&#246;nlich. Unsere Kinder kennen sich, sind irgendwie gemeinsam aufgewachsen, wir tanzten auf unseren Hochzeiten und wir M&#228;dels quatschen fast t&#228;glich miteinander (oder machen via Meeting Yoga). Also ja, ich finde Vernetzen wichtig.&nbsp; Aber ich schweife schon wieder ab.<\/p>\n\n<h2>Blogparaden und Projekte begleiten uns schon immer irgendwie<\/h2>\n<p>Neben dem <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/projekt-52-allgemeine-informationen\/\">Projekt 52<\/a> und dem <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/going-out-ein-kleines-rausgehprojekt\/\">Going Out<\/a>, die ich fr&#252;her selber &#252;ber mehrere Jahre leitete, gibt es viele andere sch&#246;ne Ideen, die schon lange Bestandteil dieser Seite sind und einige davon sind euch sicherlich schon aufgefallen. Sie sorgen f&#252;r eine gewisse Regelm&#228;&#223;igkeit hier im Heldenhaushalt und lassen einen Blick in unseren Alltag zu (was euch scheinbar ganz gut gef&#228;llt). Aber neben diesen Projekten gibt es auch welche, die uns zum Nachdenken anregen, uns Inspirationen liefern und einen Austausch f&#246;rdern.<\/p>\n<p>Nicht erst durch das Bloghexe Forum habe ich festgestellt, dass dieses Bed&#252;rfnis nach genau solchen Ideen, ziemlich gro&#223; ist. Es wird immer wieder danach Ausschau gehalten und deshalb dachte ich, gebe ich heute mal eine kleine Zusammenfassung der Blogparaden, die uns hier auf dem Heldenhaushalt begleiten. Auch um eventuelle Fragen zu diesen mal in einem Rutsch zu beantworten. Vielleicht ist ja auch die eine oder andere dazwischen, die etwas f&#252;r Euch w&#228;re.<\/p>\n<h2>Eine kleine Zusammenfassung aller Projekte und Paraden auf Heldenhaushalt<\/h2>\n<p><strong>01. WIB &#8211; Oder auch &#8220;Wochenende in Bildern&#8221;<\/strong><br \/>\nUrspr&#252;nglich war das &#8220;WIB&#8221; mal ein <a href=\"https:\/\/geborgen-wachsen.de\/2014\/09\/17\/initiative-wochenende-in-bildern\/\" target=\"_blank\" rel=\"noopener\">Projekt von Susanne Mierau<\/a> von Geborgen Wachsen, wurde aber vor einigen Jahre von <a href=\"https:\/\/www.grossekoepfe.de\/\" target=\"_blank\" rel=\"noopener\">Alu und Konsti von Grossek&#246;pfe<\/a> &#252;bernommen. Familien nehmen einen mit durch den Alltag und zeigen dabei, wie die Wochenenden bei anderen aussehen k&#246;nnen, wenn die Kinder nicht in Schule und Kita sind. Und dabei ist es egal, ob das Wochenende langweilig, aufregend, verr&#252;ckt oder banal ist. Es sollte eine Art Verbundenheit erzeugen und das tat es damals auch. So gab es auch viele sch&#246;ne Ideen und Inspirationen, aber auch die Erkenntnis, dass es bei anderen manchmal auch nicht viel aufregender aussieht, als bei einem selbst. Alltag halt. Mehr dazu k&#246;nnt ihr auch heute noch bei Susanne nachlesen. Mitmachen kann aber eigentlich jeder, der uns mit durch seinen Alltag nehmen m&#246;chte und gerade die Wochenenden bieten ja doch viel Potential etwas zu zeigen und manchmal eben auch nichts. So sieht man bei uns ja meistens vor allem den Alltag mit Fu&#223;ballkindern, aber das kann auch genauso spannend sein f&#252;r andere, die dar&#252;ber nachdenken ob das auch etwas f&#252;r sie w&#228;re. Oder man findet Leidensgenossen, die auch jedes Wochenende am Spielfeldrand stehen. Dieses Projekt begleitet uns nun schon seit 2016 und <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2016\/03\/28\/mein-oster-wochenende-in-bildern-heute-auch-mal-hier\/\">der erste Beitrag dazu ist hier<\/a>. Oh weia, ist das auch schon wieder lange her. Dieses Projekt ist ein w&#246;chentliches Projekt.<\/p>\n<p><strong>02. Die Wochenlieblinge<\/strong><br \/>\nInzwischen sind die Wochenlieblinge ein w&#246;chentliches Projekt, das ich in Eigeninitiative stattfinden lasse. Im Grunde fasse ich hier jeden Freitag meine Highlights der Woche zusammen. Dinge, an die ich mich gerne erinnern m&#246;chte. Nicht immer sind es Highlights, sondern einfach Sachen die ich gemacht oder erlebt habe, aber da sie mir beim Schreiben in den Kopf kommen, scheinen sie mir wichtig zu sein und so landen sie in diesem Beitrag. Tats&#228;chlich ist dieses w&#246;chentliche Projekt auf Grundlage eines andere Projekts entstanden. Bei <a href=\"https:\/\/berlinmittemom.com\/5-bilder-fuer-5-tage-meine-5-freitagslieblinge\/\" target=\"_blank\" rel=\"noopener\">BerlinMitteMom<\/a> fanden &#252;ber eine ganze Weile hinweg die Freitags5 statt. Jeden Freitag postete man 5 Fotos aus der Woche zu 5 immer wiederkehrenden Themen. Lieblingsbuch, Lieblingsessen, Lieblingsmoment usw&#8230; Mit der Zeit tat ich mich aber schwer mich immer auf die gleichen f&#252;nf Themen festzulegen und gestaltete das Projekt f&#252;r mich etwas individueller und aus Freitags5 wurden Freitagslieblinge wurden Wochenlieblinge (ich glaube, weil ich es nicht immer Freitags schaffte). Auch wurden es immer wieder mal mehr als 5 Fotos und so ist es nun meine Wochenzusammenfassung, die ich jeden Freitag hier ver&#246;ffentliche. Inzwischen sind zwei weitere Blogparaden darin integriert, die ich euch gleich im Folgenden vorstelle.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61838 aligncenter\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/6a00d8341c709753ef011570569c3f970b.jpg\" alt=\"\" width=\"500\" height=\"109\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/6a00d8341c709753ef011570569c3f970b.jpg 500w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/6a00d8341c709753ef011570569c3f970b-300x65.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/6a00d8341c709753ef011570569c3f970b-275x60.jpg 275w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>03. Der Freitagsf&#252;ller<\/strong><br \/>\nDieses kleine Projekt habe ich &#252;ber Jahre hinweg auf anderen Seiten immer wieder gesehen und es weites gehend ignoriert. Bis ich irgendwann dachte &#8220;Ach, machste einfach mal mit&#8221;. Aber statt den kleinen Satzschnipseln gleich einen ganzen Beitrag zu widmen (weil sich das f&#252;r mich irgendwie nicht gelohnt hat), habe ich es einfach mit in die Wochenlieblinge aufgenommen. <a href=\"https:\/\/scrapimpulse.com\/2009\/02\/freitagsfueller-1\/\" target=\"_blank\" rel=\"noopener\">Beim Freitagsf&#252;ller<\/a> bekommen wir immer 7 L&#252;ckens&#228;tze jeden Freitag Morgen von Barbara geliefert und diese L&#252;cken gilt es dann mit eigenen Worten aufzuf&#252;llen. So f&#228;llt bei jedem der Freitagsf&#252;ller sicherlich vollkommen anders aus und das macht diese Idee so faszinierend, finde ich. Und in meinem Fall ist es eine sch&#246;ne Erg&#228;nzung zum Wochenr&#252;ckblick. (Es gibt im Kontrast dazu &#252;brigens auch den Montagsstarter, aber den mache ich bisher noch nicht mit).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-61841 aligncenter\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/highfive_mama.jpg\" alt=\"\" width=\"514\" height=\"363\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/highfive_mama.jpg 842w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/highfive_mama-300x212.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/highfive_mama-768x543.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/highfive_mama-85x60.jpg 85w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\" \/><\/p>\n<p><strong>04. Neu dabei: Die High-Five von Sabine<\/strong><br \/>\nErst seit kurzem Bestandteil der Wochenlieblinge ist die w&#246;chentliche Blogparade von Sabine aus dem Mauslauch. <a href=\"https:\/\/mausloch.blogspot.com\/p\/blogparade-high-five-am-sonntag.html\" target=\"_blank\" rel=\"noopener\">&#8220;Die High-Five am Sonntag&#8221;<\/a>, so hei&#223;t es eigentlich. Aber sie sagt selber, dass man das Projekt zu jedem Zeitpunkt in der Woche umsetzen kann und so habe ich es mit in die Wochenlieblinge aufgenommen. Im Grunde greift es etwas auf, das ich mit dem Sohn mal vor vielen Jahren durchgezogen habe, als wir Gl&#252;ckstagebuch f&#252;hrten. Damals suchten wir jeden Abend vor dem Schlafen gehen nach 5 Dingen, und seien sie noch so klein, die am Tag gut waren, damit das Letzte vor dem Schlafen gehen gute Gedanken waren. Das kann eine enorme Wirkung haben und einem zeigen, dass sich immer irgendwo auch etwas Gutes finden l&#228;sst. Man trainiert damit ein positiveres Bewusstsein und den Blick f&#252;r die kleinen Dinge. Wenn man n&#228;mlich ganz genau schaut, dann findet man immer eine Kleinigkeit. Und sei es das Schokobrot am Morgen. Sabine fordert nun auf f&#252;nf Highlights in der Woche zu finden, egal wie banal sie sind, und sie auszuformulieren. Das ganz sehr ausf&#252;hrlich sein oder in 5 kurzen Stichpunkten, so wie sie jetzt in meinen Wochenlieblingen zu finden sind.<\/p>\n<h2>Und dann gibt es noch monatliche oder selbst bestimmte Aktionen<\/h2>\n<p>Mit selbst bestimmt meine ich, dass es auch Projekte gibt, die an keinen bestimmten Zeitpunkt gebunden sind. Man kann selber bestimmen, ob man jeden Tag, monatlich, w&#246;chentlich oder einfach wenn einem danach ist daran arbeitet. So war es hier im Heldenhaushalt zum Beispiel mit den &#8220;1000 Fragen an mich selbst&#8221;. Ich habe immer dann einen weiteren Beitrag dazu einflie&#223;en lassen, wenn es passte. Im Folgenden stelle ich euch noch ein paar Blogparaden vor, die nicht unbedingt jede Woche stattfinden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61839 aligncenter\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bildschirmfoto-2012-07-13-um-18.43.40.png\" alt=\"\" width=\"320\" height=\"112\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bildschirmfoto-2012-07-13-um-18.43.40.png 320w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bildschirmfoto-2012-07-13-um-18.43.40-300x105.png 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bildschirmfoto-2012-07-13-um-18.43.40-171x60.png 171w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><strong>01. Die #12von12 von Drau&#223;en nur K&#228;nnchen<\/strong><br \/>\nDieses Projekt gibt es gef&#252;hlt irgendwie auch schon immer und auch schon sehr lange hier auf dem Blog. An jedem 12. eines Monats dokumentiert man in 12 Fotos seinen Tag. Daher auch die &#8220;12 von 12&#8221; oder auch 12 Fotos am 12., wenn man es so sehen m&#246;chte. Mir f&#228;llt es immer schwer an diesem Datum auch wirklich dran zu denken Fotos zu machen, aber eigentlich ist es eine sch&#246;ne Art jemanden mit durch den Alltag zu nehmen. Der Schwerpunkt liegt hierbei auf den Fotos und weniger auf den Worten. Man versucht wirklich, wenn &#252;berhaupt, die Fotos mit nur wenigen Worten kurz zu erl&#228;utern. Mehr dazu findet ihr <a href=\"https:\/\/draussennurkaennchen.blogspot.com\/p\/12-von-12.html\" target=\"_blank\" rel=\"noopener\">bei Drau&#223;en nur K&#228;nnchen<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-61840\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bloghexen-Bloggerschnack.png\" alt=\"\" width=\"2000\" height=\"1331\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bloghexen-Bloggerschnack.png 2000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bloghexen-Bloggerschnack-300x200.png 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bloghexen-Bloggerschnack-1024x681.png 1024w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bloghexen-Bloggerschnack-768x511.png 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bloghexen-Bloggerschnack-1536x1022.png 1536w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bloghexen-Bloggerschnack-450x300.png 450w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/Bloghexen-Bloggerschnack-90x60.png 90w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><strong>02. Bloggerschnack<\/strong><br \/>\nEine Blogparade, die noch in den Kinderschuhen steckt und <a href=\"https:\/\/forum.bloghexe.de\/forum\/index.php?thread\/138-bloggerschnack-themensammlung\/\" target=\"_blank\" rel=\"noopener\">Bestandteil des Bloggerforums &#8220;Bloghexen&#8221;<\/a> ist. Im Forum wird jeden Monatsanfang ein Thema bekannt gegeben, zu dem man dann innerhalb des Monats bloggen kann. Dabei dreht sich alles inhaltlich noch um das Thema Bloggen und soll gegenseitige Inspiration, Hilfe und auch Erfahrungswerte miteinander teilen.&nbsp;<\/p>\n<p><strong>03. Mein Lebens-ABC<\/strong><br \/>\nDiese Aktion soll nun die 1000 Fragen bei mir ersetzen. Den Ansto&#223; dazu habe ich <a href=\"https:\/\/aquarium.teufel100.de\/category\/dies-und-das\/mein-lebens-abc\/\" target=\"_blank\" rel=\"noopener\">von Sven<\/a> bekommen, der dieses schon seit 2019 auf seinem Blog bearbeitet. Es geht darum f&#252;r jeden Buchstaben im ABC ein Wort zu finden, das man mit seinem Leben in Verbindung bringt und dar&#252;ber zu schreiben. Die Idee finde ich wirklich sch&#246;n und das Projekt an sich ideal, um es immer mal wieder weiter zu bearbeiten. Ich m&#246;chte jetzt im September damit starten und bin gespannt, wie es l&#228;uft. Es soll dabei helfen das eigene Leben etwas mehr zu erfassen, zu verstehen und mehr &#252;ber sich selbst zu lernen.<\/p>\n<p><strong>04. Inktober<\/strong><br \/>\nJa, <a href=\"https:\/\/inktober.com\/rules\" target=\"_blank\" rel=\"noopener\">der Inktober<\/a> steht wieder in den Startl&#246;chern und ich freue mich schon darauf. Eine Blogparade, die j&#228;hrlich wiederkehrt und nur im Oktober stattfindet, wie der Name erahnen l&#228;sst. Der Schwerpunkt hier liegt im kreativen Bereich. Kurz vor Beginn bekommen wir vom Veranstalter eine Liste an Begriffen f&#252;r den ganzen Oktober und es gilt nun jeden Tag die Themen zu bearbeiten. Dabei beschr&#228;nkt man sich auf ein Material (den schwarzen Stift so gesehen). Letztes Jahr habe ich endlich das erste Mal geschafft teilzunehmen und im Laufe des Monats entstand <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2023\/11\/02\/inktober2023-ein-geist-auf-abwegen-29-10-31-10-2023-mit-fazit\/\">eine Geschichte<\/a> rund um einen Geist und einen K&#252;rbis.&nbsp;<\/p>\n<figure style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2023\/10\/frost.jpg\" alt=\"Frost\" width=\"1000\" height=\"760\"><figcaption class=\"wp-caption-text\">Inktober 2023<\/figcaption><\/figure>\n<p>Ich hoffe, ich habe nichts an Projekten &#252;bersehen. Es gibt nat&#252;rlich viel, viel mehr da drau&#223;en in der Blogsph&#228;re, aber das sind die, die ihr hier im Heldenhaushalt immer wieder findet. Schreibt mir doch gerne mal in die Kommentare, was f&#252;r Projekte und Blogparaden ihr noch so kennt und erw&#228;hnenswert findet. Wo seid ihr auch dabei und was w&#228;re etwas f&#252;r euch!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fragt mich nicht wieso, aber irgendwie kam ich auf die Idee, dass es doch mal ganz nett w&#228;re alle Projekte und Blogparaden hier zusammen zu fassen und vorzustellen, an denen ich so teilnehme. Nicht zuletzt, weil in den vergangenen Monate die Community hier wieder ein bisschen gewachsen ist und mehr Austausch und Leben in der Blogsph&#228;re scheinbar wieder herrscht. Und wisst ihr was? Ich liebe das! Diese Projekte oder auch Blogparaden sind ja neben einer netten Inspiration f&#252;r Blogbeitr&#228;ge und Inhalte auch ein sch&#246;ner Weg zum gegenseitigen Vernetzen. Besonders davon hat die Blogsph&#228;re damals ja auch sehr gelebt. Man hat sich gegenseitig empfohlen, besucht und kommentiert. Man hat in Gespr&#228;chen miteinander Anregungen f&#252;r neue Themen bekommen und teilweise auch Freunde gefunden. Bestes Beispiel hierf&#252;r sind zum Beispiel Maru oder auch Elisa, die ich durch das Internet und die Homepage damals kennengelernt und bis heute nicht aus den Augen verloren habe. Und wir sprechen hier von mittlerweile zwei Jahrezehnten. Nicht vergessen. Und speziell Maru und ihre Familie sehen wir jedes Jahr auch pers&#246;nlich. Unsere Kinder kennen sich, sind irgendwie gemeinsam aufgewachsen, wir tanzten auf unseren Hochzeiten und wir M&#228;dels quatschen fast t&#228;glich miteinander (oder machen via Meeting Yoga). Also ja, ich finde Vernetzen wichtig.&nbsp; Aber ich schweife schon wieder ab. Blogparaden und Projekte begleiten uns schon immer irgendwie Neben dem Projekt 52 und dem Going Out, die ich fr&#252;her selber &#252;ber mehrere Jahre leitete, gibt es viele andere sch&#246;ne Ideen, die schon lange Bestandteil dieser Seite sind und einige davon sind euch sicherlich schon aufgefallen. Sie sorgen f&#252;r eine gewisse Regelm&#228;&#223;igkeit hier im Heldenhaushalt und lassen einen Blick in unseren Alltag zu (was euch scheinbar ganz gut gef&#228;llt). Aber neben diesen Projekten gibt es auch welche, die uns zum Nachdenken anregen, uns Inspirationen liefern und einen Austausch f&#246;rdern. Nicht erst durch das Bloghexe Forum habe ich festgestellt, dass dieses Bed&#252;rfnis nach genau solchen Ideen, ziemlich gro&#223; ist. Es wird immer wieder danach Ausschau gehalten und deshalb dachte ich, gebe ich heute mal eine kleine Zusammenfassung der Blogparaden, die uns hier auf dem Heldenhaushalt begleiten. Auch um eventuelle Fragen zu diesen mal in einem Rutsch zu beantworten. Vielleicht ist ja auch die eine oder andere dazwischen, die etwas f&#252;r Euch w&#228;re. Eine kleine Zusammenfassung aller Projekte und Paraden auf Heldenhaushalt 01. WIB &#8211; Oder auch &#8220;Wochenende in Bildern&#8221; Urspr&#252;nglich war das &#8220;WIB&#8221; mal ein Projekt von Susanne Mierau von Geborgen Wachsen, wurde aber vor einigen Jahre von Alu und Konsti von Grossek&#246;pfe &#252;bernommen. Familien nehmen einen mit durch den Alltag und zeigen dabei, wie die Wochenenden bei anderen aussehen k&#246;nnen, wenn die Kinder nicht in Schule und Kita sind. Und dabei ist es egal, ob das Wochenende langweilig, aufregend, verr&#252;ckt oder banal ist. Es sollte eine Art Verbundenheit erzeugen und das tat es damals auch. So gab es auch viele sch&#246;ne Ideen und Inspirationen, aber auch die Erkenntnis, dass es bei anderen manchmal auch nicht viel aufregender aussieht, als bei einem selbst. Alltag halt. Mehr dazu k&#246;nnt ihr auch heute noch bei Susanne nachlesen. Mitmachen kann aber eigentlich jeder, der uns mit durch seinen Alltag nehmen m&#246;chte und gerade die Wochenenden bieten ja doch viel Potential etwas zu zeigen und manchmal eben auch nichts. So sieht man bei uns ja meistens vor allem den Alltag mit Fu&#223;ballkindern, aber das kann auch genauso spannend sein f&#252;r andere, die dar&#252;ber nachdenken ob das auch etwas f&#252;r sie w&#228;re. Oder man findet Leidensgenossen, die auch jedes Wochenende am Spielfeldrand stehen. Dieses Projekt begleitet uns nun schon seit 2016 und der erste Beitrag dazu ist hier. Oh weia, ist das auch schon wieder lange her. Dieses Projekt ist ein w&#246;chentliches Projekt. 02. Die Wochenlieblinge Inzwischen sind die Wochenlieblinge ein w&#246;chentliches Projekt, das ich in Eigeninitiative stattfinden lasse. Im Grunde fasse ich hier jeden Freitag meine Highlights der Woche zusammen. Dinge, an die ich mich gerne erinnern m&#246;chte. Nicht immer sind es Highlights, sondern einfach Sachen die ich gemacht oder erlebt habe, aber da sie mir beim Schreiben in den Kopf kommen, scheinen sie mir wichtig zu sein und so landen sie in diesem Beitrag. Tats&#228;chlich ist dieses w&#246;chentliche Projekt auf Grundlage eines andere Projekts entstanden. Bei BerlinMitteMom fanden &#252;ber eine ganze Weile hinweg die Freitags5 statt. Jeden Freitag postete man 5 Fotos aus der Woche zu 5 immer wiederkehrenden Themen. Lieblingsbuch, Lieblingsessen, Lieblingsmoment usw&#8230; Mit der Zeit tat ich mich aber schwer mich immer auf die gleichen f&#252;nf Themen festzulegen und gestaltete das Projekt f&#252;r mich etwas individueller und aus Freitags5 wurden Freitagslieblinge wurden Wochenlieblinge (ich glaube, weil ich es nicht immer Freitags schaffte). Auch wurden es immer wieder mal mehr als 5 Fotos und so ist es nun meine Wochenzusammenfassung, die ich jeden Freitag hier ver&#246;ffentliche. Inzwischen sind zwei weitere Blogparaden darin integriert, die ich euch gleich im Folgenden vorstelle. 03. Der Freitagsf&#252;ller Dieses kleine Projekt habe ich &#252;ber Jahre hinweg auf anderen Seiten immer wieder gesehen und es weites gehend ignoriert. Bis ich irgendwann dachte &#8220;Ach, machste einfach mal mit&#8221;. Aber statt den kleinen Satzschnipseln gleich einen ganzen Beitrag zu widmen (weil sich das f&#252;r mich irgendwie nicht gelohnt hat), habe ich es einfach mit in die Wochenlieblinge aufgenommen. Beim Freitagsf&#252;ller bekommen wir immer 7 L&#252;ckens&#228;tze jeden Freitag Morgen von Barbara geliefert und diese L&#252;cken gilt es dann mit eigenen Worten aufzuf&#252;llen. So f&#228;llt bei jedem der Freitagsf&#252;ller sicherlich vollkommen anders aus und das macht diese Idee so faszinierend, finde ich. Und in meinem Fall ist es eine sch&#246;ne Erg&#228;nzung zum Wochenr&#252;ckblick. (Es gibt im Kontrast dazu &#252;brigens auch den Montagsstarter, aber den mache ich bisher noch nicht mit). 04. Neu dabei: Die High-Five von Sabine Erst seit kurzem Bestandteil der Wochenlieblinge ist die w&#246;chentliche Blogparade von Sabine aus dem Mauslauch. &#8220;Die High-Five am Sonntag&#8221;, so hei&#223;t es eigentlich. Aber sie sagt selber, dass man das Projekt zu jedem Zeitpunkt in der Woche umsetzen kann und so habe ich es mit in die Wochenlieblinge aufgenommen. Im Grunde greift es etwas auf, das ich mit dem Sohn mal vor vielen Jahren durchgezogen habe, als wir Gl&#252;ckstagebuch f&#252;hrten. Damals suchten wir jeden Abend vor dem Schlafen gehen nach 5 Dingen, und seien sie noch so klein, die am Tag gut waren, damit das Letzte vor dem Schlafen gehen gute Gedanken waren. Das kann eine enorme Wirkung haben und einem zeigen, dass sich immer irgendwo auch etwas Gutes finden l&#228;sst. Man trainiert damit ein positiveres Bewusstsein und den Blick f&#252;r die kleinen Dinge. Wenn man n&#228;mlich ganz genau schaut, dann findet man immer eine Kleinigkeit. Und sei es das Schokobrot am Morgen. Sabine fordert nun auf f&#252;nf Highlights in der Woche zu finden, egal wie banal sie sind, und sie auszuformulieren. Das ganz sehr ausf&#252;hrlich sein oder in 5 kurzen Stichpunkten, so wie sie jetzt in meinen Wochenlieblingen zu finden sind. Und dann gibt es noch monatliche oder selbst bestimmte Aktionen Mit selbst bestimmt meine ich, dass es auch Projekte gibt, die an keinen bestimmten Zeitpunkt gebunden sind. Man kann selber bestimmen, ob man jeden Tag, monatlich, w&#246;chentlich oder einfach wenn einem danach ist daran arbeitet. So war es hier im Heldenhaushalt zum Beispiel mit den &#8220;1000 Fragen an mich selbst&#8221;. Ich habe immer dann einen weiteren Beitrag dazu einflie&#223;en lassen, wenn es passte. Im Folgenden stelle ich euch noch ein paar Blogparaden vor, die nicht unbedingt jede Woche stattfinden. 01. Die #12von12 von Drau&#223;en nur K&#228;nnchen Dieses Projekt gibt es gef&#252;hlt irgendwie auch schon immer und auch schon sehr lange hier auf dem Blog. An jedem 12. eines Monats dokumentiert man in 12 Fotos seinen Tag. Daher auch die &#8220;12 von 12&#8221; oder auch 12 Fotos am 12., wenn man es so sehen m&#246;chte. Mir f&#228;llt es immer schwer an diesem Datum auch wirklich dran zu denken Fotos zu machen, aber eigentlich ist es eine sch&#246;ne Art jemanden mit durch den Alltag zu nehmen. Der Schwerpunkt liegt hierbei auf den Fotos und weniger auf den Worten. Man versucht wirklich, wenn &#252;berhaupt, die Fotos mit nur wenigen Worten kurz zu erl&#228;utern. Mehr dazu findet ihr bei Drau&#223;en nur K&#228;nnchen. 02. Bloggerschnack Eine Blogparade, die noch in den Kinderschuhen steckt und Bestandteil des Bloggerforums &#8220;Bloghexen&#8221; ist. Im Forum wird jeden Monatsanfang ein Thema bekannt gegeben, zu dem man dann innerhalb des Monats bloggen kann. Dabei dreht sich alles inhaltlich noch um das Thema Bloggen und soll gegenseitige Inspiration, Hilfe und auch Erfahrungswerte miteinander teilen.&nbsp; 03. Mein Lebens-ABC Diese Aktion soll nun die 1000 Fragen bei mir ersetzen. Den Ansto&#223; dazu habe ich von Sven bekommen, der dieses schon seit 2019 auf seinem Blog bearbeitet. Es geht darum f&#252;r jeden Buchstaben im ABC ein Wort zu finden, das man mit seinem Leben in Verbindung bringt und dar&#252;ber zu schreiben. Die Idee finde ich wirklich sch&#246;n und das Projekt an sich ideal, um es immer mal wieder weiter zu bearbeiten. Ich m&#246;chte jetzt im September damit starten und bin gespannt, wie es l&#228;uft. Es soll dabei helfen das eigene Leben etwas mehr zu erfassen, zu verstehen und mehr &#252;ber sich selbst zu lernen. 04. Inktober Ja, der Inktober steht wieder in den Startl&#246;chern und ich freue mich schon darauf. Eine Blogparade, die j&#228;hrlich wiederkehrt und nur im Oktober stattfindet, wie der Name erahnen l&#228;sst. Der Schwerpunkt hier liegt im kreativen Bereich. Kurz vor Beginn bekommen wir vom Veranstalter eine Liste an Begriffen f&#252;r den ganzen Oktober und es gilt nun jeden Tag die Themen zu bearbeiten. Dabei beschr&#228;nkt man sich auf ein Material (den schwarzen Stift so gesehen). Letztes Jahr habe ich endlich das erste Mal geschafft teilzunehmen und im Laufe des Monats entstand eine Geschichte rund um einen Geist und einen K&#252;rbis.&nbsp; Ich hoffe, ich habe nichts an Projekten &#252;bersehen. Es gibt nat&#252;rlich viel, viel mehr da drau&#223;en in der Blogsph&#228;re, aber das sind die, die ihr hier im Heldenhaushalt immer wieder findet. Schreibt mir doch gerne mal in die Kommentare, was f&#252;r Projekte und Blogparaden ihr noch so kennt und erw&#228;hnenswert findet. Wo seid ihr auch dabei und was w&#228;re etwas f&#252;r euch! &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":59285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[49],"tags":[249,3625,3626,181,3627,2463,1524],"class_list":["post-61725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogspaehre","tag-blogparade","tag-blogparaden","tag-blogprojekte","tag-blogsphaere","tag-content","tag-projekte","tag-vernetzen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blogparaden &amp; Projekte, an denen ich teilnehme - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Diese Projekte oder auch Blogparaden sind ja neben einer netten Inspiration f\u00fcr Blogbeitr\u00e4ge und Inhalte auch ein sch\u00f6ner Weg zum...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blogparaden &amp; Projekte, an denen ich teilnehme - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Diese Projekte oder auch Blogparaden sind ja neben einer netten Inspiration f\u00fcr Blogbeitr\u00e4ge und Inhalte auch ein sch\u00f6ner Weg zum...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-03T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-03T08:12:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2023\/10\/01-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"Blogparaden &#038; Projekte, an denen ich teilnehme\",\"datePublished\":\"2024-09-03T08:00:00+00:00\",\"dateModified\":\"2024-09-03T08:12:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/\"},\"wordCount\":1739,\"commentCount\":16,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/01-02.jpg\",\"keywords\":[\"Blogparade\",\"Blogparaden\",\"Blogprojekte\",\"Blogsph\u00e4re\",\"Content\",\"Projekte\",\"Vernetzen\"],\"articleSection\":[\"Blogsph\u00e4re\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/\",\"name\":\"Blogparaden & Projekte, an denen ich teilnehme - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/01-02.jpg\",\"datePublished\":\"2024-09-03T08:00:00+00:00\",\"dateModified\":\"2024-09-03T08:12:41+00:00\",\"description\":\"Diese Projekte oder auch Blogparaden sind ja neben einer netten Inspiration f\u00fcr Blogbeitr\u00e4ge und Inhalte auch ein sch\u00f6ner Weg zum...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/01-02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/01-02.jpg\",\"width\":1000,\"height\":709,\"caption\":\"Blogparaden\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/03\\\/blogparaden-projekte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogparaden &#038; Projekte, an denen ich teilnehme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blogparaden & Projekte, an denen ich teilnehme - Heldenhaushalt","description":"Diese Projekte oder auch Blogparaden sind ja neben einer netten Inspiration f\u00fcr Blogbeitr\u00e4ge und Inhalte auch ein sch\u00f6ner Weg zum...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/","og_locale":"de_DE","og_type":"article","og_title":"Blogparaden & Projekte, an denen ich teilnehme - Heldenhaushalt","og_description":"Diese Projekte oder auch Blogparaden sind ja neben einer netten Inspiration f\u00fcr Blogbeitr\u00e4ge und Inhalte auch ein sch\u00f6ner Weg zum...","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/","og_site_name":"Heldenhaushalt","article_published_time":"2024-09-03T08:00:00+00:00","article_modified_time":"2024-09-03T08:12:41+00:00","og_image":[{"width":1000,"height":709,"url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2023\/10\/01-02.jpg","type":"image\/jpeg"}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"Blogparaden &#038; Projekte, an denen ich teilnehme","datePublished":"2024-09-03T08:00:00+00:00","dateModified":"2024-09-03T08:12:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/"},"wordCount":1739,"commentCount":16,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2023\/10\/01-02.jpg","keywords":["Blogparade","Blogparaden","Blogprojekte","Blogsph\u00e4re","Content","Projekte","Vernetzen"],"articleSection":["Blogsph\u00e4re"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/","name":"Blogparaden & Projekte, an denen ich teilnehme - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2023\/10\/01-02.jpg","datePublished":"2024-09-03T08:00:00+00:00","dateModified":"2024-09-03T08:12:41+00:00","description":"Diese Projekte oder auch Blogparaden sind ja neben einer netten Inspiration f\u00fcr Blogbeitr\u00e4ge und Inhalte auch ein sch\u00f6ner Weg zum...","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2023\/10\/01-02.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2023\/10\/01-02.jpg","width":1000,"height":709,"caption":"Blogparaden"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/03\/blogparaden-projekte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"Blogparaden &#038; Projekte, an denen ich teilnehme"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":1237,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/61725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=61725"}],"version-history":[{"count":4,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/61725\/revisions"}],"predecessor-version":[{"id":61842,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/61725\/revisions\/61842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media\/59285"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=61725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=61725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=61725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}