{"id":61914,"date":"2024-09-13T10:02:32","date_gmt":"2024-09-13T08:02:32","guid":{"rendered":"https:\/\/www.heldenhaushalt.de\/sari02\/?p=61914"},"modified":"2024-09-13T10:02:32","modified_gmt":"2024-09-13T08:02:32","slug":"unsere-wochenlieblinge-362024","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/","title":{"rendered":"Unsere Wochenlieblinge 36\/2024 &#8211; Eine richtige Herbstwoche!"},"content":{"rendered":"<p style=\"text-align: right;\"><small>Enth&#228;lt (unbezahlte) Werbung*<\/small><\/p>\n<p>Heute ist Freitag, der 13.! Na, wie vielen von euch f&#228;llt das auch jetzt erst auf? Gestern kam mir kurz die Erkenntnis und dann verflog sie direkt wieder. Viel Bedeutung habe ich diesem Datum eh nie gegeben, aber irgendwie ist es dennoch immer witzig es zu erw&#228;hnen, oder? Seid Ihr in dieser Hinsicht abergl&#228;ubisch? Unsere Wochenlieblinge diese Woche werden herbstlich und gem&#252;tlich zu gleich. Als ich eben die Fotos sichtete, musste ich feststellen, dass ich glatt eine ganze Tassenparade h&#228;tte pr&#228;sentieren k&#246;nnen und musste dann doch nochmal aussortieren. Sonst w&#228;re dieser Wochenr&#252;ckblick wohl etwas einseitig geworden&#8230;<\/p>\n\n<h2><span id=\"Unsere_Wochenlieblinge_in_dieser_Woche\">Unsere Wochenlieblinge in dieser Woche\u2026<\/span><\/h2>\n<p>Die Woche startet noch recht mild. Es ist ein krasser Temperatursturz angesagt und ja, es sind mehr als 10 Grad weniger, als am vergangenen Wochenende, aber die Luft ist noch recht dr&#252;ckend, die Luftfeuchtigkeit hoch und man schwitzt dennoch recht schnell.<\/p>\n<figure id=\"attachment_61917\" aria-describedby=\"caption-attachment-61917\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61917\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-01.jpg\" alt=\"Herbst\" width=\"1000\" height=\"732\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-01.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-01-300x220.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-01-768x562.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-01-82x60.jpg 82w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-61917\" class=\"wp-caption-text\">Herbstl&#228;cheln<\/figcaption><\/figure>\n<p>Aber man sieht es mir an, oder? Ich freue mich &#252;ber die Abk&#252;hlung. Ich f&#252;hle mich gleich deutlich wohler in meiner Haut und in meinen Kuschelpullovern.&nbsp;<\/p>\n<figure id=\"attachment_61918\" aria-describedby=\"caption-attachment-61918\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61918\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-02.jpg\" alt=\"Weihnachten\" width=\"1000\" height=\"714\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-02.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-02-300x214.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-02-768x548.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-02-84x60.jpg 84w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-61918\" class=\"wp-caption-text\">Huch, ist schon Weihnachten?<\/figcaption><\/figure>\n<p>Von Dienstag auf Mittwoch bin ich Strohwitwe. Der Mann ist mal wieder auf Dienstreise. <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/09\/unser-wib-am-07-08-2024\/\">Vergangenes Wochenende<\/a> waren wir ja spontan beim Action, weil ich online gesehen hatte, dass sie Disney Weihnachtskugeln haben und bei sowas muss man schnell sein. Am Wochenende ergatterte ich die letzten beiden Pakete und es hie&#223;, es w&#252;rde nachbestellt werden. Leider kam die Woche noch nichts an, als ich alleine im Regen mit dem Rad hinfuhr. Aber auf Wunsch von <a href=\"https:\/\/irgendwas-buntes.de\/\" target=\"_blank\" rel=\"noopener\">Christine<\/a> zeige ich euch dennoch mal die, die ich bisher holen konnte. Ich h&#228;tte noch&nbsp; gerne die mit den typischen Mickey Knopfhosen. Vielleicht habe ich ja noch Gl&#252;ck.<\/p>\n<figure id=\"attachment_61919\" aria-describedby=\"caption-attachment-61919\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61919\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-03.jpg\" alt=\"Wochenlieblinge\" width=\"1000\" height=\"713\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-03.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-03-300x214.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-03-768x548.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-03-84x60.jpg 84w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-61919\" class=\"wp-caption-text\">Kekse backen geht immer<\/figcaption><\/figure>\n<p>Der Tag, an dem der Papa nicht in der Stadt war, war auch kein Training oder anderes Wichtiges, so dass ich spontan mit den Kindern beschloss den freien Nachmittag zu nutzen und Kekse zu backen. Dar&#252;ber w&#252;rde sich auch der Papa sehr freuen, wenn er am n&#228;chsten Tag wieder da ist. Ich hatte in der Woche zuvor wirklich s&#252;&#223;e Keksausstecher entdeckt, die wir nun testen wollten. Mit tollen Herbstmotto nat&#252;rlich.&nbsp;<\/p>\n<figure id=\"attachment_61920\" aria-describedby=\"caption-attachment-61920\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61920\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-04.jpg\" alt=\"Backen\" width=\"1000\" height=\"713\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-04.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-04-300x214.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-04-768x548.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-04-84x60.jpg 84w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-61920\" class=\"wp-caption-text\">Tatkr&#228;ftige Hilfe<\/figcaption><\/figure>\n<p>Eigentlich habe ich eher weniger gute Erfahrungen mit Ausstechern gemacht, bei denen man dann ein Motiv reindr&#252;ckt, aber die hier funktionieren wirklich gut und die Ergebnisse schmecken nicht nur, sondern sehen auch toll aus. So kann man einen gem&#252;tlichen Herbstnachmittag in der warmen K&#252;che verbringen und kleine Wochenlieblinge produzieren.<\/p>\n<figure id=\"attachment_61921\" aria-describedby=\"caption-attachment-61921\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61921\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-05-scaled.jpg\" alt=\"Wochenlieblinge\" width=\"2560\" height=\"1837\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-05-scaled.jpg 2560w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-05-300x215.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-05-1024x735.jpg 1024w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-05-768x551.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-05-1536x1102.jpg 1536w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-05-2048x1469.jpg 2048w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-05-84x60.jpg 84w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-61921\" class=\"wp-caption-text\">Noch mehr Herbstliebe<\/figcaption><\/figure>\n<p>Sieht man es? Der Herbst hat einfach meine Farben. Braun- und Gelbt&#246;ne, dazu diese erdigen Farben und das Licht. Ich wei&#223;, ich wiederhole mich, aber auch wenn es kalt und vielleicht auch nass ist. Ich bin hier einfach so viel mehr ich selbst. Am Mittwoch war dann auch noch Elternabend in der Schule des kleinen Sohnes. Nach einer Info-Veranstaltung sollten wir Eltern abstimmen, ob die Kinder in der 3. Klasse Noten bekommen sollen oder verbale Beurteilungen. Meine Kinder waren schon immer f&#252;r Noten. Auch der gro&#223;e Sohn damals. Sie sind f&#252;r sie greifbarer. Aber das sieht nicht jeder so und das ist ok. Einseitig und manipulativ war die Schulveranstaltung dennoch. Sie zielte alleine darauf ab verbale Zeugnisse als ultimativ und Noten als b&#246;se darzustellen und Eltern zu &#252;berreden Ersteres zu w&#228;hlen. Selten war ich auf einem Elternabend, der so lange gedauert hat. Kurz vor 21 Uhr waren wir erst zu Hause. Und das Ergebnis war unbefriedigend und der Sohn ist nun sehr traurig. Zumal diese Abstimmung und Diskussion gleich zu Beginn des Schuljahres einen Keil in die Elternschaft treibt, anstatt dass die Schule einfach das macht, was sie f&#252;r richtig h&#228;lt. Aber das l&#228;sst der Staat mal wieder nicht zu. In Hamburg ist das Modell fortschrittlicher. Es gibt f&#252;r alle eine verbale Beurteilung und wer gerne eine Note will, der bekommt sie zus&#228;tzlich dazu geschrieben&#8230; aber gut&#8230;Nun l&#228;sst es sich f&#252;r min. ein Schuljahr wohl eh nicht mehr &#228;ndern.<\/p>\n<figure id=\"attachment_61922\" aria-describedby=\"caption-attachment-61922\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61922\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-06.jpg\" alt=\"Wochenlieblinge\" width=\"1000\" height=\"766\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-06.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-06-300x230.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-06-768x588.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-06-78x60.jpg 78w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-61922\" class=\"wp-caption-text\">Dekozeit<\/figcaption><\/figure>\n<p>Diese Woche habe ich dann auch all das, was ich im letzten Jahr und&nbsp; in den letzten Wochen angesammelt habe, nach und nach im Wohnzimmer aufgestellt. Bl&#228;ttergirlanden h&#228;ngen in T&#252;rrahmen und die Tische und Sideboards sehen mehr und mehr nach Herbst aus. K&#252;rbisse und Geister d&#252;rfen nun stehen und Tee und Kakao aus passenden Tassen getrunken werden.<\/p>\n<figure id=\"attachment_61923\" aria-describedby=\"caption-attachment-61923\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61923\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-07.jpg\" alt=\"Deko\" width=\"1000\" height=\"726\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-07.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-07-300x218.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-07-768x558.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-07-83x60.jpg 83w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-61923\" class=\"wp-caption-text\">Noch mehr Deko<\/figcaption><\/figure>\n<p>Nur mit dem Gruseligen Zeug warte ich im Garten noch bis Oktober. Dann d&#252;rfen auch die kleinen Monster und Skelette in den Garten ziehen und f&#252;r ein bisschen gruseligere Stimmung sorgen. Den Garten haben wir daf&#252;r diese Woche vorne schon f&#252;r den Herbst fit gemacht, aber davon erz&#228;hle ich euch dann morgen im Rahmen der #12von12 ein wenig mehr. Aber ich liebe die kuschelige Atmosph&#228;re, die nun nach und nach in unseren vier W&#228;nden einzieht.&nbsp;<\/p>\n<h2><span id=\"Unsere_High_Five_der_Woche\"><span id=\"Zeit_fur_die_Freitagsfragen\">Unsere&nbsp;<\/span><span id=\"Zeit_fur_die_Freitagsfragen\">\u201cHigh Five\u201d der Woche<\/span><\/span><\/h2>\n<p><strong>Bei den \u201cHigh Five\u201d von Sabine geht es darum f&#252;nf Dinge zu finden, die in der Woche gut waren.&nbsp;<a href=\"https:\/\/mausloch.blogspot.com\/p\/blogparade-high-five-am-sonntag.html\" target=\"_blank\" rel=\"noopener\">Erfahrt hier mehr dazu<\/a>.<\/strong><\/p>\n<ol>\n<li>16. Hochzeitstag<\/li>\n<li>Leckere Herbstkekse gebacken<\/li>\n<li>Kuschelpullover-Zeit beginnt endlich<\/li>\n<li>Eine neue Folge &#8220;Only murders in the building&#8221;<\/li>\n<li>Erste K&#252;rbissuppe der Saison gekocht und genossen<\/li>\n<\/ol>\n<h2><span id=\"Zeit_fur_die_Freitagsfragen\">Zeit f&#252;r die Freitagsfragen&nbsp;&nbsp;<\/span><\/h2>\n<figure id=\"attachment_61924\" aria-describedby=\"caption-attachment-61924\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61924\" src=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-08.jpg\" alt=\"Wochenlieblinge\" width=\"1000\" height=\"706\" srcset=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-08.jpg 1000w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-08-300x212.jpg 300w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-08-768x542.jpg 768w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-08-85x60.jpg 85w, https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-08-920x650.jpg 920w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-61924\" class=\"wp-caption-text\">Kekse f&#252;r den Papa<\/figcaption><\/figure>\n<p><strong>Und zum Abschluss auch dieses Mal wieder Wochenlieblinge mit dem&nbsp;<a href=\"https:\/\/scrapimpulse.com\/2024\/09\/meine-woche-freitagstipps-freitagsfueller-798\/\" target=\"_blank\" rel=\"noopener\">Freitagsf&#252;ller von Babara<\/a>.<\/strong><\/p>\n<p><strong>1.<\/strong> Wir m&#252;ssen versuchen <span style=\"color: #ff9900;\">immer das Beste aus den Situationen zu machen, die uns manchmal arg besch&#228;ftigen<\/span>.<br \/>\n<strong>2<\/strong>. <span style=\"color: #ff9900;\">In manchen R&#228;umen (und in meinem Kopf) herrscht manchmal ein schreckliches<\/span> durcheinander.<br \/>\n<strong>3.<\/strong> Kurz mal <span style=\"color: #ff9900;\">inne halten und den Moment genie&#223;en &#8211; so wichtig<\/span>.<br \/>\n<strong>4.<\/strong> <span style=\"color: #ff9900;\">In dieser Jahreszeit wird es jetzt<\/span> so richtig gem&#252;tlich.<br \/>\n<strong>5.<\/strong> Obwohl ich jetzt schon wei&#223;, <span style=\"color: #ff9900;\">dass die lange Dunkelheit mir irgendwann wieder ordentlich auf die Psyche gehen wird, freue ich mich dennoch auf die kommende Zeit<\/span>.<br \/>\n<strong>6.<\/strong> <span style=\"color: #ff9900;\">Manchmal muss man erst lernen gewisse Dinge so richtig<\/span> zu genie&#223;en.<br \/>\n<strong>7.<\/strong> Was das Wochenende angeht, heute Abend freue ich mich auf <span style=\"color: #ff9900;\">ein paar Folgen &#8220;Modern Family&#8221;<\/span>, morgen habe ich geplant, <span style=\"color: #ff9900;\">die Kids bei ihren ersten Staffelspielen anzufeuern<\/span> und Sonntag m&#246;chte ich <span style=\"color: #ff9900;\">auch in diesem Jahr wieder mit dem kleinen Sohn zur <a href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2023\/10\/09\/unser-wib-am-07-08-10-2023\/\">&#8220;Steinewahn&#8221; Ausstellung<\/a> gehen<\/span>!<\/p>\n<p><small>*<strong>Anmerkung:<\/strong>&nbsp;Der Artikel &#252;ber unsere Wochenlieblinge enth&#228;lt evtl. Bilder mit Produkten, die wir in unserem Alltag nutzen oder Linkempfehlungen. Wir haben keine Bezahlung f&#252;r das Zeigen oder Nutzen derselbigen erhalten. Affiliate Links sind als solche markiert.<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enth&#228;lt (unbezahlte) Werbung* Heute ist Freitag, der 13.! Na, wie vielen von euch f&#228;llt das auch jetzt erst auf? Gestern kam mir kurz die Erkenntnis und dann verflog sie direkt wieder. Viel Bedeutung habe ich diesem Datum eh nie gegeben, aber irgendwie ist es dennoch immer witzig es zu erw&#228;hnen, oder? Seid Ihr in dieser Hinsicht abergl&#228;ubisch? Unsere Wochenlieblinge diese Woche werden herbstlich und gem&#252;tlich zu gleich. Als ich eben die Fotos sichtete, musste ich feststellen, dass ich glatt eine ganze Tassenparade h&#228;tte pr&#228;sentieren k&#246;nnen und musste dann doch nochmal aussortieren. Sonst w&#228;re dieser Wochenr&#252;ckblick wohl etwas einseitig geworden&#8230; Unsere Wochenlieblinge in dieser Woche\u2026 Die Woche startet noch recht mild. Es ist ein krasser Temperatursturz angesagt und ja, es sind mehr als 10 Grad weniger, als am vergangenen Wochenende, aber die Luft ist noch recht dr&#252;ckend, die Luftfeuchtigkeit hoch und man schwitzt dennoch recht schnell. Aber man sieht es mir an, oder? Ich freue mich &#252;ber die Abk&#252;hlung. Ich f&#252;hle mich gleich deutlich wohler in meiner Haut und in meinen Kuschelpullovern.&nbsp; Von Dienstag auf Mittwoch bin ich Strohwitwe. Der Mann ist mal wieder auf Dienstreise. Vergangenes Wochenende waren wir ja spontan beim Action, weil ich online gesehen hatte, dass sie Disney Weihnachtskugeln haben und bei sowas muss man schnell sein. Am Wochenende ergatterte ich die letzten beiden Pakete und es hie&#223;, es w&#252;rde nachbestellt werden. Leider kam die Woche noch nichts an, als ich alleine im Regen mit dem Rad hinfuhr. Aber auf Wunsch von Christine zeige ich euch dennoch mal die, die ich bisher holen konnte. Ich h&#228;tte noch&nbsp; gerne die mit den typischen Mickey Knopfhosen. Vielleicht habe ich ja noch Gl&#252;ck. Der Tag, an dem der Papa nicht in der Stadt war, war auch kein Training oder anderes Wichtiges, so dass ich spontan mit den Kindern beschloss den freien Nachmittag zu nutzen und Kekse zu backen. Dar&#252;ber w&#252;rde sich auch der Papa sehr freuen, wenn er am n&#228;chsten Tag wieder da ist. Ich hatte in der Woche zuvor wirklich s&#252;&#223;e Keksausstecher entdeckt, die wir nun testen wollten. Mit tollen Herbstmotto nat&#252;rlich.&nbsp; Eigentlich habe ich eher weniger gute Erfahrungen mit Ausstechern gemacht, bei denen man dann ein Motiv reindr&#252;ckt, aber die hier funktionieren wirklich gut und die Ergebnisse schmecken nicht nur, sondern sehen auch toll aus. So kann man einen gem&#252;tlichen Herbstnachmittag in der warmen K&#252;che verbringen und kleine Wochenlieblinge produzieren. Sieht man es? Der Herbst hat einfach meine Farben. Braun- und Gelbt&#246;ne, dazu diese erdigen Farben und das Licht. Ich wei&#223;, ich wiederhole mich, aber auch wenn es kalt und vielleicht auch nass ist. Ich bin hier einfach so viel mehr ich selbst. Am Mittwoch war dann auch noch Elternabend in der Schule des kleinen Sohnes. Nach einer Info-Veranstaltung sollten wir Eltern abstimmen, ob die Kinder in der 3. Klasse Noten bekommen sollen oder verbale Beurteilungen. Meine Kinder waren schon immer f&#252;r Noten. Auch der gro&#223;e Sohn damals. Sie sind f&#252;r sie greifbarer. Aber das sieht nicht jeder so und das ist ok. Einseitig und manipulativ war die Schulveranstaltung dennoch. Sie zielte alleine darauf ab verbale Zeugnisse als ultimativ und Noten als b&#246;se darzustellen und Eltern zu &#252;berreden Ersteres zu w&#228;hlen. Selten war ich auf einem Elternabend, der so lange gedauert hat. Kurz vor 21 Uhr waren wir erst zu Hause. Und das Ergebnis war unbefriedigend und der Sohn ist nun sehr traurig. Zumal diese Abstimmung und Diskussion gleich zu Beginn des Schuljahres einen Keil in die Elternschaft treibt, anstatt dass die Schule einfach das macht, was sie f&#252;r richtig h&#228;lt. Aber das l&#228;sst der Staat mal wieder nicht zu. In Hamburg ist das Modell fortschrittlicher. Es gibt f&#252;r alle eine verbale Beurteilung und wer gerne eine Note will, der bekommt sie zus&#228;tzlich dazu geschrieben&#8230; aber gut&#8230;Nun l&#228;sst es sich f&#252;r min. ein Schuljahr wohl eh nicht mehr &#228;ndern. Diese Woche habe ich dann auch all das, was ich im letzten Jahr und&nbsp; in den letzten Wochen angesammelt habe, nach und nach im Wohnzimmer aufgestellt. Bl&#228;ttergirlanden h&#228;ngen in T&#252;rrahmen und die Tische und Sideboards sehen mehr und mehr nach Herbst aus. K&#252;rbisse und Geister d&#252;rfen nun stehen und Tee und Kakao aus passenden Tassen getrunken werden. Nur mit dem Gruseligen Zeug warte ich im Garten noch bis Oktober. Dann d&#252;rfen auch die kleinen Monster und Skelette in den Garten ziehen und f&#252;r ein bisschen gruseligere Stimmung sorgen. Den Garten haben wir daf&#252;r diese Woche vorne schon f&#252;r den Herbst fit gemacht, aber davon erz&#228;hle ich euch dann morgen im Rahmen der #12von12 ein wenig mehr. Aber ich liebe die kuschelige Atmosph&#228;re, die nun nach und nach in unseren vier W&#228;nden einzieht.&nbsp; Unsere&nbsp;\u201cHigh Five\u201d der Woche Bei den \u201cHigh Five\u201d von Sabine geht es darum f&#252;nf Dinge zu finden, die in der Woche gut waren.&nbsp;Erfahrt hier mehr dazu. 16. Hochzeitstag Leckere Herbstkekse gebacken Kuschelpullover-Zeit beginnt endlich Eine neue Folge &#8220;Only murders in the building&#8221; Erste K&#252;rbissuppe der Saison gekocht und genossen Zeit f&#252;r die Freitagsfragen&nbsp;&nbsp; Und zum Abschluss auch dieses Mal wieder Wochenlieblinge mit dem&nbsp;Freitagsf&#252;ller von Babara. 1. Wir m&#252;ssen versuchen immer das Beste aus den Situationen zu machen, die uns manchmal arg besch&#228;ftigen. 2. In manchen R&#228;umen (und in meinem Kopf) herrscht manchmal ein schreckliches durcheinander. 3. Kurz mal inne halten und den Moment genie&#223;en &#8211; so wichtig. 4. In dieser Jahreszeit wird es jetzt so richtig gem&#252;tlich. 5. Obwohl ich jetzt schon wei&#223;, dass die lange Dunkelheit mir irgendwann wieder ordentlich auf die Psyche gehen wird, freue ich mich dennoch auf die kommende Zeit. 6. Manchmal muss man erst lernen gewisse Dinge so richtig zu genie&#223;en. 7. Was das Wochenende angeht, heute Abend freue ich mich auf ein paar Folgen &#8220;Modern Family&#8221;, morgen habe ich geplant, die Kids bei ihren ersten Staffelspielen anzufeuern und Sonntag m&#246;chte ich auch in diesem Jahr wieder mit dem kleinen Sohn zur &#8220;Steinewahn&#8221; Ausstellung gehen! *Anmerkung:&nbsp;Der Artikel &#252;ber unsere Wochenlieblinge enth&#228;lt evtl. Bilder mit Produkten, die wir in unserem Alltag nutzen oder Linkempfehlungen. Wir haben keine Bezahlung f&#252;r das Zeigen oder Nutzen derselbigen erhalten. Affiliate Links sind als solche markiert.<\/p>\n","protected":false},"author":1,"featured_media":61916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[49,3494],"tags":[45,69,3125,418,3617,81,199,872,2161],"class_list":["post-61914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogspaehre","category-rueckblick","tag-alltag","tag-familie","tag-freitagsfueller","tag-herbst","tag-high-five","tag-kinder","tag-rueckblick","tag-woche","tag-wochenlieblinge"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Wochenlieblinge 36\/2024 - Eine richtige Herbstwoche! - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Unsere Wochenlieblinge diese Woche werden herbstlich und gem\u00fctlich zu gleich. Als ich eben die Fotos sichtete, musste ich feststellen,...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Wochenlieblinge 36\/2024 - Eine richtige Herbstwoche! - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Unsere Wochenlieblinge diese Woche werden herbstlich und gem\u00fctlich zu gleich. Als ich eben die Fotos sichtete, musste ich feststellen,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-13T08:02:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"Unsere Wochenlieblinge 36\\\/2024 &#8211; Eine richtige Herbstwoche!\",\"datePublished\":\"2024-09-13T08:02:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/\"},\"wordCount\":1152,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/36-00.jpg\",\"keywords\":[\"Allt\u00e4glich\",\"Familie\",\"Freitagsf\u00fcller\",\"Herbst\",\"High Five\",\"Kinder\",\"R\u00fcckblick\",\"Woche\",\"Wochenlieblinge\"],\"articleSection\":[\"Blogsph\u00e4re\",\"R\u00fcckblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/\",\"name\":\"Unsere Wochenlieblinge 36\\\/2024 - Eine richtige Herbstwoche! - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/36-00.jpg\",\"datePublished\":\"2024-09-13T08:02:32+00:00\",\"description\":\"Unsere Wochenlieblinge diese Woche werden herbstlich und gem\u00fctlich zu gleich. Als ich eben die Fotos sichtete, musste ich feststellen,...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/36-00.jpg\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/36-00.jpg\",\"width\":1000,\"height\":730,\"caption\":\"Bereit f\u00fcr eine Saison voller Halloween-Feeling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2024\\\/09\\\/13\\\/unsere-wochenlieblinge-362024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Wochenlieblinge 36\\\/2024 &#8211; Eine richtige Herbstwoche!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Wochenlieblinge 36\/2024 - Eine richtige Herbstwoche! - Heldenhaushalt","description":"Unsere Wochenlieblinge diese Woche werden herbstlich und gem\u00fctlich zu gleich. Als ich eben die Fotos sichtete, musste ich feststellen,...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/","og_locale":"de_DE","og_type":"article","og_title":"Unsere Wochenlieblinge 36\/2024 - Eine richtige Herbstwoche! - Heldenhaushalt","og_description":"Unsere Wochenlieblinge diese Woche werden herbstlich und gem\u00fctlich zu gleich. Als ich eben die Fotos sichtete, musste ich feststellen,...","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/","og_site_name":"Heldenhaushalt","article_published_time":"2024-09-13T08:02:32+00:00","og_image":[{"width":1000,"height":730,"url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-00.jpg","type":"image\/jpeg"}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"Unsere Wochenlieblinge 36\/2024 &#8211; Eine richtige Herbstwoche!","datePublished":"2024-09-13T08:02:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/"},"wordCount":1152,"commentCount":10,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-00.jpg","keywords":["Allt\u00e4glich","Familie","Freitagsf\u00fcller","Herbst","High Five","Kinder","R\u00fcckblick","Woche","Wochenlieblinge"],"articleSection":["Blogsph\u00e4re","R\u00fcckblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/","name":"Unsere Wochenlieblinge 36\/2024 - Eine richtige Herbstwoche! - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-00.jpg","datePublished":"2024-09-13T08:02:32+00:00","description":"Unsere Wochenlieblinge diese Woche werden herbstlich und gem\u00fctlich zu gleich. Als ich eben die Fotos sichtete, musste ich feststellen,...","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/#primaryimage","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-00.jpg","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2024\/09\/36-00.jpg","width":1000,"height":730,"caption":"Bereit f\u00fcr eine Saison voller Halloween-Feeling"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2024\/09\/13\/unsere-wochenlieblinge-362024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"Unsere Wochenlieblinge 36\/2024 &#8211; Eine richtige Herbstwoche!"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":1225,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/61914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=61914"}],"version-history":[{"count":2,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/61914\/revisions"}],"predecessor-version":[{"id":61925,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/61914\/revisions\/61925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media\/61916"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=61914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=61914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=61914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}