{"id":7461,"date":"2010-01-03T00:00:00","date_gmt":"2010-01-03T00:00:00","guid":{"rendered":"http:\/\/www.mondgras.de\/sari02\/p52-10-01-wochenthema"},"modified":"2010-01-03T00:00:00","modified_gmt":"2010-01-03T00:00:00","slug":"p52-10-01-wochenthema","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/","title":{"rendered":"P52-10: 01. Wochenthema"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/01\/neueslogo52.jpg\" alt=\"\" align=\"left\">Schwupp und da geht es schon los. Nun startet die <strong>3. Runde<\/strong> vom Projekt 52 mit ganz viel frischen Wind und einem neuen Thema.<\/p>\n<p>Ich muss Euch allerdings ersteinmal sagen, wie gl&#252;cklich ich bin, dass sich tats&#228;chlich doch so viele f&#252;r die &#196;nderungen begeistern konnten <img decoding=\"async\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/loving.gif\" alt=\"*loving*\">  und keine Sorge, man kann nachreichen, das behaltet bitte immer im Hinterkopf. Die Aktion soll nicht Stress, sondern Spa&#223; und Inspiration bedeuten.<\/p>\n<p>Inzwischen haben sich <strong>ca. 80 Mitbegeisterte<\/strong> angemeldet und die Vielseitigkeit der Figuren spricht f&#252;r sich. <img decoding=\"async\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/3.gif\" alt=\"^^\">  Ich bin sowas von gespannt, wie diese Neuerung laufen wird und freue mich auf die Geschichten, die mir Eure Figuren erz&#228;hlen werden.<\/p>\n<p>Nun aber endlich zum ersten Thema, das ich ja gestern schon einmal kurz angeschnitten habe:<\/p>\n<blockquote>\n<p style=\"text-align:center\"><strong>Hallo Welt!<\/strong><\/p>\n<\/blockquote>\n<p>Stellt uns Euer Element bzw. eure Figur vor, die uns nun durch das Jahr 2010 begleiten wird. Erz&#228;hlt uns ein bisschen von ihr und warum Ihr sie ausgew&#228;hlt habt. Ich bin schon ganz neugierig auf Eure bebilderten Geschichten.<\/p>\n<p>Und nun viel Spa&#223; im neuen Projekt-Jahr!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schwupp und da geht es schon los. Nun startet die 3. Runde vom Projekt 52 mit ganz viel frischen Wind und einem neuen Thema. Ich muss Euch allerdings ersteinmal sagen, wie gl&#252;cklich ich bin, dass sich tats&#228;chlich doch so viele f&#252;r die &#196;nderungen begeistern konnten und keine Sorge, man kann nachreichen, das behaltet bitte immer im Hinterkopf. Die Aktion soll nicht Stress, sondern Spa&#223; und Inspiration bedeuten. Inzwischen haben sich ca. 80 Mitbegeisterte angemeldet und die Vielseitigkeit der Figuren spricht f&#252;r sich. Ich bin sowas von gespannt, wie diese Neuerung laufen wird und freue mich auf die Geschichten, die mir Eure Figuren erz&#228;hlen werden. Nun aber endlich zum ersten Thema, das ich ja gestern schon einmal kurz angeschnitten habe: Hallo Welt! Stellt uns Euer Element bzw. eure Figur vor, die uns nun durch das Jahr 2010 begleiten wird. Erz&#228;hlt uns ein bisschen von ihr und warum Ihr sie ausgew&#228;hlt habt. Ich bin schon ganz neugierig auf Eure bebilderten Geschichten. Und nun viel Spa&#223; im neuen Projekt-Jahr!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[180],"tags":[],"class_list":["post-7461","post","type-post","status-publish","format-standard","hentry","category-projekt-52"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P52-10: 01. Wochenthema - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P52-10: 01. Wochenthema - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-03T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/01\/neueslogo52.jpg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"P52-10: 01. Wochenthema\",\"datePublished\":\"2010-01-03T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/\"},\"wordCount\":172,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2009\\\/01\\\/neueslogo52.jpg\",\"articleSection\":[\"Projekt 52\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/\",\"name\":\"P52-10: 01. Wochenthema - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2009\\\/01\\\/neueslogo52.jpg\",\"datePublished\":\"2010-01-03T00:00:00+00:00\",\"description\":\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2009\\\/01\\\/neueslogo52.jpg\",\"contentUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2009\\\/01\\\/neueslogo52.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2010\\\/01\\\/03\\\/p52-10-01-wochenthema\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P52-10: 01. Wochenthema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P52-10: 01. Wochenthema - Heldenhaushalt","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/","og_locale":"de_DE","og_type":"article","og_title":"P52-10: 01. Wochenthema - Heldenhaushalt","og_description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/","og_site_name":"Heldenhaushalt","article_published_time":"2010-01-03T00:00:00+00:00","og_image":[{"url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/01\/neueslogo52.jpg","type":"","width":"","height":""}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"P52-10: 01. Wochenthema","datePublished":"2010-01-03T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/"},"wordCount":172,"commentCount":0,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/01\/neueslogo52.jpg","articleSection":["Projekt 52"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/","name":"P52-10: 01. Wochenthema - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/01\/neueslogo52.jpg","datePublished":"2010-01-03T00:00:00+00:00","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/#primaryimage","url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/01\/neueslogo52.jpg","contentUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/01\/neueslogo52.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2010\/01\/03\/p52-10-01-wochenthema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"P52-10: 01. Wochenthema"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":21475,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/7461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=7461"}],"version-history":[{"count":0,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/7461\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=7461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=7461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=7461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}