{"id":8575,"date":"2009-02-28T00:00:00","date_gmt":"2009-02-28T00:00:00","guid":{"rendered":"http:\/\/www.mondgras.de\/sari02\/dinge-kommen-immer-wieder"},"modified":"2009-02-28T00:00:00","modified_gmt":"2009-02-28T00:00:00","slug":"dinge-kommen-immer-wieder","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/","title":{"rendered":"Dinge kommen immer wieder"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"200\" alt=\"\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/02\/mylittlepony.jpg\" title=\"mylittlepony\"><\/p>\n<p>Gestern sa&#223; ich im Bus. Ich war auf dem Heimweg nach einem relativ entspannten Arbeitstag. Ein paar Reihen vor mir sitzt ein junges M&#228;dchen. 14, vielleicht 15 Jahre alt. In ihren H&#228;nden h&#228;lt sie eine Zeitung von \u201cMein kleines Pony\u201d.<\/p>\n<p>Es ist erstaunlich, wie alles immer wieder geht und dann erneut auftaucht. Immer und immer wieder. Letztens erst tauchten diese Gogo Dinger in der Werbung auf, die das letzte Mal in waren, da war meine Schwester so ca. 7 Jahre alt. Gogos waren das Gr&#246;&#223;te f&#252;r sie. Das ist nun ca. 9 Jahre her. Mein kleines Pony war in meiner Kindheit das Gr&#246;&#223;te. Die sch&#246;nen bunten Haare, die B&#252;rsten, die es immer dazu gab, ich hatte sogar die Heia Popeia Stube und so einen ganz besonderen Babywagen mit Schirmchen dran. Dann wurden sie irgendwann undinteressant und nun sehe ich sie wieder.<\/p>\n<p>&#196;hnlich war es auch mit den Kohlkopfkindern. Wer kennt sie noch? Mein Baby Born Ersatz zu Grundschultagen. Sie sahen unheimlich niedlich aus, hatten aber reichlich wenig von richtigen Babies.<\/p>\n<p>Alles kommt irgendwie wieder. Es sieht aus wie fr&#252;her, aber verbessert. Es kann mehr, es sieht mehr und es will mehr. Und irgendwann ist es wieder out, um ein Jahrzehnt sp&#228;ter wieder verbessert neu aufzutauchen und eine neue Generation zu begeistern.<\/p>\n<p>Einzig und alleine Barbie scheint sich durch alle Generationen hindurch zu halten, oder?<\/p>\n<p style=\"text-align: right;\"><small>[Foto von&nbsp;<a href=\"http:\/\/www.flickr.com\/photos\/dreamcicle\/\" target=\"_blank\">dreamcicle19772006 (Checking Periodcally)<\/a> mit einer <a href=\"http:\/\/creativecommons.org\/licenses\/by\/2.0\/deed.de\" target=\"_blank\">CC Lisenz<\/a>]<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gestern sa&#223; ich im Bus. Ich war auf dem Heimweg nach einem relativ entspannten Arbeitstag. Ein paar Reihen vor mir sitzt ein junges M&#228;dchen. 14, vielleicht 15 Jahre alt. In ihren H&#228;nden h&#228;lt sie eine Zeitung von \u201cMein kleines Pony\u201d. Es ist erstaunlich, wie alles immer wieder geht und dann erneut auftaucht. Immer und immer wieder. Letztens erst tauchten diese Gogo Dinger in der Werbung auf, die das letzte Mal in waren, da war meine Schwester so ca. 7 Jahre alt. Gogos waren das Gr&#246;&#223;te f&#252;r sie. Das ist nun ca. 9 Jahre her. Mein kleines Pony war in meiner Kindheit das Gr&#246;&#223;te. Die sch&#246;nen bunten Haare, die B&#252;rsten, die es immer dazu gab, ich hatte sogar die Heia Popeia Stube und so einen ganz besonderen Babywagen mit Schirmchen dran. Dann wurden sie irgendwann undinteressant und nun sehe ich sie wieder. &#196;hnlich war es auch mit den Kohlkopfkindern. Wer kennt sie noch? Mein Baby Born Ersatz zu Grundschultagen. Sie sahen unheimlich niedlich aus, hatten aber reichlich wenig von richtigen Babies. Alles kommt irgendwie wieder. Es sieht aus wie fr&#252;her, aber verbessert. Es kann mehr, es sieht mehr und es will mehr. Und irgendwann ist es wieder out, um ein Jahrzehnt sp&#228;ter wieder verbessert neu aufzutauchen und eine neue Generation zu begeistern. Einzig und alleine Barbie scheint sich durch alle Generationen hindurch zu halten, oder? [Foto von&nbsp;dreamcicle19772006 (Checking Periodcally) mit einer CC Lisenz]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[],"tags":[],"class_list":["post-8575","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dinge kommen immer wieder - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dinge kommen immer wieder - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-28T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/02\/mylittlepony.jpg\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"Dinge kommen immer wieder\",\"datePublished\":\"2009-02-28T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/mylittlepony.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/\",\"name\":\"Dinge kommen immer wieder - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/mylittlepony.jpg\",\"datePublished\":\"2009-02-28T00:00:00+00:00\",\"description\":\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/mylittlepony.jpg\",\"contentUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/mylittlepony.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2009\\\/02\\\/28\\\/dinge-kommen-immer-wieder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dinge kommen immer wieder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dinge kommen immer wieder - Heldenhaushalt","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/","og_locale":"de_DE","og_type":"article","og_title":"Dinge kommen immer wieder - Heldenhaushalt","og_description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/","og_site_name":"Heldenhaushalt","article_published_time":"2009-02-28T00:00:00+00:00","og_image":[{"url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/02\/mylittlepony.jpg","type":"","width":"","height":""}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"Dinge kommen immer wieder","datePublished":"2009-02-28T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/02\/mylittlepony.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/","name":"Dinge kommen immer wieder - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/02\/mylittlepony.jpg","datePublished":"2009-02-28T00:00:00+00:00","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/#primaryimage","url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/02\/mylittlepony.jpg","contentUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2009\/02\/mylittlepony.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2009\/02\/28\/dinge-kommen-immer-wieder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"Dinge kommen immer wieder"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":4764,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/8575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=8575"}],"version-history":[{"count":0,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/8575\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=8575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=8575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=8575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}