{"id":8846,"date":"2008-08-13T00:00:00","date_gmt":"2008-08-13T00:00:00","guid":{"rendered":"http:\/\/www.mondgras.de\/sari02\/hat-das-stoeckchen-einen-namen"},"modified":"2008-08-13T00:00:00","modified_gmt":"2008-08-13T00:00:00","slug":"hat-das-stoeckchen-einen-namen","status":"publish","type":"post","link":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/","title":{"rendered":"Hat das St&#246;ckchen einen Namen?"},"content":{"rendered":"<p>Ich wei&#223; es nicht, aber ich wei&#223;, von wem es kommt, n&#228;mlich von <a href=\"http:\/\/www.schreibakt.de\/?p=442\" target=\"_blank\">Kathi<\/a>. Ich soll mit den Buchstaben meines Namens einen Satz bilden, wie gut, dass meine Eltern mir so einen kurzen Namen gegeben haben, wenn ich sehe, wie lang die S&#228;tze bei manchen schon werden musste:<\/p>\n<p><strong>Sari<\/strong> = <strong>S<\/strong>ie <strong>a<\/strong>rbeitet <strong>r<\/strong>ichtig <strong>i<\/strong>ntensiv.<\/p>\n<p>Und weil es so sch&#246;n ist gleich nochmal in voller L&#228;nge:<br \/>\n<strong>Sarah<\/strong> = <strong>S<\/strong>ie <strong>a<\/strong>rbeitet <strong>r<\/strong>uhig, <strong>a<\/strong>ber <strong>h<\/strong>&#228;ufig.<\/p>\n<p>Und damit unsja nicht langweilig wird, erweiterte <a href=\"http:\/\/konna.pytalhost.de\/2008\/08\/11\/hausaufgabenstockchen\/\" target=\"_blank\">Konna<\/a> dieses St&#246;ckchen vor einer Weile, in dem man auch noch einen Satz aus den Namen der Personen bilden muss, an die man dieses St&#246;ckchen weiterreicht. Dann werd ich es wohl dieses Mal nicht einfach so liegen lassen, oder?<\/p>\n<p><a href=\"http:\/\/www.vienn.de\" target=\"_blank\"><strong>Tina<\/strong><\/a> = <strong>T<\/strong>ausend <strong>I<\/strong>deen <strong>n<\/strong>utzen <strong>a<\/strong>llen\u2026<br \/>\n<a href=\"http:\/\/illdividual.countzeero.eu\/\" target=\"_blank\"><strong>jnin<\/strong><\/a> = <strong>J<\/strong>edermann <strong>n<\/strong>utzt <strong>I<\/strong>nformationen <strong>n<\/strong>achmittags.<br \/>\n<a href=\"http:\/\/www.traumsterne.net\" target=\"_blank\"><strong>Nici<\/strong><\/a> = <strong>N<\/strong>iemand <strong>i<\/strong>sst&nbsp; <strong>C<\/strong>hicoree <strong>i<\/strong>rrt&#252;rmlich.<\/p>\n<p>Herrjeh, ist das ein Stuss <img decoding=\"async\" alt=\"*schwitz*\" src=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/schwitz.gif\"> Dann mal viel Spa&#223; damit, Ihr Lieben!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich wei&#223; es nicht, aber ich wei&#223;, von wem es kommt, n&#228;mlich von Kathi. Ich soll mit den Buchstaben meines Namens einen Satz bilden, wie gut, dass meine Eltern mir so einen kurzen Namen gegeben haben, wenn ich sehe, wie lang die S&#228;tze bei manchen schon werden musste: Sari = Sie arbeitet richtig intensiv. Und weil es so sch&#246;n ist gleich nochmal in voller L&#228;nge: Sarah = Sie arbeitet ruhig, aber h&#228;ufig. Und damit unsja nicht langweilig wird, erweiterte Konna dieses St&#246;ckchen vor einer Weile, in dem man auch noch einen Satz aus den Namen der Personen bilden muss, an die man dieses St&#246;ckchen weiterreicht. Dann werd ich es wohl dieses Mal nicht einfach so liegen lassen, oder? Tina = Tausend Ideen nutzen allen\u2026 jnin = Jedermann nutzt Informationen nachmittags. Nici = Niemand isst&nbsp; Chicoree irrt&#252;rmlich. Herrjeh, ist das ein Stuss Dann mal viel Spa&#223; damit, Ihr Lieben!!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[],"tags":[],"class_list":["post-8846","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hat das St\u00f6ckchen einen Namen? - Heldenhaushalt<\/title>\n<meta name=\"description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hat das St\u00f6ckchen einen Namen? - Heldenhaushalt\" \/>\n<meta property=\"og:description\" content=\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/\" \/>\n<meta property=\"og:site_name\" content=\"Heldenhaushalt\" \/>\n<meta property=\"article:published_time\" content=\"2008-08-13T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/schwitz.gif\" \/>\n<meta name=\"author\" content=\"Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:site\" content=\"@Heldenhaushalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/\"},\"author\":{\"name\":\"Sari\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"headline\":\"Hat das St&#246;ckchen einen Namen?\",\"datePublished\":\"2008-08-13T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/\"},\"wordCount\":158,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-includes\\\/images\\\/smilies\\\/schwitz.gif\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/\",\"name\":\"Hat das St\u00f6ckchen einen Namen? - Heldenhaushalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-includes\\\/images\\\/smilies\\\/schwitz.gif\",\"datePublished\":\"2008-08-13T00:00:00+00:00\",\"description\":\"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-includes\\\/images\\\/smilies\\\/schwitz.gif\",\"contentUrl\":\"http:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-includes\\\/images\\\/smilies\\\/schwitz.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/2008\\\/08\\\/13\\\/hat-das-stoeckchen-einen-namen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hat das St&#246;ckchen einen Namen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#website\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/\",\"name\":\"Heldenhaushalt\",\"description\":\"Wer es ordentlich haben will, der muss vorher anrufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/#\\\/schema\\\/person\\\/a1cc69f42a01f412eb62c151353814f6\",\"name\":\"Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"contentUrl\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\",\"width\":500,\"height\":500,\"caption\":\"Sari\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sari-april2018.png\"},\"description\":\"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heldenhaushalt\\\/\"],\"url\":\"https:\\\/\\\/www.heldenhaushalt.de\\\/sari02\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hat das St\u00f6ckchen einen Namen? - Heldenhaushalt","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/","og_locale":"de_DE","og_type":"article","og_title":"Hat das St\u00f6ckchen einen Namen? - Heldenhaushalt","og_description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","og_url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/","og_site_name":"Heldenhaushalt","article_published_time":"2008-08-13T00:00:00+00:00","og_image":[{"url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/schwitz.gif","type":"","width":"","height":""}],"author":"Sari","twitter_card":"summary_large_image","twitter_creator":"@Heldenhaushalt","twitter_site":"@Heldenhaushalt","twitter_misc":{"Verfasst von":"Sari","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/#article","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/"},"author":{"name":"Sari","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"headline":"Hat das St&#246;ckchen einen Namen?","datePublished":"2008-08-13T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/"},"wordCount":158,"commentCount":0,"publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/schwitz.gif","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/","url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/","name":"Hat das St\u00f6ckchen einen Namen? - Heldenhaushalt","isPartOf":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/#primaryimage"},"image":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/schwitz.gif","datePublished":"2008-08-13T00:00:00+00:00","description":"Auch Helden erleben den t\u00e4glichen Wahnsinn, den ein Alltag mit sich bringt und Frau Mondgras sitzt mittendrin. Berlinerin, Mutter, Ehefrau, Kreativling und auf der st\u00e4ndigen Suche nach Gl\u00fcck... Hier wird gen\u00e4ht, gebacken, gebastelt und auch mal \u00fcber den Alltag gemault.","breadcrumb":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/#primaryimage","url":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/schwitz.gif","contentUrl":"http:\/\/www.heldenhaushalt.de\/sari02\/wp-includes\/images\/smilies\/schwitz.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/2008\/08\/13\/hat-das-stoeckchen-einen-namen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.heldenhaushalt.de\/sari02\/"},{"@type":"ListItem","position":2,"name":"Hat das St&#246;ckchen einen Namen?"}]},{"@type":"WebSite","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#website","url":"https:\/\/www.heldenhaushalt.de\/sari02\/","name":"Heldenhaushalt","description":"Wer es ordentlich haben will, der muss vorher anrufen","publisher":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.heldenhaushalt.de\/sari02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/#\/schema\/person\/a1cc69f42a01f412eb62c151353814f6","name":"Sari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","url":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","contentUrl":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png","width":500,"height":500,"caption":"Sari"},"logo":{"@id":"https:\/\/www.heldenhaushalt.de\/sari02\/wp-content\/uploads\/2019\/02\/sari-april2018.png"},"description":"Frau Mondgras \u2013 Das bin ich, Sari. Gerne auch als Sari Mondgras bekannt und im Internet zu finden. 2-Fach-Mutter, Heldenehefrau, Kreativling, Harmonies\u00fcchtig und st\u00e4ndig auf der Suche nach Gl\u00fcck. Ich komme aus Berlin, bin hier aufgewachsen und lebe hier seit ich denken kann.","sameAs":["https:\/\/www.instagram.com\/heldenhaushalt\/"],"url":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/author\/admin\/"}]}},"views":4233,"_links":{"self":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/8846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/comments?post=8846"}],"version-history":[{"count":0,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/posts\/8846\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/media?parent=8846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/categories?post=8846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heldenhaushalt.de\/sari02\/index.php\/wp-json\/wp\/v2\/tags?post=8846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}